{"id":1588,"date":"2013-04-29T11:10:47","date_gmt":"2013-04-29T10:10:47","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=1588"},"modified":"2013-04-29T11:10:47","modified_gmt":"2013-04-29T10:10:47","slug":"luces-m-wave-cobra","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra","title":{"rendered":"Luces M-Wave Cobra"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div id=\"attachment_1628\" style=\"width: 501px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/04\/DSC0715.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1628\" data-attachment-id=\"1628\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra\/_dsc0715\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/04\/DSC0715.jpg?fit=1196%2C796&amp;ssl=1\" data-orig-size=\"1196,796\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D90&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1341080064&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;26&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"M-Wave Cobra \" data-image-description=\"&lt;p&gt;M-Wave Cobra&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;M-Wave Cobra&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/04\/DSC0715.jpg?fit=700%2C466&amp;ssl=1\" class=\" wp-image-1628  \" title=\"M-Wave Cobra \" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/04\/DSC0715.jpg?resize=491%2C327&#038;ssl=1\" alt=\"M-Wave Cobra\" width=\"491\" height=\"327\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/04\/DSC0715.jpg?resize=1024%2C681&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/04\/DSC0715.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/04\/DSC0715.jpg?w=1196&amp;ssl=1 1196w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><\/a><p id=\"caption-attachment-1628\" class=\"wp-caption-text\">M-Wave Cobra<\/p><\/div>\n<p>Las luces es un elemento de seguridad m\u00e1s importante de lo que pensamos para aquellos que nos movemos por la ciudad, en especial en estos d\u00edas invernales en los que las horas de Sol son escasas y la visibilidad a\u00fan siendo de d\u00eda no es demasiada buena, por ello el uso de luces facilitar\u00e1 el poder ser vistos de forma m\u00e1s clara, para ello no es necesario una gran potencia si no un destello claro. Es por ello que las Luces M-Wave Cobra son una opci\u00f3n realmente interesante dado que combina ligereza, flexibilidad de uso, instalaci\u00f3n sencilla y sin necesidad de herramientas, unas est\u00e9tica lograda, un tama\u00f1o contenido y un precio muy bajo, vamos a analizar con detalle cada uno de sus aspectos.<\/p>\n<p>En primer lugar estamos ante un accesorio construido en una combinaci\u00f3n de pl\u00e1stico y goma que supone un gran ahorro de peso,\u00a0 aspecto en el que tambi\u00e9n pone su grano de arena una tecnolog\u00eda minimalista donde se combina el uso de un led de potencia media, un min\u00fasculo circuito y 2 pilas de bot\u00f3n CR 2025 evitando la aparatosidad que supone bater\u00edas m\u00e1s voluminosas. Otro punto a favor es la cubierta de la bater\u00eda empleando 2 min\u00fasculos tornillos que puedes retirar f\u00e1cilmente gracias al peque\u00f1o destornillador que incluye el pack. Os puede sorprender el uso de un destornillador en un elemento tan simple sin embargo la idea yo la considero adecuada dado que en ocasiones estos aparatos no ofrecen la estanqueidad que deber\u00edan de ofrecer un elemento que se va a usar a la intemperie y sin duda estos tornillos ofrecer\u00e1n un cierre mucho m\u00e1s fiable que aquellas luces que ofrece un autocierre. Por otro lado este sencillo sistema pone su granito de arena en el aspecto minimalista de la luz.<\/p>\n<p>Gracias a su dise\u00f1o formando parte la propia estructura de goma del sistema de fijaci\u00f3n adem\u00e1s convierte a la luz en un elemento verdaderamente versatil que nos permite situar la luz\u00a0 entre las ventilaciones del casco, sobre la tija, el manillar, las vainas o all\u00e1 donde consideremos que sea necesario sin necesidad de ning\u00fan adaptador ni sistemas tan aparatosos como ofrecen la mayor\u00eda de luces de es estas caracter\u00edsticas en el mercado.<\/p>\n<p>La M-Wave, adem\u00e1s ofrece una luz clara y suficientemente potente para ser visto en cualquier circunstancia en un entorno urbano o incluso, en caso del modelo frontal (blanca) nos puede servir de accesorio de emergencia para solventar cualquier aprieto debido a su alta luminosidad (siempre teniendo en cuenta la clase de luz que es).<\/p>\n<p>Por sus caracter\u00edsticas recomendar\u00eda la M-Wave como accesorio a cualquier ciclista urbano para llevar siempre en su bolso\/mochila para hacer frente a esos momentos en que se nos echa la hora encima (o directamente nos vamos a tomar algo en bici), pero tambi\u00e9n a todo ciclista que pueda echarsele la hora encima y tener que llegar al atardecer o de noche a casa: los ciclistas de noche somos a\u00fan mas vulnerables cuando la visibilidad se reduce y por ello aunque circulemos por caminos o un arc\u00e9n al no hacer ruido es m\u00e1s dif\u00edcil que los dem\u00e1s usuarios de las v\u00edas se puedan dar cuenta de nuestra presencia por lo que este elemento puede aportarnos ese extra de seguridad suficiente como para tener que ahorrarnos contar una an\u00e9cdota desagradable.<\/p>\n<p>&nbsp;<\/p>\n<p>disponibles aqu\u00ed &#8230;.\u00a0<a href=\"http:\/\/valwindcycles.es\/117-mini-led-cobra-m-wave-luz-roja-.html\" target=\"_blank\">http:\/\/valwindcycles.es\/117-mini-led-cobra-m-wave-luz-roja-.html<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Las luces es un elemento de seguridad m\u00e1s importante de lo que pensamos para aquellos que nos movemos por la ciudad, en especial en estos d\u00edas invernales en los&hellip; <\/p>\n","protected":false},"author":4,"featured_media":1628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[76,77,1,75],"tags":[],"class_list":["post-1588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-novedades","category-sin-categoria","category-test"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luces M-Wave Cobra - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luces M-Wave Cobra - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Las luces es un elemento de seguridad m\u00e1s importante de lo que pensamos para aquellos que nos movemos por la ciudad, en especial en estos d\u00edas invernales en los&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"ryder.mad\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-29T10:10:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/04\/DSC0715.jpg?fit=1196%2C796&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1196\" \/>\n\t<meta property=\"og:image:height\" content=\"796\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luis Lumbreras &quot;Luiggi&quot;\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Lumbreras &quot;Luiggi&quot;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/luces-m-wave-cobra#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/luces-m-wave-cobra\"},\"author\":{\"name\":\"Luis Lumbreras \\\"Luiggi\\\"\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/ca50cd9daacbde4651c361ff1e90d274\"},\"headline\":\"Luces M-Wave Cobra\",\"datePublished\":\"2013-04-29T10:10:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/luces-m-wave-cobra\"},\"wordCount\":611,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/luces-m-wave-cobra#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/DSC0715.jpg?fit=1196%2C796&ssl=1\",\"articleSection\":{\"0\":\"NOTICIAS\",\"1\":\"NOVEDADES\",\"3\":\"Test\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/luces-m-wave-cobra#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/luces-m-wave-cobra\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/luces-m-wave-cobra\",\"name\":\"Luces M-Wave Cobra - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/luces-m-wave-cobra#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/luces-m-wave-cobra#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/DSC0715.jpg?fit=1196%2C796&ssl=1\",\"datePublished\":\"2013-04-29T10:10:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/ca50cd9daacbde4651c361ff1e90d274\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/luces-m-wave-cobra#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/luces-m-wave-cobra\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/luces-m-wave-cobra#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/DSC0715.jpg?fit=1196%2C796&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/DSC0715.jpg?fit=1196%2C796&ssl=1\",\"width\":\"1196\",\"height\":\"796\",\"caption\":\"M-Wave Cobra\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/luces-m-wave-cobra#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luces M-Wave Cobra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/ca50cd9daacbde4651c361ff1e90d274\",\"name\":\"Luis Lumbreras \\\"Luiggi\\\"\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f61045ec2fb7b307e3875ca714c2f6b224535ceab4bd12409b2e6ba82d8cf4f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f61045ec2fb7b307e3875ca714c2f6b224535ceab4bd12409b2e6ba82d8cf4f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f61045ec2fb7b307e3875ca714c2f6b224535ceab4bd12409b2e6ba82d8cf4f?s=96&d=mm&r=g\",\"caption\":\"Luis Lumbreras \\\"Luiggi\\\"\"},\"description\":\"Mi Test Dummy, mi gu\u00eda espiritual, mi Sensei, mi Kitsune, mi amigo.... Dicen las malas lenguas que ha cambiado sus huesos por tubos de carbono y que lleva atornilladas las calas directamente al pi\u00e9.\",\"sameAs\":[\"http:\\\/\\\/kitsunebikeparts.tk\\\/\",\"ryder.mad\",\"http:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=114507000&locale=es_ES&trk=tyah&trkInfo=tasluislumbrerasidx1-1-1\",\"http:\\\/\\\/www.pinterest.com\\\/llumbreras\\\/kitsune\\\/\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/luis-lumbreras\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luces M-Wave Cobra - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra","og_locale":"es_ES","og_type":"article","og_title":"Luces M-Wave Cobra - El Blog de ValwindCycles","og_description":"&nbsp; Las luces es un elemento de seguridad m\u00e1s importante de lo que pensamos para aquellos que nos movemos por la ciudad, en especial en estos d\u00edas invernales en los&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"ryder.mad","article_published_time":"2013-04-29T10:10:47+00:00","og_image":[{"width":1196,"height":796,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/04\/DSC0715.jpg?fit=1196%2C796&ssl=1","type":"image\/jpeg"}],"author":"Luis Lumbreras \"Luiggi\"","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Luis Lumbreras \"Luiggi\"","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra"},"author":{"name":"Luis Lumbreras \"Luiggi\"","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/ca50cd9daacbde4651c361ff1e90d274"},"headline":"Luces M-Wave Cobra","datePublished":"2013-04-29T10:10:47+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra"},"wordCount":611,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/04\/DSC0715.jpg?fit=1196%2C796&ssl=1","articleSection":{"0":"NOTICIAS","1":"NOVEDADES","3":"Test"},"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra","url":"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra","name":"Luces M-Wave Cobra - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/04\/DSC0715.jpg?fit=1196%2C796&ssl=1","datePublished":"2013-04-29T10:10:47+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/ca50cd9daacbde4651c361ff1e90d274"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/04\/DSC0715.jpg?fit=1196%2C796&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/04\/DSC0715.jpg?fit=1196%2C796&ssl=1","width":"1196","height":"796","caption":"M-Wave Cobra"},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/luces-m-wave-cobra#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Luces M-Wave Cobra"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/ca50cd9daacbde4651c361ff1e90d274","name":"Luis Lumbreras \"Luiggi\"","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1f61045ec2fb7b307e3875ca714c2f6b224535ceab4bd12409b2e6ba82d8cf4f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f61045ec2fb7b307e3875ca714c2f6b224535ceab4bd12409b2e6ba82d8cf4f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f61045ec2fb7b307e3875ca714c2f6b224535ceab4bd12409b2e6ba82d8cf4f?s=96&d=mm&r=g","caption":"Luis Lumbreras \"Luiggi\""},"description":"Mi Test Dummy, mi gu\u00eda espiritual, mi Sensei, mi Kitsune, mi amigo.... Dicen las malas lenguas que ha cambiado sus huesos por tubos de carbono y que lleva atornilladas las calas directamente al pi\u00e9.","sameAs":["http:\/\/kitsunebikeparts.tk\/","ryder.mad","http:\/\/www.linkedin.com\/profile\/view?id=114507000&locale=es_ES&trk=tyah&trkInfo=tasluislumbrerasidx1-1-1","http:\/\/www.pinterest.com\/llumbreras\/kitsune\/"],"url":"https:\/\/valwindcycles.es\/blog\/author\/luis-lumbreras"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-pC","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/04\/DSC0715.jpg?fit=1196%2C796&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/1588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=1588"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/1588\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/1628"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=1588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=1588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=1588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}