{"id":2074,"date":"2013-11-30T10:03:01","date_gmt":"2013-11-30T09:03:01","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=2074"},"modified":"2013-11-30T10:03:01","modified_gmt":"2013-11-30T09:03:01","slug":"test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0","title":{"rendered":"Test by Amanciio (Mundobiker.com) &#8211; John Luck Avatar MTB 3.0"},"content":{"rendered":"<p>Gracias a <a href=\"http:\/\/www.Mundobiker.com\" target=\"_blank\">www.Mundobiker.com<\/a>\u00a0y a mi amigo Amanciio (Rub\u00e9n) hoy os traigo el Test que le &#8230;. bueno mas bien sus primeras impresiones&#8230; os dejo con el:<\/p>\n<p>&nbsp;<\/p>\n<p><em>Hoy ha llegado el gran d\u00eda, el de la prueba de las<strong> zapatillas Luck Avatar 3.0<\/strong>, conseguidas a trav\u00e9s de la tienda de <a href=\"http:\/\/www.Valwindcycles.es\" target=\"_blank\">Valwindcycles<\/a>.<\/em><\/p>\n<div id=\"attachment_2075\" style=\"width: 458px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/444383p.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2075\" data-attachment-id=\"2075\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0\/444383p\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/444383p.jpg?fit=448%2C299&amp;ssl=1\" data-orig-size=\"448,299\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"444383p\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/444383p.jpg?fit=448%2C299&amp;ssl=1\" class=\"size-full wp-image-2075\" title=\"John Luck Avatar MTB 3.0\" alt=\"John Luck Avatar MTB 3.0\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/444383p.jpg?resize=448%2C299&#038;ssl=1\" width=\"448\" height=\"299\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/444383p.jpg?w=448&amp;ssl=1 448w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/444383p.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"auto, (max-width: 448px) 100vw, 448px\" \/><\/a><p id=\"caption-attachment-2075\" class=\"wp-caption-text\">John Luck Avatar MTB 3.0<\/p><\/div>\n<p><em>Para los que no conozc\u00e1is la marca, Luck lleva ya varios a\u00f1os haciendo calzado espec\u00edfico para el ciclismo, solo que lo hac\u00edan bajo el nombre de John Luck. Se trata de una empresa riojana, sita en Arnedo. Han estado presentes en varios pies de ciclistas, como Graeme Obree, ex r\u00e9cordman de la hora antes de Indur\u00e1in.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Anteriormente yo mismo tuve unas John Luck, creo recordar que por el a\u00f1o 96\/97, que fueron mis primeras zapatillas de esta marca, por lo que en cuanto vi una foto de estas Avatar me decid\u00ed a compr\u00e1rmelas en cuanto me fuera posible, ya que est\u00e9ticamente me encantan y ten\u00eda ganas de probar el famoso cierre BOA.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>He de decir que lo primero que se nota con estas zapatillas es que son ligeras. He pesado mis antiguas Scott con un peso por cada zapatilla (sin calas) de 465 gramos, mientras que las Luck han pesado 390 gramos con las calas ya colocadas.\u00a0<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>En segundo lugar, y una vez puestas donde tiene que ser, esto es, en los pies, lo primero que notas es una rigidez muy grande, lo que se va a traducir en eficacia a la hora de pedalear gracias a esa misma rigidez. Pero esa misma rigidez se convierte a su vez en uno de los puntos negativos de este tipo de zapatillas, porque a la hora de andar (cuando vas a subirte a la bici o te bajas de ella) requieren de un periodo de aprendizaje para poder caminar con ellas. Se podr\u00eda decir que es algo similar a ponerse unos zapatos de tac\u00f3n alto en el caso de las mujeres.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Una vez colocadas las calas en su sitio, metemos el pie en la zapatilla y procedemos a \u00abatarlas\u00bb con el cierre BOA (llamado Atop en estas zapatillas) y vemos que es un sistema sencillo de usar, comod\u00edsimo de poner y de quitar y para nada engorroso. Atr\u00e1s quedan los tediosos cordones de toda la vida que, si nos quedan largos, se nos pueden enganchar con los platos; atr\u00e1s quedan ya el velcro y los sistemas de carraca. A m\u00ed personalmente me ha convencido mucho este sistema de apertura y cierre. Para apretar basta con ir girando la rueda en sentido horario, y puedes escuchar perfectamente cada uno de los clics mientras notas c\u00f3mo te va apretando en el empeine. Y para liberar basta con girar en sentido antihorario, con un simple cuarto de vuelta ya tienes las zapatillas flojas para pod\u00e9rtelas quitar c\u00f3modamente. Esto se convierte en un punto fuerte de estas zapatillas.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Sin embargo, despu\u00e9s de hacer equilibrios para no caerme mientras sacaba la bici de casa, me he encontrado con el primer inconveniente de estas zapatillas, pero que a su vez tambi\u00e9n es un punto positivo, y me explico: he ido a enganchar los pies a los pedales (unos Crank Brothers Candy 2) y, sorprendido, he visto que no calaban. Primero he pensado que no habr\u00eda colocado bien las calas, pero despu\u00e9s he recordado que quiz\u00e1 los tacos laterales topaban con la plataforma de los CB y que por eso no enganchaban. Efectivamente, me he parado, he desatornillado uno de los tacos laterales (por eso se convierte en un punto positivo, ya que de no haber podido desatornillar los tacos las zapatillas no me habr\u00edan servido de nada) y he enganchado a la primera. As\u00ed que me ha tocado quitar ambos tacos laterales y as\u00ed he podido comenzar la ruta. Sin embargo, esto me va a obligar a buscar una soluci\u00f3n para poder poner nuevamente los tacos en su sitio.<\/em><\/p>\n<p>Nota: (problema que presentan en algunas zapatillas los pedales Crank Brothers, para lo cual tienen a la venta unas placas para colocar debajo de las calas)<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/uvMWAiPcvRdxrguJTVNBheW2VX2gH5K0sb94FtVy1JQ-.jpeg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2076\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0\/uvmwaipcvrdxrgujtvnbhew2vx2gh5k0sb94ftvy1jq\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/uvMWAiPcvRdxrguJTVNBheW2VX2gH5K0sb94FtVy1JQ-.jpeg?fit=162%2C162&amp;ssl=1\" data-orig-size=\"162,162\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/uvMWAiPcvRdxrguJTVNBheW2VX2gH5K0sb94FtVy1JQ-.jpeg?fit=162%2C162&amp;ssl=1\" class=\"aligncenter size-full wp-image-2076\" alt=\"\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/uvMWAiPcvRdxrguJTVNBheW2VX2gH5K0sb94FtVy1JQ-.jpeg?resize=162%2C162&#038;ssl=1\" width=\"162\" height=\"162\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/uvMWAiPcvRdxrguJTVNBheW2VX2gH5K0sb94FtVy1JQ-.jpeg?w=162&amp;ssl=1 162w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/uvMWAiPcvRdxrguJTVNBheW2VX2gH5K0sb94FtVy1JQ-.jpeg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 162px) 100vw, 162px\" \/><\/a><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Una vez solventado el inconveniente, ya he empezado a pedalear con ellas. Gracias a que no llevaba tacos laterales he podido comprobar c\u00f3mo los pedales Crank Brothers efectivamente tienen un juego lateral bastante grande, cosa que hasta ahora con mis zapatillas Scott nunca hab\u00eda podido comprobar (cuesti\u00f3n de los susodichos tacos). He notado una grad\u00edsima rigidez en el conjunto pie-pedal, lo que me ha permitido pedalear de una forma m\u00e1s c\u00f3moda y m\u00e1s segura, puesto que, inconscientemente, la rigidez te transmite seguridad. En este aspecto he de decir que las zapatillas son exclusivamente para pedalear, y que para andar hay opciones mucho mejores. Si eres un biker acostumbrado a \u00abpatear\u00bb en tus excursiones, estas zapatillas no son para ti. Sin embargo, si eres un \u00abrallyeman\u00bb y amante de ir r\u00e1pido, estas zapatillas son ideales (imagino que como todas las del estilo de estas Luck).<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Resumiendo:<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Puntos a favor:<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>&#8211; Est\u00e9tica. Habr\u00e1 a quien no le guste este tipo de zapatillas de \u00abest\u00e9tica futbolera\u00bb, pero a m\u00ed me encantan.<\/em><\/p>\n<p><em>&#8211; Rigidez. La suela de carbono hace que tu energ\u00eda vaya directa a los pedales.<\/em><\/p>\n<p><em>&#8211; Ligereza. Se agradece llevar algo ligero en los pies.<\/em><\/p>\n<p><em>&#8211; Tacos desmontables. No s\u00f3lo por el desgaste de los mismos, sino porque te permite usar las zapatillas con m\u00e1s tipos de pedales.<\/em><\/p>\n<p><em>&#8211; Cierre BOA (Atop). Comod\u00edsimo ponerte y quitarte las zapatillas gracias a su cierre.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Puntos en contra:<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>&#8211; Tacos laterales muy altos. Por eso me ha tocado desmontarlos, ya que las calas si no quedan muy hundidas y no enganchan.<\/em><\/p>\n<p><em>&#8211; Estrechez. Este tipo de zapatillas suelen ser m\u00e1s bien estrechas, y a los empeines anchos nos quedan m\u00e1s bien \u00abapretadas\u00bb.<\/em><\/p>\n<p><em>&#8211; Rigidez. Este punto positivo para el pedaleo, se convierte en un desastre para caminar. Y si quitas los tacos laterales, prep\u00e1rate para patinar cuando las calas toquen el suelo.<a href=\"javascript:void(0);\"><br \/>\n<\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gracias a www.Mundobiker.com\u00a0y a mi amigo Amanciio (Rub\u00e9n) hoy os traigo el Test que le &#8230;. bueno mas bien sus primeras impresiones&#8230; os dejo con el: &nbsp; Hoy ha llegado&hellip; <\/p>\n","protected":false},"author":2,"featured_media":2075,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[80,76,77,75],"tags":[],"class_list":["post-2074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-mafia","category-noticias","category-novedades","category-test"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Test by Amanciio (Mundobiker.com) - John Luck Avatar MTB 3.0 - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Test by Amanciio (Mundobiker.com) - John Luck Avatar MTB 3.0 - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"Gracias a www.Mundobiker.com\u00a0y a mi amigo Amanciio (Rub\u00e9n) hoy os traigo el Test que le &#8230;. bueno mas bien sus primeras impresiones&#8230; os dejo con el: &nbsp; Hoy ha llegado&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"ValwindCycles\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-30T09:03:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/444383p.jpg?fit=448%2C299&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"448\" \/>\n\t<meta property=\"og:image:height\" content=\"299\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge ValwindCycles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge ValwindCycles\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0\"},\"author\":{\"name\":\"Jorge ValwindCycles\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"headline\":\"Test by Amanciio (Mundobiker.com) &#8211; John Luck Avatar MTB 3.0\",\"datePublished\":\"2013-11-30T09:03:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0\"},\"wordCount\":1038,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/444383p.jpg?fit=448%2C299&ssl=1\",\"articleSection\":[\"LA MAFIA\",\"NOTICIAS\",\"NOVEDADES\",\"Test\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0\",\"name\":\"Test by Amanciio (Mundobiker.com) - John Luck Avatar MTB 3.0 - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/444383p.jpg?fit=448%2C299&ssl=1\",\"datePublished\":\"2013-11-30T09:03:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/444383p.jpg?fit=448%2C299&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/444383p.jpg?fit=448%2C299&ssl=1\",\"width\":448,\"height\":299},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Test by Amanciio (Mundobiker.com) &#8211; John Luck Avatar MTB 3.0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\",\"name\":\"Jorge ValwindCycles\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"caption\":\"Jorge ValwindCycles\"},\"description\":\"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.\",\"sameAs\":[\"http:\\\/\\\/www.valwindcycles.es\",\"ValwindCycles\",\"http:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=180972148&trk=nav_responsive_tab_profile\",\"http:\\\/\\\/www.pinterest.com\\\/valwindcycles\\\/\",\"https:\\\/\\\/x.com\\\/JorgeValwind\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/Valwindcycles\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/valwind\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Test by Amanciio (Mundobiker.com) - John Luck Avatar MTB 3.0 - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0","og_locale":"es_ES","og_type":"article","og_title":"Test by Amanciio (Mundobiker.com) - John Luck Avatar MTB 3.0 - El Blog de ValwindCycles","og_description":"Gracias a www.Mundobiker.com\u00a0y a mi amigo Amanciio (Rub\u00e9n) hoy os traigo el Test que le &#8230;. bueno mas bien sus primeras impresiones&#8230; os dejo con el: &nbsp; Hoy ha llegado&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"ValwindCycles","article_published_time":"2013-11-30T09:03:01+00:00","og_image":[{"width":448,"height":299,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/444383p.jpg?fit=448%2C299&ssl=1","type":"image\/jpeg"}],"author":"Jorge ValwindCycles","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Jorge ValwindCycles","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0"},"author":{"name":"Jorge ValwindCycles","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"headline":"Test by Amanciio (Mundobiker.com) &#8211; John Luck Avatar MTB 3.0","datePublished":"2013-11-30T09:03:01+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0"},"wordCount":1038,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/444383p.jpg?fit=448%2C299&ssl=1","articleSection":["LA MAFIA","NOTICIAS","NOVEDADES","Test"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0","url":"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0","name":"Test by Amanciio (Mundobiker.com) - John Luck Avatar MTB 3.0 - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/444383p.jpg?fit=448%2C299&ssl=1","datePublished":"2013-11-30T09:03:01+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/444383p.jpg?fit=448%2C299&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/444383p.jpg?fit=448%2C299&ssl=1","width":448,"height":299},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/test-by-amanciio-mundobiker-com-john-luck-avatar-mtb-3-0#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Test by Amanciio (Mundobiker.com) &#8211; John Luck Avatar MTB 3.0"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3","name":"Jorge ValwindCycles","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","caption":"Jorge ValwindCycles"},"description":"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.","sameAs":["http:\/\/www.valwindcycles.es","ValwindCycles","http:\/\/www.linkedin.com\/profile\/view?id=180972148&trk=nav_responsive_tab_profile","http:\/\/www.pinterest.com\/valwindcycles\/","https:\/\/x.com\/JorgeValwind","http:\/\/www.youtube.com\/user\/Valwindcycles"],"url":"https:\/\/valwindcycles.es\/blog\/author\/valwind"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-xs","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/11\/444383p.jpg?fit=448%2C299&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/2074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=2074"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/2074\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/2075"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=2074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=2074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=2074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}