{"id":2096,"date":"2013-12-03T08:17:52","date_gmt":"2013-12-03T07:17:52","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=2096"},"modified":"2013-12-03T08:17:52","modified_gmt":"2013-12-03T07:17:52","slug":"polar-racing-team-abr","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr","title":{"rendered":"Polar Racing Team ABR"},"content":{"rendered":"<div id=\"attachment_2097\" style=\"width: 430px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/2588-andalucia-bike-race-cordoba-jaen.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2097\" data-attachment-id=\"2097\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr\/2588-andalucia-bike-race-cordoba-jaen\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/2588-andalucia-bike-race-cordoba-jaen.jpg?fit=700%2C502&amp;ssl=1\" data-orig-size=\"700,502\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"2588-andalucia-bike-race-cordoba-jaen\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/2588-andalucia-bike-race-cordoba-jaen.jpg?fit=700%2C502&amp;ssl=1\" class=\" wp-image-2097\" title=\"Andaluc\u00eda Bike Race 2014\" alt=\"Andaluc\u00eda Bike Race 2014\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/2588-andalucia-bike-race-cordoba-jaen.jpg?resize=420%2C301&#038;ssl=1\" width=\"420\" height=\"301\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/2588-andalucia-bike-race-cordoba-jaen.jpg?w=700&amp;ssl=1 700w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/2588-andalucia-bike-race-cordoba-jaen.jpg?resize=300%2C215&amp;ssl=1 300w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/a><p id=\"caption-attachment-2097\" class=\"wp-caption-text\">Andaluc\u00eda Bike Race 2014<\/p><\/div>\n<p>Entre sue\u00f1os e ilusiones, una propuesta entre dos amigos, dos componentes del <strong>Oza 13Team<\/strong> que se quedaron sin participar en las \u00ab4horas de Cuntis\u00bb tras la anulaci\u00f3n del evento, dos personajes de miradas desafiantes cuyo \u00e1rido lugar de \u00abentreno\u00bb es el Monte do Jato&#8230;.Qu\u00e9 podr\u00edan hacer para ponerse a prueba en el 2014? De la mano de Polar les viene el reto&#8230;.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abBuscamos a los integrantes del <a href=\"http:\/\/www.polar.com\/es\/acerca_de_polar\/noticias\/campana_abr\" target=\"_blank\">Polar Racing Team<\/a>\u00a0para la <a href=\"http:\/\/www.andaluciabikerace.com\" target=\"_blank\"><strong>Andaluc\u00eda Bike Race 2014<\/strong><\/a><\/p>\n<p>\u00bfCrees que t\u00fa podr\u00edas ser uno de los diez?<\/p>\n<p>Inscr\u00edbete con tu compa\u00f1ero de equipo y consigue los m\u00e1ximos puntos posibles.<br \/>\nEntre las 20 candidaturas con mayor puntuaci\u00f3n\u00a0un jurado profesional elegir\u00e1\u00a0 a las 5 parejas que representar\u00e1n a\u00a0<a href=\"http:\/\/www.polar.com\/es\" target=\"_blank\">Polar<\/a> en la Andaluc\u00eda Bike Race\u00bb<\/p>\n<p>As\u00ed que en ello est\u00e1n este par de \u00abdoses\u00bb !!! \u00a0Nos ayudais a que puedan realizar su reto?? \u00a0Un voto de cada uno de vosotros puede hacer que est\u00e1n en la preselecci\u00f3n!<\/p>\n<div id=\"attachment_2099\" style=\"width: 442px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1455082_382098118592303_430451214_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2099\" data-attachment-id=\"2099\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr\/1455082_382098118592303_430451214_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1455082_382098118592303_430451214_n.jpg?fit=480%2C640&amp;ssl=1\" data-orig-size=\"480,640\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"1455082_382098118592303_430451214_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1455082_382098118592303_430451214_n.jpg?fit=480%2C640&amp;ssl=1\" class=\" wp-image-2099\" title=\"Benito Gestal con yo misma :)\" alt=\"Benito Gestal con yo misma :)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1455082_382098118592303_430451214_n.jpg?resize=432%2C576&#038;ssl=1\" width=\"432\" height=\"576\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1455082_382098118592303_430451214_n.jpg?w=480&amp;ssl=1 480w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1455082_382098118592303_430451214_n.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><\/a><p id=\"caption-attachment-2099\" class=\"wp-caption-text\">Benito Gestal con yo misma \ud83d\ude42<\/p><\/div>\n<div id=\"attachment_2100\" style=\"width: 471px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1477725_382098268592288_802628373_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2100\" data-attachment-id=\"2100\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr\/1477725_382098268592288_802628373_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1477725_382098268592288_802628373_n.jpg?fit=960%2C717&amp;ssl=1\" data-orig-size=\"960,717\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"1477725_382098268592288_802628373_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1477725_382098268592288_802628373_n.jpg?fit=700%2C523&amp;ssl=1\" class=\" wp-image-2100\" title=\"Alberto Lodeiro con yo misma :)\" alt=\"Alberto Lodeiro con yo misma :)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1477725_382098268592288_802628373_n.jpg?resize=461%2C344&#038;ssl=1\" width=\"461\" height=\"344\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1477725_382098268592288_802628373_n.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1477725_382098268592288_802628373_n.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 461px) 100vw, 461px\" \/><\/a><p id=\"caption-attachment-2100\" class=\"wp-caption-text\">Alberto Lodeiro con yo misma \ud83d\ude42<\/p><\/div>\n<div id=\"attachment_2101\" style=\"width: 453px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1424563_382098705258911_1621489583_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2101\" data-attachment-id=\"2101\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr\/1424563_382098705258911_1621489583_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1424563_382098705258911_1621489583_n.jpg?fit=960%2C717&amp;ssl=1\" data-orig-size=\"960,717\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"1424563_382098705258911_1621489583_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1424563_382098705258911_1621489583_n.jpg?fit=700%2C523&amp;ssl=1\" class=\" wp-image-2101 \" title=\"Benito Gestal y Alberto Lodeiro\" alt=\"Benito Gestal y Alberto Lodeiro\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1424563_382098705258911_1621489583_n.jpg?resize=443%2C331&#038;ssl=1\" width=\"443\" height=\"331\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1424563_382098705258911_1621489583_n.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1424563_382098705258911_1621489583_n.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 443px) 100vw, 443px\" \/><\/a><p id=\"caption-attachment-2101\" class=\"wp-caption-text\">Benito Gestal y Alberto Lodeiro<\/p><\/div>\n<div id=\"attachment_2102\" style=\"width: 413px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1465345_382098941925554_486056826_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2102\" data-attachment-id=\"2102\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr\/1465345_382098941925554_486056826_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1465345_382098941925554_486056826_n.jpg?fit=960%2C960&amp;ssl=1\" data-orig-size=\"960,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"1465345_382098941925554_486056826_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1465345_382098941925554_486056826_n.jpg?fit=700%2C700&amp;ssl=1\" class=\"wp-image-2102 \" title=\"Benito Gestal, Alberto Lodeiro y yo planeando el asalto a la ABR\" alt=\"Benito Gestal, Alberto Lodeiro y yo planeando el asalto a la ABR\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1465345_382098941925554_486056826_n.jpg?resize=403%2C403&#038;ssl=1\" width=\"403\" height=\"403\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1465345_382098941925554_486056826_n.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1465345_382098941925554_486056826_n.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/1465345_382098941925554_486056826_n.jpg?resize=300%2C300&amp;ssl=1 300w\" sizes=\"auto, (max-width: 403px) 100vw, 403px\" \/><\/a><p id=\"caption-attachment-2102\" class=\"wp-caption-text\">Benito Gestal, Alberto Lodeiro y yo planeando el asalto a la ABR<\/p><\/div>\n<p style=\"text-align: left\"><strong>Benito Gestal y Alberto Lodeiro<\/strong>, vamos, adem\u00e1s pod\u00e9is ganar muchos premios cada semana de la mano de <strong>#POLARracinteamabr<\/strong> <strong>#Polaradventures<\/strong>!!!!\u00a0<a href=\"http:\/\/racingteamabr.polaradventures.es\/public\/index.php\/clasificacion\/index\">http:\/\/racingteamabr.polaradventures.es\/public\/index.php\/clasificacion\/index<\/a><\/p>\n<p>Aprovechando, si t\u00fa no tienes tu <strong>POLAR Rc3<\/strong>, a\u00fan puede ser tuyo, en <a href=\"http:\/\/valwindcycles.es\/141-pulsometro-polar-rc3-gps-hr.html\" target=\"_blank\">Valwindcycles<\/a> lo tenemos a un inmejorable precio \ud83d\ude09<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_2098\" style=\"width: 502px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/slide1_product_orange_tour_de_france.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2098\" data-attachment-id=\"2098\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr\/slide1_product_orange_tour_de_france\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/slide1_product_orange_tour_de_france.png?fit=820%2C470&amp;ssl=1\" data-orig-size=\"820,470\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"slide1_product_orange_tour_de_france\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/slide1_product_orange_tour_de_france.png?fit=700%2C401&amp;ssl=1\" class=\" wp-image-2098\" title=\"POLAR RC3\" alt=\"POLAR RC3\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/slide1_product_orange_tour_de_france.png?resize=492%2C282&#038;ssl=1\" width=\"492\" height=\"282\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/slide1_product_orange_tour_de_france.png?w=820&amp;ssl=1 820w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/slide1_product_orange_tour_de_france.png?resize=300%2C171&amp;ssl=1 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><p id=\"caption-attachment-2098\" class=\"wp-caption-text\">POLAR RC3<\/p><\/div>\n<p><a href=\"void(0);\"><br \/>\n<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre sue\u00f1os e ilusiones, una propuesta entre dos amigos, dos componentes del Oza 13Team que se quedaron sin participar en las \u00ab4horas de Cuntis\u00bb tras la anulaci\u00f3n del evento, dos&hellip; <\/p>\n","protected":false},"author":33,"featured_media":2097,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[80,76],"tags":[],"class_list":["post-2096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-mafia","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Polar Racing Team ABR - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Polar Racing Team ABR - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"Entre sue\u00f1os e ilusiones, una propuesta entre dos amigos, dos componentes del Oza 13Team que se quedaron sin participar en las \u00ab4horas de Cuntis\u00bb tras la anulaci\u00f3n del evento, dos&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"santajuliana.dpc?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-03T07:17:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/2588-andalucia-bike-race-cordoba-jaen.jpg?fit=700%2C502&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"502\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Annabel JefaRiqui\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AnnabelMontiel\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Annabel JefaRiqui\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/polar-racing-team-abr#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/polar-racing-team-abr\"},\"author\":{\"name\":\"Annabel JefaRiqui\u00f1a\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/e8245352d27b86c0893936c2582f58c6\"},\"headline\":\"Polar Racing Team ABR\",\"datePublished\":\"2013-12-03T07:17:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/polar-racing-team-abr\"},\"wordCount\":296,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/polar-racing-team-abr#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/2588-andalucia-bike-race-cordoba-jaen.jpg?fit=700%2C502&ssl=1\",\"articleSection\":[\"LA MAFIA\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/polar-racing-team-abr#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/polar-racing-team-abr\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/polar-racing-team-abr\",\"name\":\"Polar Racing Team ABR - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/polar-racing-team-abr#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/polar-racing-team-abr#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/2588-andalucia-bike-race-cordoba-jaen.jpg?fit=700%2C502&ssl=1\",\"datePublished\":\"2013-12-03T07:17:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/e8245352d27b86c0893936c2582f58c6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/polar-racing-team-abr#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/polar-racing-team-abr\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/polar-racing-team-abr#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/2588-andalucia-bike-race-cordoba-jaen.jpg?fit=700%2C502&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/2588-andalucia-bike-race-cordoba-jaen.jpg?fit=700%2C502&ssl=1\",\"width\":700,\"height\":502},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/polar-racing-team-abr#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Polar Racing Team ABR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/e8245352d27b86c0893936c2582f58c6\",\"name\":\"Annabel JefaRiqui\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9f4068e5e5d8865def28ab3bd909429c623cd36032bda23321fcb0f0c5a1c0e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9f4068e5e5d8865def28ab3bd909429c623cd36032bda23321fcb0f0c5a1c0e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9f4068e5e5d8865def28ab3bd909429c623cd36032bda23321fcb0f0c5a1c0e?s=96&d=mm&r=g\",\"caption\":\"Annabel JefaRiqui\u00f1a\"},\"description\":\"Apoyando siempre a las mujeres en el dif\u00edcil mundillo de #comosermadrebikerynomorirenelintento y todo lo que nos ayude a avanzar, tatuada en la piel una 29er aunque si hay que defender colores el turquesa se lleva la palma\u2026. As\u00ed que mi opini\u00f3n estar\u00e1 entre cl\u00e1sica, friki o extraterrestre\u2026. Si ves una chica maja con una interminable sonrisa con calcetines frikis hasta la rodilla y una gorra cl\u00e1sica en su cabeza seguro que es ella\u2026 mi JefaRiqui\u00f1a\",\"sameAs\":[\"http:\\\/\\\/mumshand.blogspot.com.es\",\"santajuliana.dpc?fref=ts\",\"http:\\\/\\\/www.pinterest.com\\\/santajuliana\\\/\",\"https:\\\/\\\/x.com\\\/AnnabelMontiel\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/annabel-jefariquina\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Polar Racing Team ABR - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr","og_locale":"es_ES","og_type":"article","og_title":"Polar Racing Team ABR - El Blog de ValwindCycles","og_description":"Entre sue\u00f1os e ilusiones, una propuesta entre dos amigos, dos componentes del Oza 13Team que se quedaron sin participar en las \u00ab4horas de Cuntis\u00bb tras la anulaci\u00f3n del evento, dos&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"santajuliana.dpc?fref=ts","article_published_time":"2013-12-03T07:17:52+00:00","og_image":[{"width":700,"height":502,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/2588-andalucia-bike-race-cordoba-jaen.jpg?fit=700%2C502&ssl=1","type":"image\/jpeg"}],"author":"Annabel JefaRiqui\u00f1a","twitter_card":"summary_large_image","twitter_creator":"@AnnabelMontiel","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Annabel JefaRiqui\u00f1a","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr"},"author":{"name":"Annabel JefaRiqui\u00f1a","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/e8245352d27b86c0893936c2582f58c6"},"headline":"Polar Racing Team ABR","datePublished":"2013-12-03T07:17:52+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr"},"wordCount":296,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/2588-andalucia-bike-race-cordoba-jaen.jpg?fit=700%2C502&ssl=1","articleSection":["LA MAFIA","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr","url":"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr","name":"Polar Racing Team ABR - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/2588-andalucia-bike-race-cordoba-jaen.jpg?fit=700%2C502&ssl=1","datePublished":"2013-12-03T07:17:52+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/e8245352d27b86c0893936c2582f58c6"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/2588-andalucia-bike-race-cordoba-jaen.jpg?fit=700%2C502&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/2588-andalucia-bike-race-cordoba-jaen.jpg?fit=700%2C502&ssl=1","width":700,"height":502},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/polar-racing-team-abr#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Polar Racing Team ABR"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/e8245352d27b86c0893936c2582f58c6","name":"Annabel JefaRiqui\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d9f4068e5e5d8865def28ab3bd909429c623cd36032bda23321fcb0f0c5a1c0e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d9f4068e5e5d8865def28ab3bd909429c623cd36032bda23321fcb0f0c5a1c0e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9f4068e5e5d8865def28ab3bd909429c623cd36032bda23321fcb0f0c5a1c0e?s=96&d=mm&r=g","caption":"Annabel JefaRiqui\u00f1a"},"description":"Apoyando siempre a las mujeres en el dif\u00edcil mundillo de #comosermadrebikerynomorirenelintento y todo lo que nos ayude a avanzar, tatuada en la piel una 29er aunque si hay que defender colores el turquesa se lleva la palma\u2026. As\u00ed que mi opini\u00f3n estar\u00e1 entre cl\u00e1sica, friki o extraterrestre\u2026. Si ves una chica maja con una interminable sonrisa con calcetines frikis hasta la rodilla y una gorra cl\u00e1sica en su cabeza seguro que es ella\u2026 mi JefaRiqui\u00f1a","sameAs":["http:\/\/mumshand.blogspot.com.es","santajuliana.dpc?fref=ts","http:\/\/www.pinterest.com\/santajuliana\/","https:\/\/x.com\/AnnabelMontiel"],"url":"https:\/\/valwindcycles.es\/blog\/author\/annabel-jefariquina"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-xO","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2013\/12\/2588-andalucia-bike-race-cordoba-jaen.jpg?fit=700%2C502&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/2096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=2096"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/2096\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/2097"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=2096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=2096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=2096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}