{"id":2662,"date":"2014-04-16T20:04:17","date_gmt":"2014-04-16T19:04:17","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=2662"},"modified":"2014-04-16T20:11:57","modified_gmt":"2014-04-16T19:11:57","slug":"aun-no-conoces-bpart-components","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components","title":{"rendered":"Aun no conoces Bpart Components ???"},"content":{"rendered":"<p>Como viene siendo habitual estas \u00faltimas semanas la estupenda <a href=\"https:\/\/valwindcycles.es\/blog\/?p=2436\" target=\"_blank\">Eva<\/a> no deja de darme sorpresas con las marcas que se est\u00e1n uniendo a su \u00abagenda\u00bb como representante&#8230;. y claro&#8230; si Eva lo tiene&#8230; Valwindcycles lo tiene&#8230;. \u00a0en breve contaremos con los componentes de esta marca espa\u00f1ola de un par de chicos muy majos&#8230;..<\/p>\n<p>Aqui os dejo con su presentaci\u00f3n:<\/p>\n<p><strong><em>BPart Components nace en 2012 creada por dos amigos que comparten afici\u00f3n por la\u00a0MTB\u00a0y la naturaleza. Partiendo de ah\u00ed, y debido a nuestra experiencia en el mundo del\u00a0mecanizado en CNC, comenzamos a fabricar componentes para nuestras propias\u00a0MTB\u00a0y, gracias al apoyo de otros riders, decidimos dar a conocer nuestros\u00a0componentes\u00a0y que as\u00ed todos pudierais disfrutar de ellos. Por eso fundamos BPart, con sede en Valencia (Espa\u00f1a).<\/em><\/strong><\/p>\n<p><strong><em>Nuestro primer objetivo siempre va a ser ofrecer una calidad excelente. Todas nuestras piezas son fabricadas en nuestra planta de Valencia para controlar todo el proceso de producci\u00f3n. Eso nos permite contar con la tecnolog\u00eda m\u00e1s avanzada en el mundo del\u00a0CNC, con el compromiso de tener la mayor precisi\u00f3n y la m\u00e1xima ligereza posible. Tenemos un equipo de I+D desarrollando productos para que vosotros no os teng\u00e1is que preocupar de nada, s\u00f3lo disfrutar. Nuestros componentes siempre estar\u00e1n mecanizados a partir de\u00a0AL 7075-T6, luego les aplicaremos un tratamiento llamado\u00a0anodizado\u00a0que garantiza una durabilidad excelente y unos colores muy atractivos entre los que elegir. Incluso podr\u00e9is\u00a0personalizarlos.<\/em><\/strong><\/p>\n<p><strong><em>El prop\u00f3sito de Bpart Components es haceros disfrutar con cada uno de los componentes de vuestra MTB. Agradecemos la confianza depositada en nuestra marca.<\/em><\/strong><\/p>\n<p>Su web <a href=\"http:\/\/bpartcomponents.com\" target=\"_blank\">Bpart Components<\/a><\/p>\n<div id=\"attachment_2663\" style=\"width: 501px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/04\/bparts-copia.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2663\" data-attachment-id=\"2663\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components\/bparts-copia\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/04\/bparts-copia.jpg?fit=1046%2C825&amp;ssl=1\" data-orig-size=\"1046,825\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"bparts copia\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/04\/bparts-copia.jpg?fit=700%2C552&amp;ssl=1\" class=\" wp-image-2663\" title=\"Bpart Components\" alt=\"Bpart Components\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/04\/bparts-copia.jpg?resize=491%2C387&#038;ssl=1\" width=\"491\" height=\"387\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/04\/bparts-copia.jpg?resize=1024%2C807&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/04\/bparts-copia.jpg?resize=300%2C236&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/04\/bparts-copia.jpg?w=1046&amp;ssl=1 1046w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><\/a><p id=\"caption-attachment-2663\" class=\"wp-caption-text\">Bpart Components<\/p><\/div>\n<p>Ir dandole un vistazo e ir haciendo la lista de la compra para cuando est\u00e9n en <a href=\"http:\/\/www.Valwindcycles.es\" target=\"_blank\">www.Valwindcycles.es<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como viene siendo habitual estas \u00faltimas semanas la estupenda Eva no deja de darme sorpresas con las marcas que se est\u00e1n uniendo a su \u00abagenda\u00bb como representante&#8230;. y claro&#8230; si&hellip; <\/p>\n","protected":false},"author":2,"featured_media":2666,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[80,76,77],"tags":[],"class_list":["post-2662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-mafia","category-noticias","category-novedades"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aun no conoces Bpart Components ??? - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aun no conoces Bpart Components ??? - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"Como viene siendo habitual estas \u00faltimas semanas la estupenda Eva no deja de darme sorpresas con las marcas que se est\u00e1n uniendo a su \u00abagenda\u00bb como representante&#8230;. y claro&#8230; si&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"ValwindCycles\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-16T19:04:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-04-16T19:11:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/04\/image.jpeg?fit=1181%2C1181&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t<meta property=\"og:image:height\" content=\"1181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge ValwindCycles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge ValwindCycles\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/aun-no-conoces-bpart-components#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/aun-no-conoces-bpart-components\"},\"author\":{\"name\":\"Jorge ValwindCycles\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"headline\":\"Aun no conoces Bpart Components ???\",\"datePublished\":\"2014-04-16T19:04:17+00:00\",\"dateModified\":\"2014-04-16T19:11:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/aun-no-conoces-bpart-components\"},\"wordCount\":316,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/aun-no-conoces-bpart-components#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/image.jpeg?fit=1181%2C1181&ssl=1\",\"articleSection\":[\"LA MAFIA\",\"NOTICIAS\",\"NOVEDADES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/aun-no-conoces-bpart-components#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/aun-no-conoces-bpart-components\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/aun-no-conoces-bpart-components\",\"name\":\"Aun no conoces Bpart Components ??? - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/aun-no-conoces-bpart-components#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/aun-no-conoces-bpart-components#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/image.jpeg?fit=1181%2C1181&ssl=1\",\"datePublished\":\"2014-04-16T19:04:17+00:00\",\"dateModified\":\"2014-04-16T19:11:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/aun-no-conoces-bpart-components#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/aun-no-conoces-bpart-components\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/aun-no-conoces-bpart-components#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/image.jpeg?fit=1181%2C1181&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/image.jpeg?fit=1181%2C1181&ssl=1\",\"width\":1181,\"height\":1181},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/aun-no-conoces-bpart-components#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aun no conoces Bpart Components ???\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\",\"name\":\"Jorge ValwindCycles\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"caption\":\"Jorge ValwindCycles\"},\"description\":\"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.\",\"sameAs\":[\"http:\\\/\\\/www.valwindcycles.es\",\"ValwindCycles\",\"http:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=180972148&trk=nav_responsive_tab_profile\",\"http:\\\/\\\/www.pinterest.com\\\/valwindcycles\\\/\",\"https:\\\/\\\/x.com\\\/JorgeValwind\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/Valwindcycles\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/valwind\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aun no conoces Bpart Components ??? - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components","og_locale":"es_ES","og_type":"article","og_title":"Aun no conoces Bpart Components ??? - El Blog de ValwindCycles","og_description":"Como viene siendo habitual estas \u00faltimas semanas la estupenda Eva no deja de darme sorpresas con las marcas que se est\u00e1n uniendo a su \u00abagenda\u00bb como representante&#8230;. y claro&#8230; si&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"ValwindCycles","article_published_time":"2014-04-16T19:04:17+00:00","article_modified_time":"2014-04-16T19:11:57+00:00","og_image":[{"width":1181,"height":1181,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/04\/image.jpeg?fit=1181%2C1181&ssl=1","type":"image\/jpeg"}],"author":"Jorge ValwindCycles","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Jorge ValwindCycles","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components"},"author":{"name":"Jorge ValwindCycles","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"headline":"Aun no conoces Bpart Components ???","datePublished":"2014-04-16T19:04:17+00:00","dateModified":"2014-04-16T19:11:57+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components"},"wordCount":316,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/04\/image.jpeg?fit=1181%2C1181&ssl=1","articleSection":["LA MAFIA","NOTICIAS","NOVEDADES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components","url":"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components","name":"Aun no conoces Bpart Components ??? - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/04\/image.jpeg?fit=1181%2C1181&ssl=1","datePublished":"2014-04-16T19:04:17+00:00","dateModified":"2014-04-16T19:11:57+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/04\/image.jpeg?fit=1181%2C1181&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/04\/image.jpeg?fit=1181%2C1181&ssl=1","width":1181,"height":1181},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/aun-no-conoces-bpart-components#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Aun no conoces Bpart Components ???"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3","name":"Jorge ValwindCycles","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","caption":"Jorge ValwindCycles"},"description":"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.","sameAs":["http:\/\/www.valwindcycles.es","ValwindCycles","http:\/\/www.linkedin.com\/profile\/view?id=180972148&trk=nav_responsive_tab_profile","http:\/\/www.pinterest.com\/valwindcycles\/","https:\/\/x.com\/JorgeValwind","http:\/\/www.youtube.com\/user\/Valwindcycles"],"url":"https:\/\/valwindcycles.es\/blog\/author\/valwind"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-GW","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/04\/image.jpeg?fit=1181%2C1181&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/2662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=2662"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/2662\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/2666"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=2662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=2662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=2662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}