{"id":2769,"date":"2014-05-20T08:27:29","date_gmt":"2014-05-20T07:27:29","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=2769"},"modified":"2014-05-20T08:28:21","modified_gmt":"2014-05-20T07:28:21","slug":"enduro-en-la-zona-zero-de-ainsa-por-eva-castro","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro","title":{"rendered":"Enduro en la Zona Zero de Ainsa por Eva Castro"},"content":{"rendered":"<p>Genial carrera de enduro en la Zona Zero de Ainsa. Senderos interminables espectaculares, una organizaci\u00f3n incre\u00edble y que mejor manera de acabar el fin de semana con una victoria.<br \/>\nGracias a toda la organizaci\u00f3n y voluntarios por el gran trabajo!!!!<\/p>\n<div id=\"attachment_2772\" style=\"width: 471px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10303384_10152416247265842_300189709502249265_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2772\" data-attachment-id=\"2772\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro\/10303384_10152416247265842_300189709502249265_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10303384_10152416247265842_300189709502249265_n.jpg?fit=960%2C717&amp;ssl=1\" data-orig-size=\"960,717\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"10303384_10152416247265842_300189709502249265_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10303384_10152416247265842_300189709502249265_n.jpg?fit=700%2C523&amp;ssl=1\" class=\" wp-image-2772\" title=\"con la colaboraci\u00f3n de MtbPro Magazine \" alt=\"con la colaboraci\u00f3n de MtbPro Magazine \" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10303384_10152416247265842_300189709502249265_n.jpg?resize=461%2C344&#038;ssl=1\" width=\"461\" height=\"344\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10303384_10152416247265842_300189709502249265_n.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10303384_10152416247265842_300189709502249265_n.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 461px) 100vw, 461px\" \/><\/a><p id=\"caption-attachment-2772\" class=\"wp-caption-text\">con la colaboraci\u00f3n de MtbPro Magazine<\/p><\/div>\n<div id=\"attachment_2774\" style=\"width: 486px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10372063_10152416247310842_747095719953427899_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2774\" data-attachment-id=\"2774\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro\/10372063_10152416247310842_747095719953427899_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10372063_10152416247310842_747095719953427899_n.jpg?fit=595%2C800&amp;ssl=1\" data-orig-size=\"595,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"10372063_10152416247310842_747095719953427899_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10372063_10152416247310842_747095719953427899_n.jpg?fit=595%2C800&amp;ssl=1\" class=\" wp-image-2774\" title=\"Reconociendo el terreno :)\" alt=\"Reconociendo el terreno :)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10372063_10152416247310842_747095719953427899_n.jpg?resize=476%2C640&#038;ssl=1\" width=\"476\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10372063_10152416247310842_747095719953427899_n.jpg?w=595&amp;ssl=1 595w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10372063_10152416247310842_747095719953427899_n.jpg?resize=223%2C300&amp;ssl=1 223w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><p id=\"caption-attachment-2774\" class=\"wp-caption-text\">Reconociendo el terreno \ud83d\ude42<\/p><\/div>\n<div id=\"attachment_2773\" style=\"width: 490px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10320560_10152418598620842_8925679885977009524_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2773\" data-attachment-id=\"2773\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro\/10320560_10152418598620842_8925679885977009524_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10320560_10152418598620842_8925679885977009524_n.jpg?fit=800%2C600&amp;ssl=1\" data-orig-size=\"800,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"10320560_10152418598620842_8925679885977009524_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10320560_10152418598620842_8925679885977009524_n.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-2773\" title=\"Con parte de los voluntarios celebrando la victoria \" alt=\"Con parte de los voluntarios celebrando la victoria\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10320560_10152418598620842_8925679885977009524_n.jpg?resize=480%2C360&#038;ssl=1\" width=\"480\" height=\"360\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10320560_10152418598620842_8925679885977009524_n.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10320560_10152418598620842_8925679885977009524_n.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><p id=\"caption-attachment-2773\" class=\"wp-caption-text\">Con parte de los voluntarios celebrando la victoria<\/p><\/div>\n<div id=\"attachment_2770\" style=\"width: 503px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/1012564_10152418598995842_8203379928223021819_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2770\" data-attachment-id=\"2770\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro\/1012564_10152418598995842_8203379928223021819_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/1012564_10152418598995842_8203379928223021819_n.jpg?fit=704%2C960&amp;ssl=1\" data-orig-size=\"704,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"1012564_10152418598995842_8203379928223021819_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/1012564_10152418598995842_8203379928223021819_n.jpg?fit=700%2C955&amp;ssl=1\" class=\"wp-image-2770 \" title=\"1er puesto Enduro en la Zona Zero de Ainsa \" alt=\"1er puesto Enduro en la Zona Zero de Ainsa \" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/1012564_10152418598995842_8203379928223021819_n.jpg?resize=493%2C672&#038;ssl=1\" width=\"493\" height=\"672\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/1012564_10152418598995842_8203379928223021819_n.jpg?w=704&amp;ssl=1 704w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/1012564_10152418598995842_8203379928223021819_n.jpg?resize=220%2C300&amp;ssl=1 220w\" sizes=\"auto, (max-width: 493px) 100vw, 493px\" \/><\/a><p id=\"caption-attachment-2770\" class=\"wp-caption-text\">1er puesto Enduro en la Zona Zero de Ainsa<\/p><\/div>\n<p>Detalle de los calcetos en el podium.. a que est\u00e1n chulos ? en breve quiz\u00e1s mas info sobre ellos \ud83d\ude42<\/p>\n<p>y parte de mi victoria es gracias a este fant\u00e1stico producto de los chicos de Musette &#8230;. el Booster que lo pod\u00e9is en encontrar en <a href=\"http:\/\/www.Valwindcycles.es\" target=\"_blank\">www.Valwindcycles.es <\/a><\/p>\n<p>\u00abEstoy enamorada de la p\u00f3cima. Ayer gan\u00e9 el enduro gracias a lo que entreno, pero tambi\u00e9n al Booster. Estaba cansada, pero en la \u00faltima crono fui a tope, con 2 kms planos de pedaleo en la parte final. \u00a1Sprint hasta meta!\u00bb<\/p>\n<div id=\"attachment_2771\" style=\"width: 501px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10264143_272629236252102_792683098670732862_o.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2771\" data-attachment-id=\"2771\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro\/10264143_272629236252102_792683098670732862_o\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10264143_272629236252102_792683098670732862_o.jpg?fit=1185%2C751&amp;ssl=1\" data-orig-size=\"1185,751\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"10264143_272629236252102_792683098670732862_o\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10264143_272629236252102_792683098670732862_o.jpg?fit=700%2C443&amp;ssl=1\" class=\" wp-image-2771\" title=\" el Booster que pod\u00e9is comprar en www.Valwindcycles.es\" alt=\" el Booster que pod\u00e9is comprar en www.Valwindcycles.es\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10264143_272629236252102_792683098670732862_o.jpg?resize=491%2C311&#038;ssl=1\" width=\"491\" height=\"311\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10264143_272629236252102_792683098670732862_o.jpg?resize=1024%2C648&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10264143_272629236252102_792683098670732862_o.jpg?resize=300%2C190&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10264143_272629236252102_792683098670732862_o.jpg?w=1185&amp;ssl=1 1185w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><\/a><p id=\"caption-attachment-2771\" class=\"wp-caption-text\">el Booster que pod\u00e9is comprar en www.Valwindcycles.es<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Genial carrera de enduro en la Zona Zero de Ainsa. Senderos interminables espectaculares, una organizaci\u00f3n incre\u00edble y que mejor manera de acabar el fin de semana con una victoria. Gracias&hellip; <\/p>\n","protected":false},"author":47,"featured_media":2774,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[72,80,76],"tags":[],"class_list":["post-2769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-la-mafia","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enduro en la Zona Zero de Ainsa por Eva Castro - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enduro en la Zona Zero de Ainsa por Eva Castro - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"Genial carrera de enduro en la Zona Zero de Ainsa. Senderos interminables espectaculares, una organizaci\u00f3n incre\u00edble y que mejor manera de acabar el fin de semana con una victoria. Gracias&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"EvaCastroRider3?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-20T07:27:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-05-20T07:28:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10372063_10152416247310842_747095719953427899_n.jpg?fit=595%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"595\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eva Castro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EvaC33\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eva Castro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro\"},\"author\":{\"name\":\"Eva Castro\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/c12678583219ee01e9b90c461e5c5aee\"},\"headline\":\"Enduro en la Zona Zero de Ainsa por Eva Castro\",\"datePublished\":\"2014-05-20T07:27:29+00:00\",\"dateModified\":\"2014-05-20T07:28:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro\"},\"wordCount\":218,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/10372063_10152416247310842_747095719953427899_n.jpg?fit=595%2C800&ssl=1\",\"articleSection\":[\"Eventos\",\"LA MAFIA\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro\",\"name\":\"Enduro en la Zona Zero de Ainsa por Eva Castro - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/10372063_10152416247310842_747095719953427899_n.jpg?fit=595%2C800&ssl=1\",\"datePublished\":\"2014-05-20T07:27:29+00:00\",\"dateModified\":\"2014-05-20T07:28:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/c12678583219ee01e9b90c461e5c5aee\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/10372063_10152416247310842_747095719953427899_n.jpg?fit=595%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/10372063_10152416247310842_747095719953427899_n.jpg?fit=595%2C800&ssl=1\",\"width\":595,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enduro en la Zona Zero de Ainsa por Eva Castro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/c12678583219ee01e9b90c461e5c5aee\",\"name\":\"Eva Castro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c9cb0716f614ff201e92deeb313e813fc84ce56508c243dfdad7cc22183cc3e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c9cb0716f614ff201e92deeb313e813fc84ce56508c243dfdad7cc22183cc3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c9cb0716f614ff201e92deeb313e813fc84ce56508c243dfdad7cc22183cc3e?s=96&d=mm&r=g\",\"caption\":\"Eva Castro\"},\"description\":\"Recordada mundialmente por poner los pelos de punta a todos los que est\u00e1bamos en 2007 en la WorldCup 4X de Vigo\u2026 una bajada con instinto asesino y resultado de Podium. Es la encargada del tema competici\u00f3n tanto DH como FourCross donde nos dar\u00e1 su punto de vista de las Worldcup a lo largo del a\u00f1o y test de productos donde como no ser\u00e1n los art\u00edculos orientados al lado mas salvaje y oscuro del Mtb\u2026 enDURO \u2026\",\"sameAs\":[\"http:\\\/\\\/evacastro2007.blogspot.com.es\",\"EvaCastroRider3?fref=ts\",\"https:\\\/\\\/x.com\\\/EvaC33\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/VideoEva1\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/eva\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enduro en la Zona Zero de Ainsa por Eva Castro - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro","og_locale":"es_ES","og_type":"article","og_title":"Enduro en la Zona Zero de Ainsa por Eva Castro - El Blog de ValwindCycles","og_description":"Genial carrera de enduro en la Zona Zero de Ainsa. Senderos interminables espectaculares, una organizaci\u00f3n incre\u00edble y que mejor manera de acabar el fin de semana con una victoria. Gracias&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"EvaCastroRider3?fref=ts","article_published_time":"2014-05-20T07:27:29+00:00","article_modified_time":"2014-05-20T07:28:21+00:00","og_image":[{"width":595,"height":800,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10372063_10152416247310842_747095719953427899_n.jpg?fit=595%2C800&ssl=1","type":"image\/jpeg"}],"author":"Eva Castro","twitter_card":"summary_large_image","twitter_creator":"@EvaC33","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Eva Castro","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro"},"author":{"name":"Eva Castro","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/c12678583219ee01e9b90c461e5c5aee"},"headline":"Enduro en la Zona Zero de Ainsa por Eva Castro","datePublished":"2014-05-20T07:27:29+00:00","dateModified":"2014-05-20T07:28:21+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro"},"wordCount":218,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10372063_10152416247310842_747095719953427899_n.jpg?fit=595%2C800&ssl=1","articleSection":["Eventos","LA MAFIA","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro","url":"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro","name":"Enduro en la Zona Zero de Ainsa por Eva Castro - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10372063_10152416247310842_747095719953427899_n.jpg?fit=595%2C800&ssl=1","datePublished":"2014-05-20T07:27:29+00:00","dateModified":"2014-05-20T07:28:21+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/c12678583219ee01e9b90c461e5c5aee"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10372063_10152416247310842_747095719953427899_n.jpg?fit=595%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10372063_10152416247310842_747095719953427899_n.jpg?fit=595%2C800&ssl=1","width":595,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/enduro-en-la-zona-zero-de-ainsa-por-eva-castro#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Enduro en la Zona Zero de Ainsa por Eva Castro"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/c12678583219ee01e9b90c461e5c5aee","name":"Eva Castro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6c9cb0716f614ff201e92deeb313e813fc84ce56508c243dfdad7cc22183cc3e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c9cb0716f614ff201e92deeb313e813fc84ce56508c243dfdad7cc22183cc3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c9cb0716f614ff201e92deeb313e813fc84ce56508c243dfdad7cc22183cc3e?s=96&d=mm&r=g","caption":"Eva Castro"},"description":"Recordada mundialmente por poner los pelos de punta a todos los que est\u00e1bamos en 2007 en la WorldCup 4X de Vigo\u2026 una bajada con instinto asesino y resultado de Podium. Es la encargada del tema competici\u00f3n tanto DH como FourCross donde nos dar\u00e1 su punto de vista de las Worldcup a lo largo del a\u00f1o y test de productos donde como no ser\u00e1n los art\u00edculos orientados al lado mas salvaje y oscuro del Mtb\u2026 enDURO \u2026","sameAs":["http:\/\/evacastro2007.blogspot.com.es","EvaCastroRider3?fref=ts","https:\/\/x.com\/EvaC33","http:\/\/www.youtube.com\/user\/VideoEva1"],"url":"https:\/\/valwindcycles.es\/blog\/author\/eva"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-IF","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/05\/10372063_10152416247310842_747095719953427899_n.jpg?fit=595%2C800&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/2769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=2769"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/2769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/2774"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=2769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=2769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=2769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}