{"id":287,"date":"2012-05-18T09:00:06","date_gmt":"2012-05-18T07:00:06","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=287"},"modified":"2012-05-18T14:48:40","modified_gmt":"2012-05-18T12:48:40","slug":"kenda-nevegal-tubeless-2-1","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1","title":{"rendered":"Kenda Nevegal Tubeless 2.1"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div id=\"attachment_358\" style=\"width: 452px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-358\" data-attachment-id=\"358\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1\/dsc09101\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101.jpg?fit=3072%2C2304&amp;ssl=1\" data-orig-size=\"3072,2304\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DSC-W55&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1331399783&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.3&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.025&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Kenda Nevegal Tubeless 2.1\" data-image-description=\"&lt;p&gt;Kenda Nevegal Tubeless 2.1&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Kenda Nevegal Tubeless 2.1&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-358   \" title=\"Kenda Nevegal Tubeless 2.1\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101.jpg?resize=442%2C332&#038;ssl=1\" alt=\"Kenda Nevegal Tubeless 2.1\" width=\"442\" height=\"332\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><\/a><p id=\"caption-attachment-358\" class=\"wp-caption-text\">Kenda Nevegal Tubeless 2.1<\/p><\/div>\n<p>La Kenda Nevegal es la cubierta todo uso de Kenda, y en cada versi\u00f3n ofrece unas caracter\u00edsticas muy diferentes que hacen que en cada medida nos resulte una cubierta muy diferente. En el caso del modelo 2.1 Tubeless tenemos una cubierta que enga\u00f1a, dado que su medida nos har\u00eda pensar en una cubierta encaminada al XC, sin embargo es una cubierta con un bal\u00f3n m\u00e1s que suficiente para un uso All Mountain o incluso Enduro ligero, su agarre es una de sus mayores ventajas en especial el agarre lateral donde se percibe de forma clara cuando llegamos al l\u00edmite de este sin llegar a deslizar la cubierta, adem\u00e1s de ofrecer una tracci\u00f3n sorprendente, todo ello es en gran parte debido al uso del DTC (Dual Tread Compound), esto no es m\u00e1s que la combinaci\u00f3n de 2 de los compuestos de competici\u00f3n de Kenda, por un lado el compuesto Stick-E en los flancos, un tipo de goma especialmente blanda en los flancos (dureza Shore 50A) dise\u00f1ada para que prime el agarre en las situaciones extremas donde la prioridad es el agarre lateral; por otro lado el compuesto L3R un compuesto de dureza media (dureza Shore 60A) que hace que la durabilidad de la cubierta sea mayor sin poner en compromiso la tracci\u00f3n a la vez que se reduce la resistencia a la rodadura.<\/p>\n<p>Este equilibro de compuestos sumado a un taqueado intermedio dise\u00f1ado para equilibrar los 3 factores esenciales en una cubierta, baja resistencia a la rodadura, alta tracci\u00f3n y gran agarre, hacen a esta cubierta en la ideal tanto delante como detr\u00e1s para infinidad de terrenos y usos, desde suelos compactos, a suelos con barro moderado o terrenos de roca suelta o ra\u00edces sin mostrar carencias en ninguno de estos campos, convirti\u00e9ndose en una magn\u00edfica idea para todas aquellas personas que no quieran complicarse en cambios de cubierta seg\u00fan la meteorolog\u00eda, o la zona donde vayan a circular.<\/p>\n<p>Otro aspecto destacable de la Nevegal UST es su resistencia a los pinchazos, en primero lugar al ser una cubierta dise\u00f1ada espec\u00edficamente para UST tiene los flancos reforzados por lo que los pellizcos y llantazos son pr\u00e1cticamente anecd\u00f3ticos, el complemento perfecto ser\u00e1 un kit antipinchazos como el Kit sellante Stan\u2019s No Tubes, en mi caso incluso un clavo de 2mm de di\u00e1metro no ha sido suficiente para detenerme en una ruta.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_362\" style=\"width: 432px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/2012-05-05-11.54.05.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-362\" data-attachment-id=\"362\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1\/2012-05-05-11-54-05\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/2012-05-05-11.54.05.jpg?fit=3218%2C2400&amp;ssl=1\" data-orig-size=\"3218,2400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;LG-P999&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"rodando con el clavo sin problemas\" data-image-description=\"&lt;p&gt;rodando con el clavo sin problemas&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;rodando con el clavo sin problemas&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/2012-05-05-11.54.05.jpg?fit=700%2C522&amp;ssl=1\" class=\" wp-image-362       \" title=\"rodando con el clavo sin problemas\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/2012-05-05-11.54.05.jpg?resize=422%2C315&#038;ssl=1\" alt=\"rodando con el clavo sin problemas\" width=\"422\" height=\"315\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/2012-05-05-11.54.05.jpg?resize=1024%2C763&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/2012-05-05-11.54.05.jpg?resize=300%2C223&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/2012-05-05-11.54.05.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/2012-05-05-11.54.05.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 422px) 100vw, 422px\" \/><\/a><p id=\"caption-attachment-362\" class=\"wp-caption-text\">rodando con el clavo sin problemas<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>El peso, en Kenda es bastante variable, el peso medio son 820 gramos con una horquilla de error de de 40 gramos tanto por encima como por debajo, de hecho las unidades que utilizo actualmente est\u00e1n en 784 y 787 gramos, sin embargo los pesos de Kenda son bastante variables de unas unidades a otras tal y como indican los peso de cat\u00e1logo.<\/p>\n<p>En definitiva la Nevegal 2.1 UST es la cubierta perfecta para un amplio rango de usuarios, desde quienes quieren una cubierta polivalente y duradera para entrenar, a rutas en las que buscas algo m\u00e1s, Trail o incluso ser\u00eda una buena opci\u00f3n como cubierta trasera para una bici de enduro dando m\u00e1s manejabilidad de cara a los cambios de direcci\u00f3n bruscos sobre el modelo de 2.35, sin embargo no es aconsejable dejarse enga\u00f1ar por la medida dado que el bal\u00f3n, comparado con otras marcas es m\u00e1s ancho de lo que podr\u00edamos pensar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La Kenda Nevegal es la cubierta todo uso de Kenda, y en cada versi\u00f3n ofrece unas caracter\u00edsticas muy diferentes que hacen que en cada medida nos resulte una cubierta&hellip; <\/p>\n","protected":false},"author":4,"featured_media":358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[75],"tags":[],"class_list":["post-287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-test"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kenda Nevegal Tubeless 2.1 - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kenda Nevegal Tubeless 2.1 - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"&nbsp; La Kenda Nevegal es la cubierta todo uso de Kenda, y en cada versi\u00f3n ofrece unas caracter\u00edsticas muy diferentes que hacen que en cada medida nos resulte una cubierta&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"ryder.mad\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-18T07:00:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-05-18T12:48:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101-1024x768.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luis Lumbreras &quot;Luiggi&quot;\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Lumbreras &quot;Luiggi&quot;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/kenda-nevegal-tubeless-2-1#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/kenda-nevegal-tubeless-2-1\"},\"author\":{\"name\":\"Luis Lumbreras \\\"Luiggi\\\"\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/ca50cd9daacbde4651c361ff1e90d274\"},\"headline\":\"Kenda Nevegal Tubeless 2.1\",\"datePublished\":\"2012-05-18T07:00:06+00:00\",\"dateModified\":\"2012-05-18T12:48:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/kenda-nevegal-tubeless-2-1\"},\"wordCount\":605,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/kenda-nevegal-tubeless-2-1#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/DSC09101.jpg?fit=3072%2C2304&ssl=1\",\"articleSection\":[\"Test\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/kenda-nevegal-tubeless-2-1#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/kenda-nevegal-tubeless-2-1\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/kenda-nevegal-tubeless-2-1\",\"name\":\"Kenda Nevegal Tubeless 2.1 - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/kenda-nevegal-tubeless-2-1#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/kenda-nevegal-tubeless-2-1#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/DSC09101.jpg?fit=3072%2C2304&ssl=1\",\"datePublished\":\"2012-05-18T07:00:06+00:00\",\"dateModified\":\"2012-05-18T12:48:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/ca50cd9daacbde4651c361ff1e90d274\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/kenda-nevegal-tubeless-2-1#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/kenda-nevegal-tubeless-2-1\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/kenda-nevegal-tubeless-2-1#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/DSC09101.jpg?fit=3072%2C2304&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/DSC09101.jpg?fit=3072%2C2304&ssl=1\",\"width\":\"3072\",\"height\":\"2304\",\"caption\":\"Kenda Nevegal Tubeless 2.1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/kenda-nevegal-tubeless-2-1#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kenda Nevegal Tubeless 2.1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/ca50cd9daacbde4651c361ff1e90d274\",\"name\":\"Luis Lumbreras \\\"Luiggi\\\"\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f61045ec2fb7b307e3875ca714c2f6b224535ceab4bd12409b2e6ba82d8cf4f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f61045ec2fb7b307e3875ca714c2f6b224535ceab4bd12409b2e6ba82d8cf4f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f61045ec2fb7b307e3875ca714c2f6b224535ceab4bd12409b2e6ba82d8cf4f?s=96&d=mm&r=g\",\"caption\":\"Luis Lumbreras \\\"Luiggi\\\"\"},\"description\":\"Mi Test Dummy, mi gu\u00eda espiritual, mi Sensei, mi Kitsune, mi amigo.... Dicen las malas lenguas que ha cambiado sus huesos por tubos de carbono y que lleva atornilladas las calas directamente al pi\u00e9.\",\"sameAs\":[\"http:\\\/\\\/kitsunebikeparts.tk\\\/\",\"ryder.mad\",\"http:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=114507000&locale=es_ES&trk=tyah&trkInfo=tasluislumbrerasidx1-1-1\",\"http:\\\/\\\/www.pinterest.com\\\/llumbreras\\\/kitsune\\\/\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/luis-lumbreras\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kenda Nevegal Tubeless 2.1 - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1","og_locale":"es_ES","og_type":"article","og_title":"Kenda Nevegal Tubeless 2.1 - El Blog de ValwindCycles","og_description":"&nbsp; La Kenda Nevegal es la cubierta todo uso de Kenda, y en cada versi\u00f3n ofrece unas caracter\u00edsticas muy diferentes que hacen que en cada medida nos resulte una cubierta&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"ryder.mad","article_published_time":"2012-05-18T07:00:06+00:00","article_modified_time":"2012-05-18T12:48:40+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101-1024x768.jpg","type":"image\/jpeg"}],"author":"Luis Lumbreras \"Luiggi\"","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Luis Lumbreras \"Luiggi\"","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1"},"author":{"name":"Luis Lumbreras \"Luiggi\"","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/ca50cd9daacbde4651c361ff1e90d274"},"headline":"Kenda Nevegal Tubeless 2.1","datePublished":"2012-05-18T07:00:06+00:00","dateModified":"2012-05-18T12:48:40+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1"},"wordCount":605,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101.jpg?fit=3072%2C2304&ssl=1","articleSection":["Test"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1","url":"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1","name":"Kenda Nevegal Tubeless 2.1 - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101.jpg?fit=3072%2C2304&ssl=1","datePublished":"2012-05-18T07:00:06+00:00","dateModified":"2012-05-18T12:48:40+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/ca50cd9daacbde4651c361ff1e90d274"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101.jpg?fit=3072%2C2304&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101.jpg?fit=3072%2C2304&ssl=1","width":"3072","height":"2304","caption":"Kenda Nevegal Tubeless 2.1"},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/kenda-nevegal-tubeless-2-1#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Kenda Nevegal Tubeless 2.1"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/ca50cd9daacbde4651c361ff1e90d274","name":"Luis Lumbreras \"Luiggi\"","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1f61045ec2fb7b307e3875ca714c2f6b224535ceab4bd12409b2e6ba82d8cf4f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f61045ec2fb7b307e3875ca714c2f6b224535ceab4bd12409b2e6ba82d8cf4f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f61045ec2fb7b307e3875ca714c2f6b224535ceab4bd12409b2e6ba82d8cf4f?s=96&d=mm&r=g","caption":"Luis Lumbreras \"Luiggi\""},"description":"Mi Test Dummy, mi gu\u00eda espiritual, mi Sensei, mi Kitsune, mi amigo.... Dicen las malas lenguas que ha cambiado sus huesos por tubos de carbono y que lleva atornilladas las calas directamente al pi\u00e9.","sameAs":["http:\/\/kitsunebikeparts.tk\/","ryder.mad","http:\/\/www.linkedin.com\/profile\/view?id=114507000&locale=es_ES&trk=tyah&trkInfo=tasluislumbrerasidx1-1-1","http:\/\/www.pinterest.com\/llumbreras\/kitsune\/"],"url":"https:\/\/valwindcycles.es\/blog\/author\/luis-lumbreras"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-4D","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2012\/05\/DSC09101.jpg?fit=3072%2C2304&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=287"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/358"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}