{"id":29,"date":"2010-01-04T20:51:00","date_gmt":"2010-01-04T20:51:00","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=29"},"modified":"2010-01-04T20:51:00","modified_gmt":"2010-01-04T20:51:00","slug":"team-valwind","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/team-valwind","title":{"rendered":"Team Valwind"},"content":{"rendered":"<p>Despu\u00e9s de varios d\u00edas buscando informaci\u00f3n por los sitios mas \u00abraros\u00bb ya tengo listo mi \u00abcurr\u00edculum deportivo\u00bb, bueno o algo parecido, tendr\u00eda que tener algunos datos mas ya que faltan carreras, bueno faltan muchas&nbsp;ya que&nbsp;solo puse las importantes&#8230;..<br \/>Y para que? bueno pues este a\u00f1o \u00abnacer\u00e1\u00bb mi equipo, bueno equipo no, mas bien mono-equipo ya que este a\u00f1o ser\u00e9 yo el \u00abpatrocinado\u00bb por mi tienda <a href=\"http:\/\/www.valwindcycles.com\/\">Valwindcycles<\/a> y sobre todo con la colaboraci\u00f3n de mi gran amigo <a href=\"http:\/\/www.ramonironbaby.com\/index.php?page=biografia\">Ram\u00f3n Gonzalez<\/a>&nbsp;conocido&nbsp;como IronBaby en el mundo del culturismo,&nbsp;un Pro&nbsp;tanto deportivamente como personalmente,&nbsp;al cual le tengo que estar muy agradecido, no solo por su amistad y&nbsp;esta oportunidad si no que ya me hab\u00eda \u00abayudado\u00bb con el patrocinio de su&nbsp;linea de tiendas&nbsp;<span style=\"color: red;\"><strong>Fitness Zone<\/strong><\/span> hace unos a\u00f1os.<\/p>\n<p>Podeis visitar cualquiera de sus tiendas en las siguientes localidades:<\/p>\n<p><span style=\"color: red;\"><strong>Fitness Zone &#8211; Vigo<\/strong><\/span><br \/><span style=\"color: red;\"><strong><\/strong><\/span><\/p>\n<p>Direcci\u00f3n: C\/ L\u00f3pez Mora, 64 &#8211; Bajo<\/p>\n<p>C\u00f3digo Postal: 36211<\/p>\n<p>Ciudad: Vigo<\/p>\n<p>Provincia: Pontevedra <\/p>\n<p>Tel\u00e9fono:986 42 52 31<\/p>\n<p><span style=\"color: red;\"><strong>Fitness Zone &#8211;&nbsp;Ourense<\/strong><\/span><\/p>\n<p>Direcci\u00f3n: C\/ Jes\u00fas Soria, 2 &#8211; Bajo<\/p>\n<p>C\u00f3digo Postal: 32002<\/p>\n<p>Ciudad: Orense<\/p>\n<p>Provincia: Orense <\/p>\n<p>Tel\u00e9fono:988 60 91 61<\/p>\n<p>Correo electr\u00f3nico <a href=\"mailto:fitnesszone@ramonironbaby.com\">fitnesszone@ramonironbaby.com<\/a><\/p>\n<p>Respecto al \u00abfuturo\u00bb del equipo para el a\u00f1o que viene ya \u00ababriremos\u00bb el mercado de \u00abfichajes\u00bb&#8230;<\/p>\n<p>Y con Ram\u00f3n como intermediario puede que surja la colaboraci\u00f3n conmigo&nbsp;de una marca de suplementos deportivos, la cual a\u00fan no dir\u00e9 su nombre ya que no es fijo, aunque con el buen hacer de Ram\u00f3n seguro que consigue que tenga a mi disposicion la fant\u00e1stica linea de productos de esta marca.<\/p>\n<p>Pod\u00e9is entrar en la <a href=\"http:\/\/www.ramonironbaby.com\/index.php?page=biografia\">web de Ram\u00f3n<\/a> si quereis saber mas sobre su carrera deportiva o para solicitar su ayuda en la consecucion de vuestros objetivos deportivos mediante la preparacion de dietas, entrenos&nbsp;o suplementacion.<\/p>\n<p>Una vista previa de mi \u00abcurr\u00edculum\u00bb<\/p>\n<p><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a href=\"https:\/\/i0.wp.com\/3.bp.blogspot.com\/_4Vs_a38m158\/S0cKGFJZASI\/AAAAAAAABiA\/Vf0EodRd9sE\/s1600-h\/catsx%2Bsin.jpg\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\"><img data-recalc-dims=\"1\" decoding=\"async\" border=\"0\" ps=\"true\" src=\"https:\/\/i0.wp.com\/3.bp.blogspot.com\/_4Vs_a38m158\/S0cKGFJZASI\/AAAAAAAABiA\/Vf0EodRd9sE\/s640\/catsx%2Bsin.jpg?w=700\" \/><\/a><\/div>\n<p><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><\/div>\n<p>Ya ir\u00e9 comentando alguna cosa mas sobre el equipo ya que estoy con el tema dise\u00f1o de ropa y dem\u00e1s historias de federacion y similares.<\/p>\n<p>Bye.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de varios d\u00edas buscando informaci\u00f3n por los sitios mas \u00abraros\u00bb ya tengo listo mi \u00abcurr\u00edculum deportivo\u00bb, bueno o algo parecido, tendr\u00eda que tener algunos datos mas ya que faltan&hellip; <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,4],"tags":[],"class_list":["post-29","post","type-post","status-publish","format-standard","hentry","category-fitness-zone","category-team-valwind"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Team Valwind - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/team-valwind\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Team Valwind - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de varios d\u00edas buscando informaci\u00f3n por los sitios mas \u00abraros\u00bb ya tengo listo mi \u00abcurr\u00edculum deportivo\u00bb, bueno o algo parecido, tendr\u00eda que tener algunos datos mas ya que faltan&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/team-valwind\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"ValwindCycles\" \/>\n<meta property=\"article:published_time\" content=\"2010-01-04T20:51:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.bp.blogspot.com\/_4Vs_a38m158\/S0cKGFJZASI\/AAAAAAAABiA\/Vf0EodRd9sE\/s640\/catsx+sin.jpg\" \/>\n<meta name=\"author\" content=\"Jorge ValwindCycles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge ValwindCycles\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/team-valwind#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/team-valwind\"},\"author\":{\"name\":\"Jorge ValwindCycles\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"headline\":\"Team Valwind\",\"datePublished\":\"2010-01-04T20:51:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/team-valwind\"},\"wordCount\":360,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/team-valwind#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/_4Vs_a38m158\\\/S0cKGFJZASI\\\/AAAAAAAABiA\\\/Vf0EodRd9sE\\\/s640\\\/catsx+sin.jpg\",\"articleSection\":[\"Fitness zone\",\"Team Valwind\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/team-valwind#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/team-valwind\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/team-valwind\",\"name\":\"Team Valwind - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/team-valwind#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/team-valwind#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/_4Vs_a38m158\\\/S0cKGFJZASI\\\/AAAAAAAABiA\\\/Vf0EodRd9sE\\\/s640\\\/catsx+sin.jpg\",\"datePublished\":\"2010-01-04T20:51:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/team-valwind#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/team-valwind\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/team-valwind#primaryimage\",\"url\":\"http:\\\/\\\/3.bp.blogspot.com\\\/_4Vs_a38m158\\\/S0cKGFJZASI\\\/AAAAAAAABiA\\\/Vf0EodRd9sE\\\/s640\\\/catsx+sin.jpg\",\"contentUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/_4Vs_a38m158\\\/S0cKGFJZASI\\\/AAAAAAAABiA\\\/Vf0EodRd9sE\\\/s640\\\/catsx+sin.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/team-valwind#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Team Valwind\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\",\"name\":\"Jorge ValwindCycles\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"caption\":\"Jorge ValwindCycles\"},\"description\":\"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.\",\"sameAs\":[\"http:\\\/\\\/www.valwindcycles.es\",\"ValwindCycles\",\"http:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=180972148&trk=nav_responsive_tab_profile\",\"http:\\\/\\\/www.pinterest.com\\\/valwindcycles\\\/\",\"https:\\\/\\\/x.com\\\/JorgeValwind\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/Valwindcycles\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/valwind\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Team Valwind - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/team-valwind","og_locale":"es_ES","og_type":"article","og_title":"Team Valwind - El Blog de ValwindCycles","og_description":"Despu\u00e9s de varios d\u00edas buscando informaci\u00f3n por los sitios mas \u00abraros\u00bb ya tengo listo mi \u00abcurr\u00edculum deportivo\u00bb, bueno o algo parecido, tendr\u00eda que tener algunos datos mas ya que faltan&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/team-valwind","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"ValwindCycles","article_published_time":"2010-01-04T20:51:00+00:00","og_image":[{"url":"http:\/\/3.bp.blogspot.com\/_4Vs_a38m158\/S0cKGFJZASI\/AAAAAAAABiA\/Vf0EodRd9sE\/s640\/catsx+sin.jpg","type":"","width":"","height":""}],"author":"Jorge ValwindCycles","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Jorge ValwindCycles","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/team-valwind#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/team-valwind"},"author":{"name":"Jorge ValwindCycles","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"headline":"Team Valwind","datePublished":"2010-01-04T20:51:00+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/team-valwind"},"wordCount":360,"commentCount":2,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/team-valwind#primaryimage"},"thumbnailUrl":"http:\/\/3.bp.blogspot.com\/_4Vs_a38m158\/S0cKGFJZASI\/AAAAAAAABiA\/Vf0EodRd9sE\/s640\/catsx+sin.jpg","articleSection":["Fitness zone","Team Valwind"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/team-valwind#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/team-valwind","url":"https:\/\/valwindcycles.es\/blog\/team-valwind","name":"Team Valwind - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/team-valwind#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/team-valwind#primaryimage"},"thumbnailUrl":"http:\/\/3.bp.blogspot.com\/_4Vs_a38m158\/S0cKGFJZASI\/AAAAAAAABiA\/Vf0EodRd9sE\/s640\/catsx+sin.jpg","datePublished":"2010-01-04T20:51:00+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/team-valwind#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/team-valwind"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/team-valwind#primaryimage","url":"http:\/\/3.bp.blogspot.com\/_4Vs_a38m158\/S0cKGFJZASI\/AAAAAAAABiA\/Vf0EodRd9sE\/s640\/catsx+sin.jpg","contentUrl":"http:\/\/3.bp.blogspot.com\/_4Vs_a38m158\/S0cKGFJZASI\/AAAAAAAABiA\/Vf0EodRd9sE\/s640\/catsx+sin.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/team-valwind#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Team Valwind"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3","name":"Jorge ValwindCycles","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","caption":"Jorge ValwindCycles"},"description":"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.","sameAs":["http:\/\/www.valwindcycles.es","ValwindCycles","http:\/\/www.linkedin.com\/profile\/view?id=180972148&trk=nav_responsive_tab_profile","http:\/\/www.pinterest.com\/valwindcycles\/","https:\/\/x.com\/JorgeValwind","http:\/\/www.youtube.com\/user\/Valwindcycles"],"url":"https:\/\/valwindcycles.es\/blog\/author\/valwind"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-t","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=29"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/29\/revisions"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=29"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=29"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}