{"id":3176,"date":"2014-08-03T20:54:02","date_gmt":"2014-08-03T19:54:02","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=3176"},"modified":"2014-08-03T20:54:02","modified_gmt":"2014-08-03T19:54:02","slug":"12-horas-btt-abegondo-fotos-por-pirucho-pequeno","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno","title":{"rendered":"12 Horas BTT Abegondo Fotos por Pirucho Pequeno"},"content":{"rendered":"<p>Aprovechando el par\u00f3n en el Open, este fin de semana participamos en las 12 Horas BTT Abegondo.<\/p>\n<p>Como se puede adivinar por su nombre se trata de una prueba cicloturista de gran fondo de 12 horas de duraci\u00f3n, cuyas normas son muy sencillas, desde las 10:00 hasta las 22:00 se pueden dar todas las vueltas que se quieran a un circuito marcado por la organizaci\u00f3n y gana quien m\u00e1s vueltas complete.<\/p>\n<p>La participaci\u00f3n puede realizarse de manera individual o por equipos, en formaciones de 2, 3 o 4 miembros, formados por miembros del mismo sexo o mixtos.<\/p>\n<p>Bicicletas Brais Chas eligi\u00f3 un enclave privilegiado para su desarrollo, la meta estaba situada en el centro del ayuntamiento de Abegondo, lugar con todos los servicios necesarios; aparcamiento, duchas, servicios, cafeter\u00eda y espacio para las carpas de los equipos.<\/p>\n<p>Respecto al trazado era perfecto para este tipo de pruebas; con una longitud de 9 km , un perfil muy rodador y sin dificultad t\u00e9cnica, esto permite hacer muchos kil\u00f3metros sin tener que pasar apuros cuando se acumula el cansancio. La nota negativa la pusieron los diversos chaparones que tuvimos que sufrir a pesar de estar a 2 de Agosto (esto es el verano gallego), aun as\u00ed el circuito se mantuvo 100% ciclable pero un poquito m\u00e1s divertido por lo resbaladizo que se puso alguna zona.<\/p>\n<p>Se organiz\u00f3 como una prueba \u201cno competitiva\u201d por lo que fue la ocasi\u00f3n perfecta para disfrutar de una jordana entera de diversi\u00f3n con los amigos, pero vivimos en Espa\u00f1a y la competitividad se toma junto con el caf\u00e9, sin p\u00f3dium, ni trofeos, siguen surgiendo los \u201cpiques\u201d sanos donde todo equipo intenta dar m\u00e1s vueltas que el vecino, lo cual le otorga a este tipo de pruebas su car\u00e1cter adictivo.<\/p>\n<p>Mis felicitaciones a la organizaci\u00f3n, maravillosamente arropados por la voz y locuci\u00f3n del speaker Victorio Rodriguez, las 12 horas pasaron volando, esperamos impacientes la 2\u00aa edici\u00f3n en el 2015.<\/p>\n<p>El enlace con las fotograf\u00edas:<a href=\"https:\/\/plus.google.com\/u\/0\/photos\/+LuzIglesias\/albums\/6043302300466390321\" target=\"_blank\"> AQUI\u00a0<\/a><\/p>\n<p>PD: Por segunda vez en mi vida como fot\u00f3grafa aficionada, fui atropellada por un ciclista, pod\u00e9is ver la foto del antes, se ve como el pobre chico se golpea primero la cara contra un arbolito, por eso me alegra que me atropellase, as\u00ed cay\u00f3 sobre algo blando (o sea ,yo)<\/p>\n<div id=\"attachment_3177\" style=\"width: 447px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018387.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3177\" data-attachment-id=\"3177\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018387\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018387.jpg?fit=694%2C743&amp;ssl=1\" data-orig-size=\"694,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (24)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018387.jpg?fit=694%2C743&amp;ssl=1\" class=\" wp-image-3177  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (24)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018387.jpg?resize=437%2C468&#038;ssl=1\" width=\"437\" height=\"468\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018387.jpg?w=694&amp;ssl=1 694w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018387.jpg?resize=280%2C300&amp;ssl=1 280w\" sizes=\"auto, (max-width: 437px) 100vw, 437px\" \/><\/a><p id=\"caption-attachment-3177\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3199\" style=\"width: 456px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019140.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3199\" data-attachment-id=\"3199\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1019140\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019140.jpg?fit=557%2C743&amp;ssl=1\" data-orig-size=\"557,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (2)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019140.jpg?fit=557%2C743&amp;ssl=1\" class=\" wp-image-3199 \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (2)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019140.jpg?resize=446%2C594&#038;ssl=1\" width=\"446\" height=\"594\" \/><\/a><p id=\"caption-attachment-3199\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3198\" style=\"width: 486px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019106.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3198\" data-attachment-id=\"3198\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1019106\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019106.jpg?fit=991%2C743&amp;ssl=1\" data-orig-size=\"991,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (3)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019106.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-3198  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (3)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019106.jpg?resize=476%2C357&#038;ssl=1\" width=\"476\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019106.jpg?w=991&amp;ssl=1 991w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019106.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><p id=\"caption-attachment-3198\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3197\" style=\"width: 455px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019021.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3197\" data-attachment-id=\"3197\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1019021\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019021.jpg?fit=926%2C743&amp;ssl=1\" data-orig-size=\"926,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (4)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019021.jpg?fit=700%2C562&amp;ssl=1\" class=\" wp-image-3197  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (4)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019021.jpg?resize=445%2C357&#038;ssl=1\" width=\"445\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019021.jpg?w=926&amp;ssl=1 926w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019021.jpg?resize=300%2C240&amp;ssl=1 300w\" sizes=\"auto, (max-width: 445px) 100vw, 445px\" \/><\/a><p id=\"caption-attachment-3197\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3193\" style=\"width: 486px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018899.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3193\" data-attachment-id=\"3193\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018899\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018899.jpg?fit=991%2C743&amp;ssl=1\" data-orig-size=\"991,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (8)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018899.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-3193  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (8)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018899.jpg?resize=476%2C357&#038;ssl=1\" width=\"476\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018899.jpg?w=991&amp;ssl=1 991w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018899.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><p id=\"caption-attachment-3193\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3187\" style=\"width: 456px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018540.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3187\" data-attachment-id=\"3187\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018540\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018540.jpg?fit=928%2C742&amp;ssl=1\" data-orig-size=\"928,742\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (14)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018540.jpg?fit=700%2C560&amp;ssl=1\" class=\" wp-image-3187  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (14)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018540.jpg?resize=446%2C356&#038;ssl=1\" width=\"446\" height=\"356\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018540.jpg?w=928&amp;ssl=1 928w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018540.jpg?resize=300%2C239&amp;ssl=1 300w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/><\/a><p id=\"caption-attachment-3187\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3191\" style=\"width: 486px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018712.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3191\" data-attachment-id=\"3191\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018712\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018712.jpg?fit=991%2C743&amp;ssl=1\" data-orig-size=\"991,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (10)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018712.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-3191  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (10)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018712.jpg?resize=476%2C357&#038;ssl=1\" width=\"476\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018712.jpg?w=991&amp;ssl=1 991w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018712.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><p id=\"caption-attachment-3191\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3196\" style=\"width: 486px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019001.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3196\" data-attachment-id=\"3196\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1019001\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019001.jpg?fit=991%2C743&amp;ssl=1\" data-orig-size=\"991,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (5)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019001.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-3196  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (5)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019001.jpg?resize=476%2C357&#038;ssl=1\" width=\"476\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019001.jpg?w=991&amp;ssl=1 991w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019001.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><p id=\"caption-attachment-3196\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3190\" style=\"width: 486px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018660.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3190\" data-attachment-id=\"3190\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018660\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018660.jpg?fit=991%2C743&amp;ssl=1\" data-orig-size=\"991,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (11)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018660.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-3190  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (11)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018660.jpg?resize=476%2C357&#038;ssl=1\" width=\"476\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018660.jpg?w=991&amp;ssl=1 991w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018660.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><p id=\"caption-attachment-3190\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3189\" style=\"width: 455px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018567.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3189\" data-attachment-id=\"3189\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018567\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018567.jpg?fit=927%2C743&amp;ssl=1\" data-orig-size=\"927,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (12)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018567.jpg?fit=700%2C561&amp;ssl=1\" class=\" wp-image-3189  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (12)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018567.jpg?resize=445%2C357&#038;ssl=1\" width=\"445\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018567.jpg?w=927&amp;ssl=1 927w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018567.jpg?resize=300%2C240&amp;ssl=1 300w\" sizes=\"auto, (max-width: 445px) 100vw, 445px\" \/><\/a><p id=\"caption-attachment-3189\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3194\" style=\"width: 486px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018972.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3194\" data-attachment-id=\"3194\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018972\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018972.jpg?fit=991%2C743&amp;ssl=1\" data-orig-size=\"991,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (7)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018972.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-3194  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (7)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018972.jpg?resize=476%2C357&#038;ssl=1\" width=\"476\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018972.jpg?w=991&amp;ssl=1 991w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018972.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><p id=\"caption-attachment-3194\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3188\" style=\"width: 501px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018547.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3188\" data-attachment-id=\"3188\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018547\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018547.jpg?fit=1029%2C743&amp;ssl=1\" data-orig-size=\"1029,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (13)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018547.jpg?fit=700%2C505&amp;ssl=1\" class=\" wp-image-3188  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (13)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018547.jpg?resize=491%2C354&#038;ssl=1\" width=\"491\" height=\"354\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018547.jpg?resize=1024%2C739&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018547.jpg?resize=300%2C216&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018547.jpg?w=1029&amp;ssl=1 1029w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><\/a><p id=\"caption-attachment-3188\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3192\" style=\"width: 486px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018875.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3192\" data-attachment-id=\"3192\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018875\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018875.jpg?fit=991%2C743&amp;ssl=1\" data-orig-size=\"991,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (9)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018875.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-3192  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (9)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018875.jpg?resize=476%2C357&#038;ssl=1\" width=\"476\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018875.jpg?w=991&amp;ssl=1 991w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018875.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><p id=\"caption-attachment-3192\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3178\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018442.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3178\" data-attachment-id=\"3178\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018442\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018442.jpg?fit=926%2C743&amp;ssl=1\" data-orig-size=\"926,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (23)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018442.jpg?fit=700%2C562&amp;ssl=1\" class=\" wp-image-3178   \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (23)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018442.jpg?resize=490%2C393&#038;ssl=1\" width=\"490\" height=\"393\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018442.jpg?w=926&amp;ssl=1 926w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018442.jpg?resize=300%2C240&amp;ssl=1 300w\" sizes=\"auto, (max-width: 490px) 100vw, 490px\" \/><\/a><p id=\"caption-attachment-3178\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3195\" style=\"width: 486px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018984.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3195\" data-attachment-id=\"3195\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018984\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018984.jpg?fit=991%2C743&amp;ssl=1\" data-orig-size=\"991,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (6)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018984.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-3195  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (6)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018984.jpg?resize=476%2C357&#038;ssl=1\" width=\"476\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018984.jpg?w=991&amp;ssl=1 991w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018984.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><p id=\"caption-attachment-3195\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3186\" style=\"width: 501px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018515.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3186\" data-attachment-id=\"3186\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018515\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018515.jpg?fit=1029%2C743&amp;ssl=1\" data-orig-size=\"1029,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (15)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018515.jpg?fit=700%2C505&amp;ssl=1\" class=\" wp-image-3186  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (15)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018515.jpg?resize=491%2C354&#038;ssl=1\" width=\"491\" height=\"354\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018515.jpg?resize=1024%2C739&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018515.jpg?resize=300%2C216&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018515.jpg?w=1029&amp;ssl=1 1029w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><\/a><p id=\"caption-attachment-3186\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3184\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018501.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3184\" data-attachment-id=\"3184\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018501\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018501.jpg?fit=926%2C743&amp;ssl=1\" data-orig-size=\"926,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (17)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018501.jpg?fit=700%2C562&amp;ssl=1\" class=\" wp-image-3184  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (17)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018501.jpg?resize=500%2C401&#038;ssl=1\" width=\"500\" height=\"401\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018501.jpg?w=926&amp;ssl=1 926w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018501.jpg?resize=300%2C240&amp;ssl=1 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><p id=\"caption-attachment-3184\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3183\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018498.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3183\" data-attachment-id=\"3183\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018498\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018498.jpg?fit=927%2C743&amp;ssl=1\" data-orig-size=\"927,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (18)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018498.jpg?fit=700%2C561&amp;ssl=1\" class=\" wp-image-3183  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (18)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018498.jpg?resize=500%2C401&#038;ssl=1\" width=\"500\" height=\"401\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018498.jpg?w=927&amp;ssl=1 927w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018498.jpg?resize=300%2C240&amp;ssl=1 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><p id=\"caption-attachment-3183\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3182\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018489.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3182\" data-attachment-id=\"3182\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018489\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018489.jpg?fit=927%2C743&amp;ssl=1\" data-orig-size=\"927,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (19)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018489.jpg?fit=700%2C561&amp;ssl=1\" class=\" wp-image-3182  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (19)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018489.jpg?resize=500%2C401&#038;ssl=1\" width=\"500\" height=\"401\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018489.jpg?w=927&amp;ssl=1 927w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018489.jpg?resize=300%2C240&amp;ssl=1 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><p id=\"caption-attachment-3182\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3181\" style=\"width: 486px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018486.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3181\" data-attachment-id=\"3181\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018486\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018486.jpg?fit=991%2C743&amp;ssl=1\" data-orig-size=\"991,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (20)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018486.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-3181  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (20)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018486.jpg?resize=476%2C357&#038;ssl=1\" width=\"476\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018486.jpg?w=991&amp;ssl=1 991w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018486.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><p id=\"caption-attachment-3181\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3180\" style=\"width: 486px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018480.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3180\" data-attachment-id=\"3180\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018480\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018480.jpg?fit=991%2C743&amp;ssl=1\" data-orig-size=\"991,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (21)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018480.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-3180  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (21)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018480.jpg?resize=476%2C357&#038;ssl=1\" width=\"476\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018480.jpg?w=991&amp;ssl=1 991w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018480.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><p id=\"caption-attachment-3180\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3185\" style=\"width: 486px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018509.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3185\" data-attachment-id=\"3185\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018509\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018509.jpg?fit=991%2C743&amp;ssl=1\" data-orig-size=\"991,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (16)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018509.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-3185  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (16)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018509.jpg?resize=476%2C357&#038;ssl=1\" width=\"476\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018509.jpg?w=991&amp;ssl=1 991w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018509.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><p id=\"caption-attachment-3185\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3179\" style=\"width: 486px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018447.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3179\" data-attachment-id=\"3179\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1018447\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018447.jpg?fit=991%2C743&amp;ssl=1\" data-orig-size=\"991,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (22)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018447.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-3179  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (22)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018447.jpg?resize=476%2C357&#038;ssl=1\" width=\"476\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018447.jpg?w=991&amp;ssl=1 991w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1018447.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><p id=\"caption-attachment-3179\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p style=\"text-align: center\">\n<div id=\"attachment_3200\" style=\"width: 486px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019144.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3200\" data-attachment-id=\"3200\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\/p1019144\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019144.jpg?fit=991%2C743&amp;ssl=1\" data-orig-size=\"991,743\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (1)\" data-image-description=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;12 Horas BTT Abegondo Fotos por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019144.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-3200  \" alt=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno (1)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019144.jpg?resize=476%2C357&#038;ssl=1\" width=\"476\" height=\"357\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019144.jpg?w=991&amp;ssl=1 991w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019144.jpg?resize=300%2C224&amp;ssl=1 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><p id=\"caption-attachment-3200\" class=\"wp-caption-text\">12 Horas BTT Abegondo Fotos por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\">\n","protected":false},"excerpt":{"rendered":"<p>Aprovechando el par\u00f3n en el Open, este fin de semana participamos en las 12 Horas BTT Abegondo. Como se puede adivinar por su nombre se trata de una prueba cicloturista&hellip; <\/p>\n","protected":false},"author":32,"featured_media":3197,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[72,71,80,76],"tags":[],"class_list":["post-3176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-fotos","category-la-mafia","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>12 Horas BTT Abegondo Fotos por Pirucho Pequeno - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"Aprovechando el par\u00f3n en el Open, este fin de semana participamos en las 12 Horas BTT Abegondo. Como se puede adivinar por su nombre se trata de una prueba cicloturista&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"luzmaria.iglesiasmosquera?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-03T19:54:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019021.jpg?fit=926%2C743&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"926\" \/>\n\t<meta property=\"og:image:height\" content=\"743\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pirucho Pequeno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pirucho Pequeno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\"},\"author\":{\"name\":\"Pirucho Pequeno\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/2dc70d4ba4335aacd4f8dbf7805eee9e\"},\"headline\":\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno\",\"datePublished\":\"2014-08-03T19:54:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\"},\"wordCount\":728,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/P1019021.jpg?fit=926%2C743&ssl=1\",\"articleSection\":[\"Eventos\",\"Fotos\",\"LA MAFIA\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\",\"name\":\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/P1019021.jpg?fit=926%2C743&ssl=1\",\"datePublished\":\"2014-08-03T19:54:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/2dc70d4ba4335aacd4f8dbf7805eee9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/P1019021.jpg?fit=926%2C743&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/P1019021.jpg?fit=926%2C743&ssl=1\",\"width\":926,\"height\":743,\"caption\":\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"12 Horas BTT Abegondo Fotos por Pirucho Pequeno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/2dc70d4ba4335aacd4f8dbf7805eee9e\",\"name\":\"Pirucho Pequeno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g\",\"caption\":\"Pirucho Pequeno\"},\"description\":\"Se puede decir que es una especie de \u201cgroupie de ciclistas\u201d, nunca ha competido pero le encanta el mundo del ciclismo. Sus tareas principales son avituallar y fotografiar a todo aquel que me se lo pida con una sonrisa. Sus albumes de fotos en GOOGLE+ son visitados por cientos, miles, millones de personas y hasta marcianos y derivados. Ojo que aunque la ve\u00e1is en las carreras con una mirada angelical no recoge ni chaquetillas ni termicas en la salida, lo que le da fama de mala mujer.\",\"sameAs\":[\"https:\\\/\\\/picasaweb.google.com\\\/114831358335341071162\",\"luzmaria.iglesiasmosquera?fref=ts\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/pirucho-pequeno\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"12 Horas BTT Abegondo Fotos por Pirucho Pequeno - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno","og_locale":"es_ES","og_type":"article","og_title":"12 Horas BTT Abegondo Fotos por Pirucho Pequeno - El Blog de ValwindCycles","og_description":"Aprovechando el par\u00f3n en el Open, este fin de semana participamos en las 12 Horas BTT Abegondo. Como se puede adivinar por su nombre se trata de una prueba cicloturista&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"luzmaria.iglesiasmosquera?fref=ts","article_published_time":"2014-08-03T19:54:02+00:00","og_image":[{"width":926,"height":743,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019021.jpg?fit=926%2C743&ssl=1","type":"image\/jpeg"}],"author":"Pirucho Pequeno","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Pirucho Pequeno","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno"},"author":{"name":"Pirucho Pequeno","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/2dc70d4ba4335aacd4f8dbf7805eee9e"},"headline":"12 Horas BTT Abegondo Fotos por Pirucho Pequeno","datePublished":"2014-08-03T19:54:02+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno"},"wordCount":728,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019021.jpg?fit=926%2C743&ssl=1","articleSection":["Eventos","Fotos","LA MAFIA","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno","url":"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno","name":"12 Horas BTT Abegondo Fotos por Pirucho Pequeno - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019021.jpg?fit=926%2C743&ssl=1","datePublished":"2014-08-03T19:54:02+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/2dc70d4ba4335aacd4f8dbf7805eee9e"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019021.jpg?fit=926%2C743&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019021.jpg?fit=926%2C743&ssl=1","width":926,"height":743,"caption":"12 Horas BTT Abegondo Fotos por Pirucho Pequeno"},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/12-horas-btt-abegondo-fotos-por-pirucho-pequeno#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"12 Horas BTT Abegondo Fotos por Pirucho Pequeno"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/2dc70d4ba4335aacd4f8dbf7805eee9e","name":"Pirucho Pequeno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g","caption":"Pirucho Pequeno"},"description":"Se puede decir que es una especie de \u201cgroupie de ciclistas\u201d, nunca ha competido pero le encanta el mundo del ciclismo. Sus tareas principales son avituallar y fotografiar a todo aquel que me se lo pida con una sonrisa. Sus albumes de fotos en GOOGLE+ son visitados por cientos, miles, millones de personas y hasta marcianos y derivados. Ojo que aunque la ve\u00e1is en las carreras con una mirada angelical no recoge ni chaquetillas ni termicas en la salida, lo que le da fama de mala mujer.","sameAs":["https:\/\/picasaweb.google.com\/114831358335341071162","luzmaria.iglesiasmosquera?fref=ts"],"url":"https:\/\/valwindcycles.es\/blog\/author\/pirucho-pequeno"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-Pe","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/08\/P1019021.jpg?fit=926%2C743&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/3176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=3176"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/3176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/3197"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=3176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=3176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=3176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}