{"id":3504,"date":"2014-09-22T22:50:29","date_gmt":"2014-09-22T21:50:29","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=3504"},"modified":"2014-09-22T22:50:29","modified_gmt":"2014-09-22T21:50:29","slug":"lo-que-se-echa-de-menos-por-mo-niki","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki","title":{"rendered":"Lo que se echa de menos&#8230; por Mo \u00abNiki\u00bb"},"content":{"rendered":"<p>Es evidente la morri\u00f1a que tengo. .. se nota y s\u00f3lo me falta gritarlo a s\u00f3lo tres meses aqu\u00ed los d\u00edas se hacen largos, m\u00e1s cuando echas de menos. Es dif\u00edcil sacarte de tu d\u00eda a d\u00eda a la gente, a lo que hac\u00edas..siempre he sido una persona afectiva de m\u00e1s creo, me doy a la gente desde el minuto uno y creo que es lo que me implica en todos los aspectos, por aqu\u00ed lo expreso porque puedo llegar a todos quienes conozco y que aunque no se los pueda decir a uno, ellos la saben y sino se los recuerdo.<br \/>\nNo hay d\u00eda en que haga algo y desee que est\u00e9n aqu\u00ed o estar all\u00ed con ellos.<br \/>\nHe y tengo que aprender tambi\u00e9n a lanzarme sola, soy una \u00f1o\u00f1as y que me juzguen jejeje<br \/>\nNo obstante siempre he sido afortunada, un ejemplo de ello es quienes me han acogido y que el tiempo har\u00e1 que sean tan fuertes los lazos como los que hasta ahora tengo y llevo.<br \/>\nGracias a quienes han estado y gracias a quienes est\u00e1n, a los que de vez en mes aguantan esta chapa, a los que est\u00e1n por venir y estar aqu\u00ed.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3505\" style=\"width: 501px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/1909315_10204187073853546_1855824185200551534_o.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3505\" data-attachment-id=\"3505\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki\/1909315_10204187073853546_1855824185200551534_o\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/1909315_10204187073853546_1855824185200551534_o.jpg?fit=1024%2C576&amp;ssl=1\" data-orig-size=\"1024,576\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb  (8)\" data-image-description=\"&lt;p&gt;Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb &lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/1909315_10204187073853546_1855824185200551534_o.jpg?fit=700%2C394&amp;ssl=1\" class=\" wp-image-3505  \" alt=\"Lo que se echa de menos... por Mo &quot;Niki&quot; \" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/1909315_10204187073853546_1855824185200551534_o.jpg?resize=491%2C277&#038;ssl=1\" width=\"491\" height=\"277\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/1909315_10204187073853546_1855824185200551534_o.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/1909315_10204187073853546_1855824185200551534_o.jpg?resize=300%2C168&amp;ssl=1 300w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><\/a><p id=\"caption-attachment-3505\" class=\"wp-caption-text\">Lo que se echa de menos&#8230; por Mo \u00abNiki\u00bb<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3512\" style=\"width: 442px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10665843_10204187063013275_1087220371110485311_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3512\" data-attachment-id=\"3512\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki\/10665843_10204187063013275_1087220371110485311_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10665843_10204187063013275_1087220371110485311_n.jpg?fit=720%2C960&amp;ssl=1\" data-orig-size=\"720,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb  (1)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10665843_10204187063013275_1087220371110485311_n.jpg?fit=700%2C933&amp;ssl=1\" class=\" wp-image-3512 \" alt=\"Lo que se echa de menos... por Mo &quot;Niki&quot; (1)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10665843_10204187063013275_1087220371110485311_n.jpg?resize=432%2C576&#038;ssl=1\" width=\"432\" height=\"576\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10665843_10204187063013275_1087220371110485311_n.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10665843_10204187063013275_1087220371110485311_n.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><\/a><p id=\"caption-attachment-3512\" class=\"wp-caption-text\">Lo que se echa de menos&#8230; por Mo \u00abNiki\u00bb<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3511\" style=\"width: 389px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10645082_10204174554380567_834075870727424933_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3511\" data-attachment-id=\"3511\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki\/10645082_10204174554380567_834075870727424933_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10645082_10204174554380567_834075870727424933_n.jpg?fit=379%2C496&amp;ssl=1\" data-orig-size=\"379,496\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb  (2)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10645082_10204174554380567_834075870727424933_n.jpg?fit=379%2C496&amp;ssl=1\" class=\"size-full wp-image-3511\" alt=\"Lo que se echa de menos... por Mo &quot;Niki&quot; (2)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10645082_10204174554380567_834075870727424933_n.jpg?resize=379%2C496&#038;ssl=1\" width=\"379\" height=\"496\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10645082_10204174554380567_834075870727424933_n.jpg?w=379&amp;ssl=1 379w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10645082_10204174554380567_834075870727424933_n.jpg?resize=229%2C300&amp;ssl=1 229w\" sizes=\"auto, (max-width: 379px) 100vw, 379px\" \/><\/a><p id=\"caption-attachment-3511\" class=\"wp-caption-text\">Lo que se echa de menos&#8230; por Mo \u00abNiki\u00bb<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3510\" style=\"width: 501px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10636816_10204187078893672_7594291559033567512_o.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3510\" data-attachment-id=\"3510\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki\/10636816_10204187078893672_7594291559033567512_o\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10636816_10204187078893672_7594291559033567512_o.jpg?fit=1024%2C576&amp;ssl=1\" data-orig-size=\"1024,576\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb  (3)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10636816_10204187078893672_7594291559033567512_o.jpg?fit=700%2C394&amp;ssl=1\" class=\" wp-image-3510  \" alt=\"Lo que se echa de menos... por Mo &quot;Niki&quot; (3)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10636816_10204187078893672_7594291559033567512_o.jpg?resize=491%2C277&#038;ssl=1\" width=\"491\" height=\"277\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10636816_10204187078893672_7594291559033567512_o.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10636816_10204187078893672_7594291559033567512_o.jpg?resize=300%2C168&amp;ssl=1 300w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><\/a><p id=\"caption-attachment-3510\" class=\"wp-caption-text\">Lo que se echa de menos&#8230; por Mo \u00abNiki\u00bb<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3509\" style=\"width: 476px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10632883_10204187069653441_1975124338328317621_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3509\" data-attachment-id=\"3509\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki\/10632883_10204187069653441_1975124338328317621_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10632883_10204187069653441_1975124338328317621_n.jpg?fit=863%2C459&amp;ssl=1\" data-orig-size=\"863,459\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb  (4)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10632883_10204187069653441_1975124338328317621_n.jpg?fit=700%2C372&amp;ssl=1\" class=\" wp-image-3509  \" alt=\"Lo que se echa de menos... por Mo &quot;Niki&quot; (4)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10632883_10204187069653441_1975124338328317621_n.jpg?resize=466%2C248&#038;ssl=1\" width=\"466\" height=\"248\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10632883_10204187069653441_1975124338328317621_n.jpg?w=863&amp;ssl=1 863w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10632883_10204187069653441_1975124338328317621_n.jpg?resize=300%2C159&amp;ssl=1 300w\" sizes=\"auto, (max-width: 466px) 100vw, 466px\" \/><\/a><p id=\"caption-attachment-3509\" class=\"wp-caption-text\">Lo que se echa de menos&#8230; por Mo \u00abNiki\u00bb<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3508\" style=\"width: 492px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10361985_10204180783176283_1805802169658653887_n1.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3508\" data-attachment-id=\"3508\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki\/10361985_10204180783176283_1805802169658653887_n-2\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10361985_10204180783176283_1805802169658653887_n1.jpg?fit=803%2C489&amp;ssl=1\" data-orig-size=\"803,489\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb  (5)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10361985_10204180783176283_1805802169658653887_n1.jpg?fit=700%2C426&amp;ssl=1\" class=\" wp-image-3508 \" alt=\"Lo que se echa de menos... por Mo &quot;Niki&quot; (5)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10361985_10204180783176283_1805802169658653887_n1.jpg?resize=482%2C293&#038;ssl=1\" width=\"482\" height=\"293\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10361985_10204180783176283_1805802169658653887_n1.jpg?w=803&amp;ssl=1 803w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10361985_10204180783176283_1805802169658653887_n1.jpg?resize=300%2C182&amp;ssl=1 300w\" sizes=\"auto, (max-width: 482px) 100vw, 482px\" \/><\/a><p id=\"caption-attachment-3508\" class=\"wp-caption-text\">Lo que se echa de menos&#8230; por Mo \u00abNiki\u00bb<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3507\" style=\"width: 471px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10348177_10204187081893747_5585059249646698347_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3507\" data-attachment-id=\"3507\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki\/10348177_10204187081893747_5585059249646698347_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10348177_10204187081893747_5585059249646698347_n.jpg?fit=960%2C540&amp;ssl=1\" data-orig-size=\"960,540\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb  (6)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10348177_10204187081893747_5585059249646698347_n.jpg?fit=700%2C394&amp;ssl=1\" class=\" wp-image-3507  \" alt=\"Lo que se echa de menos... por Mo &quot;Niki&quot; (6)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10348177_10204187081893747_5585059249646698347_n.jpg?resize=461%2C259&#038;ssl=1\" width=\"461\" height=\"259\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10348177_10204187081893747_5585059249646698347_n.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10348177_10204187081893747_5585059249646698347_n.jpg?resize=300%2C168&amp;ssl=1 300w\" sizes=\"auto, (max-width: 461px) 100vw, 461px\" \/><\/a><p id=\"caption-attachment-3507\" class=\"wp-caption-text\">Lo que se echa de menos&#8230; por Mo \u00abNiki\u00bb<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3506\" style=\"width: 501px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10293650_10204187067213380_2362028517259153398_o.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3506\" data-attachment-id=\"3506\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki\/10293650_10204187067213380_2362028517259153398_o\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10293650_10204187067213380_2362028517259153398_o.jpg?fit=1024%2C576&amp;ssl=1\" data-orig-size=\"1024,576\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb  (7)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Lo que se echa de menos&amp;#8230; por Mo \u00abNiki\u00bb &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10293650_10204187067213380_2362028517259153398_o.jpg?fit=700%2C394&amp;ssl=1\" class=\" wp-image-3506  \" alt=\"Lo que se echa de menos... por Mo &quot;Niki&quot; (7)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10293650_10204187067213380_2362028517259153398_o.jpg?resize=491%2C277&#038;ssl=1\" width=\"491\" height=\"277\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10293650_10204187067213380_2362028517259153398_o.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10293650_10204187067213380_2362028517259153398_o.jpg?resize=300%2C168&amp;ssl=1 300w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><\/a><p id=\"caption-attachment-3506\" class=\"wp-caption-text\">Lo que se echa de menos&#8230; por Mo \u00abNiki\u00bb<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es evidente la morri\u00f1a que tengo. .. se nota y s\u00f3lo me falta gritarlo a s\u00f3lo tres meses aqu\u00ed los d\u00edas se hacen largos, m\u00e1s cuando echas de menos. Es&hellip; <\/p>\n","protected":false},"author":64,"featured_media":3509,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo que se echa de menos... por Mo &quot;Niki&quot;  - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo que se echa de menos... por Mo &quot;Niki&quot;  - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"Es evidente la morri\u00f1a que tengo. .. se nota y s\u00f3lo me falta gritarlo a s\u00f3lo tres meses aqu\u00ed los d\u00edas se hacen largos, m\u00e1s cuando echas de menos. Es&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/nikmonal?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-22T21:50:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10632883_10204187069653441_1975124338328317621_n.jpg?fit=863%2C459&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"863\" \/>\n\t<meta property=\"og:image:height\" content=\"459\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mo &quot;Niki&quot;\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mo &quot;Niki&quot;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/lo-que-se-echa-de-menos-por-mo-niki#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/lo-que-se-echa-de-menos-por-mo-niki\"},\"author\":{\"name\":\"Mo \\\"Niki\\\"\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/586b332f1d82693137962cb4b43d1b89\"},\"headline\":\"Lo que se echa de menos&#8230; por Mo \u00abNiki\u00bb\",\"datePublished\":\"2014-09-22T21:50:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/lo-que-se-echa-de-menos-por-mo-niki\"},\"wordCount\":363,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/lo-que-se-echa-de-menos-por-mo-niki#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/10632883_10204187069653441_1975124338328317621_n.jpg?fit=863%2C459&ssl=1\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/lo-que-se-echa-de-menos-por-mo-niki#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/lo-que-se-echa-de-menos-por-mo-niki\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/lo-que-se-echa-de-menos-por-mo-niki\",\"name\":\"Lo que se echa de menos... por Mo \\\"Niki\\\" - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/lo-que-se-echa-de-menos-por-mo-niki#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/lo-que-se-echa-de-menos-por-mo-niki#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/10632883_10204187069653441_1975124338328317621_n.jpg?fit=863%2C459&ssl=1\",\"datePublished\":\"2014-09-22T21:50:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/586b332f1d82693137962cb4b43d1b89\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/lo-que-se-echa-de-menos-por-mo-niki#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/lo-que-se-echa-de-menos-por-mo-niki\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/lo-que-se-echa-de-menos-por-mo-niki#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/10632883_10204187069653441_1975124338328317621_n.jpg?fit=863%2C459&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/10632883_10204187069653441_1975124338328317621_n.jpg?fit=863%2C459&ssl=1\",\"width\":863,\"height\":459,\"caption\":\"Lo que se echa de menos... por Mo \\\"Niki\\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/lo-que-se-echa-de-menos-por-mo-niki#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo que se echa de menos&#8230; por Mo \u00abNiki\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/586b332f1d82693137962cb4b43d1b89\",\"name\":\"Mo \\\"Niki\\\"\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2108705c711676ad05f515fa3d182402a2d8b89282f198c11625c2c5d386763f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2108705c711676ad05f515fa3d182402a2d8b89282f198c11625c2c5d386763f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2108705c711676ad05f515fa3d182402a2d8b89282f198c11625c2c5d386763f?s=96&d=mm&r=g\",\"caption\":\"Mo \\\"Niki\\\"\"},\"description\":\"Hacerle cosquillas a la vida!!! en esta frase se puede resumir la esencia de su esp\u00edritu y su pasi\u00f3n por los deportes de aventura y por todo lo que se propone en la vida\u2026 y lo consigue !!! quien la conoce lo sabe.. y quien no tambi\u00e9n, solo es necesario verla encima de una bici, corriendo o con el neopreno puesto y todo ello con esa incre\u00edble, m\u00e1gica e incansable sonrisa que ilumina cada kilometro de los miles que recorre al a\u00f1o esta guap\u00edsima aventurera nacida en Colombia.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nikmonal?fref=ts\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/monica\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo que se echa de menos... por Mo \"Niki\"  - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki","og_locale":"es_ES","og_type":"article","og_title":"Lo que se echa de menos... por Mo \"Niki\"  - El Blog de ValwindCycles","og_description":"Es evidente la morri\u00f1a que tengo. .. se nota y s\u00f3lo me falta gritarlo a s\u00f3lo tres meses aqu\u00ed los d\u00edas se hacen largos, m\u00e1s cuando echas de menos. Es&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"https:\/\/www.facebook.com\/nikmonal?fref=ts","article_published_time":"2014-09-22T21:50:29+00:00","og_image":[{"width":863,"height":459,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10632883_10204187069653441_1975124338328317621_n.jpg?fit=863%2C459&ssl=1","type":"image\/jpeg"}],"author":"Mo \"Niki\"","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Mo \"Niki\"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki"},"author":{"name":"Mo \"Niki\"","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/586b332f1d82693137962cb4b43d1b89"},"headline":"Lo que se echa de menos&#8230; por Mo \u00abNiki\u00bb","datePublished":"2014-09-22T21:50:29+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki"},"wordCount":363,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10632883_10204187069653441_1975124338328317621_n.jpg?fit=863%2C459&ssl=1","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki","url":"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki","name":"Lo que se echa de menos... por Mo \"Niki\" - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10632883_10204187069653441_1975124338328317621_n.jpg?fit=863%2C459&ssl=1","datePublished":"2014-09-22T21:50:29+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/586b332f1d82693137962cb4b43d1b89"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10632883_10204187069653441_1975124338328317621_n.jpg?fit=863%2C459&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10632883_10204187069653441_1975124338328317621_n.jpg?fit=863%2C459&ssl=1","width":863,"height":459,"caption":"Lo que se echa de menos... por Mo \"Niki\""},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/lo-que-se-echa-de-menos-por-mo-niki#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Lo que se echa de menos&#8230; por Mo \u00abNiki\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/586b332f1d82693137962cb4b43d1b89","name":"Mo \"Niki\"","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2108705c711676ad05f515fa3d182402a2d8b89282f198c11625c2c5d386763f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2108705c711676ad05f515fa3d182402a2d8b89282f198c11625c2c5d386763f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2108705c711676ad05f515fa3d182402a2d8b89282f198c11625c2c5d386763f?s=96&d=mm&r=g","caption":"Mo \"Niki\""},"description":"Hacerle cosquillas a la vida!!! en esta frase se puede resumir la esencia de su esp\u00edritu y su pasi\u00f3n por los deportes de aventura y por todo lo que se propone en la vida\u2026 y lo consigue !!! quien la conoce lo sabe.. y quien no tambi\u00e9n, solo es necesario verla encima de una bici, corriendo o con el neopreno puesto y todo ello con esa incre\u00edble, m\u00e1gica e incansable sonrisa que ilumina cada kilometro de los miles que recorre al a\u00f1o esta guap\u00edsima aventurera nacida en Colombia.","sameAs":["https:\/\/www.facebook.com\/nikmonal?fref=ts"],"url":"https:\/\/valwindcycles.es\/blog\/author\/monica"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-Uw","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/09\/10632883_10204187069653441_1975124338328317621_n.jpg?fit=863%2C459&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/3504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=3504"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/3504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/3509"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=3504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=3504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=3504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}