{"id":4042,"date":"2014-11-11T05:05:57","date_gmt":"2014-11-11T04:05:57","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=4042"},"modified":"2014-11-11T05:05:57","modified_gmt":"2014-11-11T04:05:57","slug":"despellejando-una-cronica-ii-trail-da-groba-por-almu","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu","title":{"rendered":"Despellejando una cr\u00f3nica&#8230; II Trail da Groba &#8211;  por Almu"},"content":{"rendered":"<p align=\"JUSTIFY\">Han pasado ya m\u00e1s de 48 horas desde la celebraci\u00f3n del <strong>II Trail da Groba<\/strong> organizado por el Concello de Baiona, y durante todo ese tiempo le he dado tantas vueltas a si escribir o no lo sucedido, que al final, decidida al menos por pasar p\u00e1gina de una maldita vez, me he dispuesto a ello.<\/p>\n<p align=\"JUSTIFY\">Desde el mismo momento que me inscribo a cualquier prueba deportiva, acepto el reglamento, me hago un planing de entreno, me intereso en hacerme con el material que me va a hacer falta, y me involucro en la consecuci\u00f3n de mi meta y objetivo, con la finalidad de disfrutar y sufrir en su justa medida, para ver compensado ese esfuerzo.<\/p>\n<p align=\"JUSTIFY\">Lleg\u00f3 el d\u00eda y ten\u00eda casi la absoluta certeza de que acabar\u00eda, en un tiempo m\u00e1s o menos digno. Casi tres meses y acumulados casi 1200 kms de carrera a pie y horas de entreno. Sab\u00eda cu\u00e1les eran algunos de mis puntos fuertes, y tambi\u00e9n mis debilidades, entre los cuales no est\u00e1 desfallecer por la lluvia o por circunstancias climatol\u00f3gicas adversas. Quienes me conocen saben que entreno con cualquier tipo de condici\u00f3n atmosf\u00e9rica, siempre bajo mi responsabilidad y haciendo uso de una cualidad muy importante en el deporte que es la prudencia.<\/p>\n<p align=\"JUSTIFY\">Este a\u00f1o confieso que me tambi\u00e9n me inscrib\u00ed pensando que no podr\u00eda ser peor que la edici\u00f3n pasada, en la que a\u00fan con alerta naranja por lluvias, la carrera se llev\u00f3 a cabo, y que, por azares del destino y por la suerte del principiante (tanto para el organizador como para los participantes), no tuvo mayores consecuencias que las de peque\u00f1as odiseas pasadas por agua, y solventadas in extremis por Protecci\u00f3n Civil.<\/p>\n<p align=\"JUSTIFY\">Pues bien, si fue peor, inimaginablemente peor. S\u00f3lo voy a relatar mi experiencia personal, y con eso dejar zanjado esta dura experiencia deportiva, de la que s\u00f3lo hay un culpable, que es el organizador de una prueba, que por segundo a\u00f1o consecutivo se salta su propio reglamento, haciendo responsables a los mismos participantes de su propia seguridad. Esto no es una an\u00e9cdota m\u00e1s, ni una vivencia que contar a mis nietos, es que yo el s\u00e1bado tem\u00ed por mi seguridad y por mi vida. Y a la organizaci\u00f3n a la que hab\u00eda confiado la log\u00edstica, la seguridad y el desarrollo de una prueba que iba a ser la consecuci\u00f3n de mi reto, le ha importado b\u00e1sicamente lo mismo que las bo\u00f1igas de las bestias que habitan en la sierra de la Groba.<\/p>\n<p align=\"JUSTIFY\">Resumiendo:<\/p>\n<p align=\"JUSTIFY\">1,-Control exhaustivo del material: dorsal? (preguntan) el siete (respondo)&#8230;.suerte\u00a1 siguiente\u00a1<\/p>\n<p align=\"JUSTIFY\">(\u201cempezamos bien\u201d, pienso&#8230;.y me voy pal mont\u00f3n)<\/p>\n<p align=\"JUSTIFY\">2,-Charla o explicaciones previas. Vale que no asist\u00ed a la reuni\u00f3n t\u00e9cnica, pero en todos los trails se explica por lo menos de qu\u00e9 color son las cintas antes de dar pistoletazo&#8230;.nada, salida\u00a1\u00a1<\/p>\n<p align=\"JUSTIFY\">3,-Hasta el segundo avituallamiento todo transcurr\u00ed\u00f3 m\u00e1s o menos normal, poca lluvia, pero a medida que empec\u00e9 a ascender, todo fue empeorando. Una vez pas\u00e9 el avituallamiento de O Cortelli\u00f1o la lluvia era tremenda. Al principio no iba sola, pero a medida que pasaban los minutos me fui quedando, ya fuere porque la lluvia me hac\u00eda cerrar los ojos, el viento me empujaba de lado, y el fr\u00edo me iba calando hasta las orejas.<\/p>\n<p align=\"JUSTIFY\">4,-Los \u00faltimos kms, metros, minutos u horas, ya hab\u00eda perdido la noci\u00f3n del tiempo, antes de llegar a Poza negra, fueron realmente dantescos. No era capaz de abrir la mochila, ni notaba los dedos de las manos, y me miraba a los pies por si me los hab\u00eda amputado sin darme cuenta porque no los sent\u00eda, y tampoco me los ve\u00eda por la niebla. La niebla que no dejaba ver ni las cintas que marcaban el recorrido. Estaba desorientad\u00edsima. Me gir\u00e9 y no ve\u00eda nada, y hacia arriba tampoco se ve\u00eda mucho m\u00e1s. Logr\u00e9 mantener la calma por la mala sangre que me hice en ese momento de pensar qui\u00e9n era la mente iluminada que piensa que hacer un trail en el mes de noviembre con esta climatolog\u00eda es lo mejor para promover el turismo, la participaci\u00f3n y el disfrute deportivo de los atletas que religiosamente cumplen y aceptan el reglamento, y confian su meta y su dinero en pruebas como esta. Reglamento que ellos mismos redactan dejando constancia de que la prueba puede verse alterada, modificada o suspendida por circustancias adversas de este tipo.<\/p>\n<p align=\"JUSTIFY\">5,-Lleg\u00fae al avituallamiento y s\u00f3lo vi las luces del coche de mi padre, era lo \u00fanico que quer\u00eda ver. Ahi estaban porque mi intenci\u00f3n era la de cambiarme de ropa (cosa a la que la organizaci\u00f3n no puso facilidades, pese a solicitarlo por correo anteriormente, trat\u00e1ndose de una carrera tan larga, es habitual realizar estos cambios de ropa).<\/p>\n<p align=\"JUSTIFY\">Malamente llegu\u00e9 hasta \u00e9l mientras mi madre me sujetaba. Temblaba como si fuera el final del mundo, mientras vemos como una cabecita sale de la caseta del avituallamiento y me pregunta: \u00bfte retiras?&#8230;.. Como no era capaz de articular ninguna palabra, simplemente lo maldec\u00ed interiormente dese\u00e1ndole una feliz estancia en el infierno el resto de sus d\u00edas, mientras me call\u00e9 las ganas de decirle, no te preocupes, ya me voy yo a morir a mi casa.<\/p>\n<p align=\"JUSTIFY\">Hasta ah\u00ed el final de esta historia. Juro dos cosas por lo que m\u00e1s quiero en este mundo:<\/p>\n<p align=\"JUSTIFY\">-Que no vuelvo a participar en esa prueba, a menos que los responsables admitan la desastrosa calamidad de prueba que han organizado, y su intenci\u00f3n de no volver a poner en riesgo a ni un s\u00f3lo participante m\u00e1s, que aunque s\u00f3lo fuese uno, su vida vale lo mismo que la del resto de participantes.<\/p>\n<p align=\"JUSTIFY\">-Que mis padres no me vuelven a ver en esas circunstancias el resto de lo que me queda de existencia.<\/p>\n<p align=\"JUSTIFY\">Me surgen multitud de preguntas, sobre reglamentos deportivos incumplidos (en esta y m\u00e1s pruebas), sobre la finalidad del deporte amateur, sobre la capacidad de algunas entidades en organizar eventos. Hasta me surge la duda de si el mundo se dirige hacia un reto com\u00fan: acaparar emoticonos de aplausitos en los grupos de guasap, o el de aburrir a la infancia futura con las historias de viejos carcamales&#8230;.<\/p>\n<p align=\"JUSTIFY\">Yo me bajo del mundo, va muy deprisa y yo soy di\u00e9sel&#8230;.Mientras tanto seguir\u00e9 entrenando como la que m\u00e1s, disfrutando de mi tiempo libre como a mi me de la gana, sin poner en peligro a nadie, disfrutando de la buena compa\u00f1\u00eda, y haciendo realidad mi retos en la medida de lo posible, porque a partir de ahora, me cuidar\u00e9 muy mucho antes de presionar la tecla de inscribir&#8230;..<\/p>\n<p align=\"JUSTIFY\">Llegado a este punto s\u00f3lo puedo dar las gracias por haber le\u00eddo todo este repertorio.<\/p>\n<p align=\"JUSTIFY\"><strong>A Cuidarse y a disfrutar\u00a1\u00a1<\/strong><\/p>\n<p>\u00a0Foto de <a href=\"https:\/\/www.facebook.com\/manuel.parada.56?fref=ts\" target=\"_blank\">Manuel Parada\u00a0<\/a><\/p>\n<div id=\"attachment_4046\" style=\"width: 501px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4046\" data-attachment-id=\"4046\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu\/10525393_10204019464039655_4030392780358247325_o\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?fit=2048%2C1366&amp;ssl=1\" data-orig-size=\"2048,1366\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\" Despellejando una cr\u00f3nica&amp;#8230; II Trail da Groba &amp;#8211;  por Almu\" data-image-description=\"&lt;p&gt; Despellejando una cr\u00f3nica&amp;#8230; II Trail da Groba &amp;#8211;  por Almu&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt; Despellejando una cr\u00f3nica&amp;#8230; II Trail da Groba &amp;#8211;  por Almu&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?fit=700%2C467&amp;ssl=1\" class=\" wp-image-4046  \" alt=\" Despellejando una cr\u00f3nica... II Trail da Groba -  por Almu\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?resize=491%2C328&#038;ssl=1\" width=\"491\" height=\"328\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?w=1400&amp;ssl=1 1400w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><\/a><p id=\"caption-attachment-4046\" class=\"wp-caption-text\">Despellejando una cr\u00f3nica&#8230; II Trail da Groba &#8211; por Almu<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Han pasado ya m\u00e1s de 48 horas desde la celebraci\u00f3n del II Trail da Groba organizado por el Concello de Baiona, y durante todo ese tiempo le he dado tantas&hellip; <\/p>\n","protected":false},"author":65,"featured_media":4046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[72,80,76],"tags":[],"class_list":["post-4042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-la-mafia","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Despellejando una cr\u00f3nica... II Trail da Groba - por Almu - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Despellejando una cr\u00f3nica... II Trail da Groba - por Almu - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"Han pasado ya m\u00e1s de 48 horas desde la celebraci\u00f3n del II Trail da Groba organizado por el Concello de Baiona, y durante todo ese tiempo le he dado tantas&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-11T04:05:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?fit=2048%2C1366&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Almu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Almu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/despellejando-una-cronica-ii-trail-da-groba-por-almu#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/despellejando-una-cronica-ii-trail-da-groba-por-almu\"},\"author\":{\"name\":\"Almu\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/081173dcdb570286f86e577c70e9822d\"},\"headline\":\"Despellejando una cr\u00f3nica&#8230; II Trail da Groba &#8211; por Almu\",\"datePublished\":\"2014-11-11T04:05:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/despellejando-una-cronica-ii-trail-da-groba-por-almu\"},\"wordCount\":1211,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/despellejando-una-cronica-ii-trail-da-groba-por-almu#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/10525393_10204019464039655_4030392780358247325_o.jpg?fit=2048%2C1366&ssl=1\",\"articleSection\":[\"Eventos\",\"LA MAFIA\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/despellejando-una-cronica-ii-trail-da-groba-por-almu#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/despellejando-una-cronica-ii-trail-da-groba-por-almu\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/despellejando-una-cronica-ii-trail-da-groba-por-almu\",\"name\":\"Despellejando una cr\u00f3nica... II Trail da Groba - por Almu - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/despellejando-una-cronica-ii-trail-da-groba-por-almu#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/despellejando-una-cronica-ii-trail-da-groba-por-almu#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/10525393_10204019464039655_4030392780358247325_o.jpg?fit=2048%2C1366&ssl=1\",\"datePublished\":\"2014-11-11T04:05:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/081173dcdb570286f86e577c70e9822d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/despellejando-una-cronica-ii-trail-da-groba-por-almu#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/despellejando-una-cronica-ii-trail-da-groba-por-almu\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/despellejando-una-cronica-ii-trail-da-groba-por-almu#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/10525393_10204019464039655_4030392780358247325_o.jpg?fit=2048%2C1366&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/10525393_10204019464039655_4030392780358247325_o.jpg?fit=2048%2C1366&ssl=1\",\"width\":2048,\"height\":1366,\"caption\":\"Despellejando una cr\u00f3nica... II Trail da Groba - por Almu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/despellejando-una-cronica-ii-trail-da-groba-por-almu#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Despellejando una cr\u00f3nica&#8230; II Trail da Groba &#8211; por Almu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/081173dcdb570286f86e577c70e9822d\",\"name\":\"Almu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g\",\"caption\":\"Almu\"},\"description\":\"Como dec\u00eda hace unos d\u00edas en una de sus entradas en el blog.. el trail running es correr en la monta\u00f1a, la monta\u00f1a es libertad, naturaleza, aire puro, desconexi\u00f3n, es sentirse en afinidad y comuni\u00f3n con ese entorno natural, es avanzar sin importar el tiempo, la distancia o el ritmo, es buscar la soledad y el silencio\u2026. Es llegar a meta habiendo recorrido un camino en el que te has hecho fuerte, en el que has controlado todas las dificultades que se han presentado a lo largo de ese viaje\u2026.. Parece una filosof\u00eda de la vida no ? SweetSmile \u2026 la chica que corre\u2026 nada.. pedalea \u2026 escribe y vive la \u201cESENCIA\u201d Valwind como una autentica MafiosaValwind, la m\u00e1gica sonrisa, la runner-biker-nadadora-reportera dicharachera, energ\u00eda contagiosa en su m\u00e1ximo esplendor. El otro d\u00eda se desped\u00eda en una de sus entradas en el blog con esta sabia frase del Baron Pierre de Coubertin; \u201cEl deporte busca dominar el miedo, triunfar sobre la fatiga, vencer a la dificultad\u201d. Ella lo hace y adem\u00e1s con una m\u00e1gica sonrisa\u2026 Almu SweetSmile\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/almu\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Despellejando una cr\u00f3nica... II Trail da Groba - por Almu - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu","og_locale":"es_ES","og_type":"article","og_title":"Despellejando una cr\u00f3nica... II Trail da Groba - por Almu - El Blog de ValwindCycles","og_description":"Han pasado ya m\u00e1s de 48 horas desde la celebraci\u00f3n del II Trail da Groba organizado por el Concello de Baiona, y durante todo ese tiempo le he dado tantas&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_published_time":"2014-11-11T04:05:57+00:00","og_image":[{"width":2048,"height":1366,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?fit=2048%2C1366&ssl=1","type":"image\/jpeg"}],"author":"Almu","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Almu","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu"},"author":{"name":"Almu","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/081173dcdb570286f86e577c70e9822d"},"headline":"Despellejando una cr\u00f3nica&#8230; II Trail da Groba &#8211; por Almu","datePublished":"2014-11-11T04:05:57+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu"},"wordCount":1211,"commentCount":1,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?fit=2048%2C1366&ssl=1","articleSection":["Eventos","LA MAFIA","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu","url":"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu","name":"Despellejando una cr\u00f3nica... II Trail da Groba - por Almu - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?fit=2048%2C1366&ssl=1","datePublished":"2014-11-11T04:05:57+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/081173dcdb570286f86e577c70e9822d"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?fit=2048%2C1366&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?fit=2048%2C1366&ssl=1","width":2048,"height":1366,"caption":"Despellejando una cr\u00f3nica... II Trail da Groba - por Almu"},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/despellejando-una-cronica-ii-trail-da-groba-por-almu#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Despellejando una cr\u00f3nica&#8230; II Trail da Groba &#8211; por Almu"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/081173dcdb570286f86e577c70e9822d","name":"Almu","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g","caption":"Almu"},"description":"Como dec\u00eda hace unos d\u00edas en una de sus entradas en el blog.. el trail running es correr en la monta\u00f1a, la monta\u00f1a es libertad, naturaleza, aire puro, desconexi\u00f3n, es sentirse en afinidad y comuni\u00f3n con ese entorno natural, es avanzar sin importar el tiempo, la distancia o el ritmo, es buscar la soledad y el silencio\u2026. Es llegar a meta habiendo recorrido un camino en el que te has hecho fuerte, en el que has controlado todas las dificultades que se han presentado a lo largo de ese viaje\u2026.. Parece una filosof\u00eda de la vida no ? SweetSmile \u2026 la chica que corre\u2026 nada.. pedalea \u2026 escribe y vive la \u201cESENCIA\u201d Valwind como una autentica MafiosaValwind, la m\u00e1gica sonrisa, la runner-biker-nadadora-reportera dicharachera, energ\u00eda contagiosa en su m\u00e1ximo esplendor. El otro d\u00eda se desped\u00eda en una de sus entradas en el blog con esta sabia frase del Baron Pierre de Coubertin; \u201cEl deporte busca dominar el miedo, triunfar sobre la fatiga, vencer a la dificultad\u201d. Ella lo hace y adem\u00e1s con una m\u00e1gica sonrisa\u2026 Almu SweetSmile","url":"https:\/\/valwindcycles.es\/blog\/author\/almu"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-13c","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2014\/11\/10525393_10204019464039655_4030392780358247325_o.jpg?fit=2048%2C1366&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/4042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=4042"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/4042\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/4046"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=4042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=4042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=4042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}