{"id":4676,"date":"2015-02-10T10:52:58","date_gmt":"2015-02-10T09:52:58","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=4676"},"modified":"2015-02-10T10:52:58","modified_gmt":"2015-02-10T09:52:58","slug":"volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel","title":{"rendered":"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel"},"content":{"rendered":"<p>El Domingo se corr\u00eda el Trail de Moa\u00f1a, el primer Trail de Galicia Maxica Trail Adventures\u2026.<\/p>\n<p>Yo ten\u00eda claro clar\u00edsimo que no lo iba a correr, si analizo mi interior MIEDO \u00a0es la palabra que definir\u00eda lo que sent\u00eda, miedo a no estar a la altura, con lo que lo m\u00e1s f\u00e1cil era esconderme tras la excusa de quedarme cuidando de los ni\u00f1os, mientras mis compa\u00f1eras, mis chicas del Can Can corr\u00edan\u2026. Pero al parecer los astros estaban alineados para que no fuera a s\u00ed, para desbloquear mis miedos, para que por una vez me dejara llevar por los sentidos y no me sintiera peor que nadie por no estar a la altura, sino que sencillamente me dejara llevar y disfrutara de ese momento\u2026 El trail parec\u00eda la esencia de la vida\u2026.<\/p>\n<p>As\u00ed que el Domingo yo era la chica NO cuando empez\u00f3 la aventura, yo no estaba preparada para hacer un trail, ni de cuerpo ni de mente&#8230; Empezamos la ma\u00f1ana con risas y dos compa\u00f1erazos con MAYUSCULAS, nos faltaba la Bego, pero a esa la llevamos siempre! Reencuentros en el pabell\u00f3n de Moa\u00f1a, Bro\u00a0<a href=\"https:\/\/www.facebook.com\/jose.vera.777\" target=\"_blank\">Jos\u00e9<\/a>\u00a0, no sabes que vuelco me dio el coraz\u00f3n al verte! Nuevas caras a las que ponerle sonrisas, el abrazo de mi Capo Valwind y diciendo NO, esto no es para mi arranca la salida&#8230;. Y sigo diciendo NO una y otra vez, pero en nombre del compa\u00f1erismo y la cabezoner\u00eda\u00a0<a href=\"https:\/\/www.facebook.com\/jmuinomartinez\" target=\"_blank\">Jos\u00e9 Ram\u00f3n Mui\u00f1o<\/a>\u00a0me lleva sin hacerme ni caso, me promete que daremos vuelta en el avituallamiento&#8230;<br \/>\nNada mas lejos de la realidad, afortunadamente! Y va tirando de mi, charlando y entreteniendo a la cabeza del NO, y casi sin darnos cuenta llegamos a la parte m\u00e1s elevada del trail, con unas vistas dignas de la m\u00e1s superlativa belleza, vali\u00f3 la pena llegar&#8230; Un corredor perdido y bastante cansado se nos une, y con \u00e9l entre \u00e1nimos y charla empezamos a descender&#8230; Sin palabras lo que en esos momentos se vive, el coraz\u00f3n dispuesto a llenarse de olores y sensaciones, el r\u00edo, el bosque, las trazadas est\u00e1n llenas de magia y vida! Y a cada parada en la que crees que no puedes mas un gesto de Joserra que nos pon\u00eda las pilas al otro corredor y a mi&#8230; Y como el que no quiere la cosa llegamos a meta con una emoci\u00f2n incomparable! Lo logramos!!!! Esto no se puede pagar con nada!!! Pura vida\u2026. Fluir ser\u00eda el resumen del momento, por una vez dejarse llevar sin complejos de ser la \u00faltima, de no estar a la altura de las circunstancias, disfrutar de los momentos, de las esencias que nos regala este camino, disfrutar de nuestra Galicia llena de Magia y lugares dignos de cuentos de hadas\u2026. Y disfrutar del compa\u00f1erismo\u2026.<\/p>\n<p>Y un aplauso por el compa\u00f1erismo de cada uno de los que all\u00ed estuvieron&#8230;<br \/>\nY a mis chicas del Can Can solo decios que sois mi alma!!!! Sin vosotras no soy nada! Estoy prepar\u00e1ndome para la pr\u00f3xima, porque quiero seguir sintiendo, quiero seguir viviendo y volando por lugares m\u00e1gicos!<\/p>\n<div id=\"attachment_4680\" style=\"width: 455px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10980744_10203460949031970_6486953435770022212_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4680\" data-attachment-id=\"4680\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel\/10980744_10203460949031970_6486953435770022212_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10980744_10203460949031970_6486953435770022212_n.jpg?fit=742%2C960&amp;ssl=1\" data-orig-size=\"742,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel (1)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10980744_10203460949031970_6486953435770022212_n.jpg?fit=700%2C906&amp;ssl=1\" class=\" wp-image-4680 \" alt=\"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel (1)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10980744_10203460949031970_6486953435770022212_n.jpg?resize=445%2C576&#038;ssl=1\" width=\"445\" height=\"576\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10980744_10203460949031970_6486953435770022212_n.jpg?w=742&amp;ssl=1 742w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10980744_10203460949031970_6486953435770022212_n.jpg?resize=231%2C300&amp;ssl=1 231w\" sizes=\"auto, (max-width: 445px) 100vw, 445px\" \/><\/a><p id=\"caption-attachment-4680\" class=\"wp-caption-text\">Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4679\" style=\"width: 503px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10968496_589724361163010_6393454547579131459_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4679\" data-attachment-id=\"4679\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel\/10968496_589724361163010_6393454547579131459_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10968496_589724361163010_6393454547579131459_n.jpg?fit=704%2C960&amp;ssl=1\" data-orig-size=\"704,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel (2)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10968496_589724361163010_6393454547579131459_n.jpg?fit=700%2C955&amp;ssl=1\" class=\" wp-image-4679 \" alt=\"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel (2)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10968496_589724361163010_6393454547579131459_n.jpg?resize=493%2C672&#038;ssl=1\" width=\"493\" height=\"672\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10968496_589724361163010_6393454547579131459_n.jpg?w=704&amp;ssl=1 704w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10968496_589724361163010_6393454547579131459_n.jpg?resize=220%2C300&amp;ssl=1 220w\" sizes=\"auto, (max-width: 493px) 100vw, 493px\" \/><\/a><p id=\"caption-attachment-4679\" class=\"wp-caption-text\">Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4678\" style=\"width: 442px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10959662_589724444496335_6392180726813065692_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4678\" data-attachment-id=\"4678\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel\/10959662_589724444496335_6392180726813065692_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10959662_589724444496335_6392180726813065692_n.jpg?fit=720%2C960&amp;ssl=1\" data-orig-size=\"720,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel (3)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10959662_589724444496335_6392180726813065692_n.jpg?fit=700%2C933&amp;ssl=1\" class=\" wp-image-4678 \" alt=\"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel (3)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10959662_589724444496335_6392180726813065692_n.jpg?resize=432%2C576&#038;ssl=1\" width=\"432\" height=\"576\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10959662_589724444496335_6392180726813065692_n.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10959662_589724444496335_6392180726813065692_n.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><\/a><p id=\"caption-attachment-4678\" class=\"wp-caption-text\">Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4677\" style=\"width: 442px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10402563_589724417829671_588769842856654014_n.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4677\" data-attachment-id=\"4677\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel\/10402563_589724417829671_588769842856654014_n\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10402563_589724417829671_588769842856654014_n.jpg?fit=720%2C960&amp;ssl=1\" data-orig-size=\"720,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel (4)\" data-image-description=\"&lt;p&gt;Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10402563_589724417829671_588769842856654014_n.jpg?fit=700%2C933&amp;ssl=1\" class=\" wp-image-4677 \" alt=\"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel (4)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10402563_589724417829671_588769842856654014_n.jpg?resize=432%2C576&#038;ssl=1\" width=\"432\" height=\"576\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10402563_589724417829671_588769842856654014_n.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10402563_589724417829671_588769842856654014_n.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><\/a><p id=\"caption-attachment-4677\" class=\"wp-caption-text\">Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel<\/p><\/div>\n<p>&nbsp;<\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Domingo se corr\u00eda el Trail de Moa\u00f1a, el primer Trail de Galicia Maxica Trail Adventures\u2026. Yo ten\u00eda claro clar\u00edsimo que no lo iba a correr, si analizo mi interior&hellip; <\/p>\n","protected":false},"author":33,"featured_media":4678,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[80,76],"tags":[],"class_list":["post-4676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-mafia","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"El Domingo se corr\u00eda el Trail de Moa\u00f1a, el primer Trail de Galicia Maxica Trail Adventures\u2026. Yo ten\u00eda claro clar\u00edsimo que no lo iba a correr, si analizo mi interior&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"santajuliana.dpc?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-10T09:52:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10959662_589724444496335_6392180726813065692_n.jpg?fit=720%2C960&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Annabel JefaRiqui\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AnnabelMontiel\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Annabel JefaRiqui\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel\"},\"author\":{\"name\":\"Annabel JefaRiqui\u00f1a\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/e8245352d27b86c0893936c2582f58c6\"},\"headline\":\"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel\",\"datePublished\":\"2015-02-10T09:52:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel\"},\"wordCount\":638,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/10959662_589724444496335_6392180726813065692_n.jpg?fit=720%2C960&ssl=1\",\"articleSection\":[\"LA MAFIA\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel\",\"name\":\"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/10959662_589724444496335_6392180726813065692_n.jpg?fit=720%2C960&ssl=1\",\"datePublished\":\"2015-02-10T09:52:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/e8245352d27b86c0893936c2582f58c6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/10959662_589724444496335_6392180726813065692_n.jpg?fit=720%2C960&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/10959662_589724444496335_6392180726813065692_n.jpg?fit=720%2C960&ssl=1\",\"width\":720,\"height\":960,\"caption\":\"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/e8245352d27b86c0893936c2582f58c6\",\"name\":\"Annabel JefaRiqui\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9f4068e5e5d8865def28ab3bd909429c623cd36032bda23321fcb0f0c5a1c0e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9f4068e5e5d8865def28ab3bd909429c623cd36032bda23321fcb0f0c5a1c0e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9f4068e5e5d8865def28ab3bd909429c623cd36032bda23321fcb0f0c5a1c0e?s=96&d=mm&r=g\",\"caption\":\"Annabel JefaRiqui\u00f1a\"},\"description\":\"Apoyando siempre a las mujeres en el dif\u00edcil mundillo de #comosermadrebikerynomorirenelintento y todo lo que nos ayude a avanzar, tatuada en la piel una 29er aunque si hay que defender colores el turquesa se lleva la palma\u2026. As\u00ed que mi opini\u00f3n estar\u00e1 entre cl\u00e1sica, friki o extraterrestre\u2026. Si ves una chica maja con una interminable sonrisa con calcetines frikis hasta la rodilla y una gorra cl\u00e1sica en su cabeza seguro que es ella\u2026 mi JefaRiqui\u00f1a\",\"sameAs\":[\"http:\\\/\\\/mumshand.blogspot.com.es\",\"santajuliana.dpc?fref=ts\",\"http:\\\/\\\/www.pinterest.com\\\/santajuliana\\\/\",\"https:\\\/\\\/x.com\\\/AnnabelMontiel\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/annabel-jefariquina\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel","og_locale":"es_ES","og_type":"article","og_title":"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel - El Blog de ValwindCycles","og_description":"El Domingo se corr\u00eda el Trail de Moa\u00f1a, el primer Trail de Galicia Maxica Trail Adventures\u2026. Yo ten\u00eda claro clar\u00edsimo que no lo iba a correr, si analizo mi interior&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"santajuliana.dpc?fref=ts","article_published_time":"2015-02-10T09:52:58+00:00","og_image":[{"width":720,"height":960,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10959662_589724444496335_6392180726813065692_n.jpg?fit=720%2C960&ssl=1","type":"image\/jpeg"}],"author":"Annabel JefaRiqui\u00f1a","twitter_card":"summary_large_image","twitter_creator":"@AnnabelMontiel","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Annabel JefaRiqui\u00f1a","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel"},"author":{"name":"Annabel JefaRiqui\u00f1a","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/e8245352d27b86c0893936c2582f58c6"},"headline":"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel","datePublished":"2015-02-10T09:52:58+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel"},"wordCount":638,"commentCount":1,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10959662_589724444496335_6392180726813065692_n.jpg?fit=720%2C960&ssl=1","articleSection":["LA MAFIA","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel","url":"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel","name":"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10959662_589724444496335_6392180726813065692_n.jpg?fit=720%2C960&ssl=1","datePublished":"2015-02-10T09:52:58+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/e8245352d27b86c0893936c2582f58c6"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10959662_589724444496335_6392180726813065692_n.jpg?fit=720%2C960&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10959662_589724444496335_6392180726813065692_n.jpg?fit=720%2C960&ssl=1","width":720,"height":960,"caption":"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel"},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/volando-por-lugares-magicos-trail-de-moana-por-jefariquina-annabel#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Volando por lugares m\u00e1gicos, Trail de Moa\u00f1a por JefaRiqui\u00f1a Annabel"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/e8245352d27b86c0893936c2582f58c6","name":"Annabel JefaRiqui\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d9f4068e5e5d8865def28ab3bd909429c623cd36032bda23321fcb0f0c5a1c0e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d9f4068e5e5d8865def28ab3bd909429c623cd36032bda23321fcb0f0c5a1c0e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9f4068e5e5d8865def28ab3bd909429c623cd36032bda23321fcb0f0c5a1c0e?s=96&d=mm&r=g","caption":"Annabel JefaRiqui\u00f1a"},"description":"Apoyando siempre a las mujeres en el dif\u00edcil mundillo de #comosermadrebikerynomorirenelintento y todo lo que nos ayude a avanzar, tatuada en la piel una 29er aunque si hay que defender colores el turquesa se lleva la palma\u2026. As\u00ed que mi opini\u00f3n estar\u00e1 entre cl\u00e1sica, friki o extraterrestre\u2026. Si ves una chica maja con una interminable sonrisa con calcetines frikis hasta la rodilla y una gorra cl\u00e1sica en su cabeza seguro que es ella\u2026 mi JefaRiqui\u00f1a","sameAs":["http:\/\/mumshand.blogspot.com.es","santajuliana.dpc?fref=ts","http:\/\/www.pinterest.com\/santajuliana\/","https:\/\/x.com\/AnnabelMontiel"],"url":"https:\/\/valwindcycles.es\/blog\/author\/annabel-jefariquina"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-1dq","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/02\/10959662_589724444496335_6392180726813065692_n.jpg?fit=720%2C960&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/4676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=4676"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/4676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/4678"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=4676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=4676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=4676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}