{"id":4748,"date":"2015-03-02T17:29:39","date_gmt":"2015-03-02T16:29:39","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=4748"},"modified":"2015-03-02T17:29:39","modified_gmt":"2015-03-02T16:29:39","slug":"ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita","title":{"rendered":"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita"},"content":{"rendered":"<p>Hace cerca de dos a\u00f1os hice una lista con 50 cosas que hacer antes de morir, y entre ellas la n\u00famero 20 dice lo siguiente:<\/p>\n<p>\u00bb Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb<\/p>\n<p>Lo cierto es que nunca sabes si la vida te brindar\u00e1 la oportunidad de cumplirlas todas,la mayor\u00eda o tan solo unas pocas&#8230;<\/p>\n<div>\n<p>El 21 de Febrero, tras varias semanas recaudando fondos para el Proyecto Sahara (un total de 911 euros aportados por grandes amigos y compa\u00f1eros que se solidarizaron con la causa) emprendo mi aventura rumbo a los campos de refugiados de Smara sin imaginar que all\u00ed encontrar\u00eda un pueblo cargado de cari\u00f1o y hospitalidad. La base fundamental del viaje era correr 42km por el desierto en la 15 edici\u00f3n del Sahara Marathon, pero result\u00f3 ser mucho mucho m\u00e1s que eso. All\u00ed encontr\u00e9 el apoyo incondicional de mi compa\u00f1ero de aventura Iv\u00e1n, el cari\u00f1o y la complicidad de dos hermanos de Lebrija que hicieron que una semana se convirtiese en momentos cargados de sonrisas, Paco y Juanma os debemos un Bogavante \u00abjarto de mandarinas\u00bb. Pero sobretodo&#8230; all\u00ed, en medio de la nada, en medio del desierto&#8230;<\/p>\n<p>Encontr\u00e9 a mi segunda familia. Jalida, Najat, Senia, Mama&#8230; Os lo debemos todo, por cada una de vuestras sonrisas, de vuestras l\u00e1grimas, de vuestros gestos, de vuestras muestras de cari\u00f1o, de vuestro esfuerzo&#8230; Porque con vuestras miradas nos lo dec\u00eds todo, porque no hace falta hablar un mismo idioma, porque el idioma universal es el amor y porque solo he encontrado unos sentimientos tan sinceros en el Sahara, por eso y mucho m\u00e1s&#8230; Os lo debemos todo.<\/p>\n<p>Hay momentos e historias que resultan imposibles de contar, solo se pueden vivir.<\/p>\n<div id=\"attachment_4762\" style=\"width: 452px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0063.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4762\" data-attachment-id=\"4762\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\/img_0063\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0063.jpg?fit=1800%2C1800&amp;ssl=1\" data-orig-size=\"1800,1800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita  (1)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0063.jpg?fit=700%2C700&amp;ssl=1\" class=\" wp-image-4762   \" alt=\"&quot;Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones &quot; por Andreita (1)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0063.jpg?resize=442%2C442&#038;ssl=1\" width=\"442\" height=\"442\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0063.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0063.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0063.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0063.jpg?w=1800&amp;ssl=1 1800w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0063.jpg?w=1400&amp;ssl=1 1400w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><\/a><p id=\"caption-attachment-4762\" class=\"wp-caption-text\">\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4749\" style=\"width: 452px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0048.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4749\" data-attachment-id=\"4749\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\/img_0048\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0048.jpg?fit=1280%2C960&amp;ssl=1\" data-orig-size=\"1280,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita  (14)\" data-image-description=\"&lt;p&gt;\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita &lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0048.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-4749   \" alt=\"&quot;Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones &quot; por Andreita (14)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0048.jpg?resize=442%2C332&#038;ssl=1\" width=\"442\" height=\"332\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0048.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0048.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0048.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><\/a><p id=\"caption-attachment-4749\" class=\"wp-caption-text\">\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4752\" style=\"width: 471px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0051.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4752\" data-attachment-id=\"4752\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\/img_0051\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0051.jpg?fit=960%2C1280&amp;ssl=1\" data-orig-size=\"960,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita  (11)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0051.jpg?fit=700%2C933&amp;ssl=1\" class=\" wp-image-4752 \" alt=\"&quot;Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones &quot; por Andreita (11)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0051.jpg?resize=461%2C614&#038;ssl=1\" width=\"461\" height=\"614\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0051.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0051.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0051.jpg?w=960&amp;ssl=1 960w\" sizes=\"auto, (max-width: 461px) 100vw, 461px\" \/><\/a><p id=\"caption-attachment-4752\" class=\"wp-caption-text\">\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4751\" style=\"width: 452px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0050.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4751\" data-attachment-id=\"4751\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\/img_0050\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0050.jpg?fit=1280%2C960&amp;ssl=1\" data-orig-size=\"1280,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita  (12)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0050.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-4751   \" alt=\"&quot;Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones &quot; por Andreita (12)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0050.jpg?resize=442%2C332&#038;ssl=1\" width=\"442\" height=\"332\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0050.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0050.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0050.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><\/a><p id=\"caption-attachment-4751\" class=\"wp-caption-text\">\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4758\" style=\"width: 452px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0059.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4758\" data-attachment-id=\"4758\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\/img_0059\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0059.jpg?fit=1136%2C640&amp;ssl=1\" data-orig-size=\"1136,640\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita  (5)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0059.jpg?fit=700%2C394&amp;ssl=1\" class=\" wp-image-4758   \" alt=\"&quot;Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones &quot; por Andreita (5)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0059.jpg?resize=442%2C249&#038;ssl=1\" width=\"442\" height=\"249\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0059.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0059.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0059.jpg?w=1136&amp;ssl=1 1136w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><\/a><p id=\"caption-attachment-4758\" class=\"wp-caption-text\">\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4761\" style=\"width: 452px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0062.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4761\" data-attachment-id=\"4761\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\/img_0062\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0062.jpg?fit=1136%2C640&amp;ssl=1\" data-orig-size=\"1136,640\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita  (2)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0062.jpg?fit=700%2C394&amp;ssl=1\" class=\" wp-image-4761   \" alt=\"&quot;Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones &quot; por Andreita (2)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0062.jpg?resize=442%2C249&#038;ssl=1\" width=\"442\" height=\"249\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0062.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0062.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0062.jpg?w=1136&amp;ssl=1 1136w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><\/a><p id=\"caption-attachment-4761\" class=\"wp-caption-text\">\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4760\" style=\"width: 452px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0061.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4760\" data-attachment-id=\"4760\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\/img_0061\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0061.jpg?fit=1136%2C640&amp;ssl=1\" data-orig-size=\"1136,640\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita  (3)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0061.jpg?fit=700%2C394&amp;ssl=1\" class=\" wp-image-4760   \" alt=\"&quot;Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones &quot; por Andreita (3)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0061.jpg?resize=442%2C249&#038;ssl=1\" width=\"442\" height=\"249\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0061.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0061.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0061.jpg?w=1136&amp;ssl=1 1136w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><\/a><p id=\"caption-attachment-4760\" class=\"wp-caption-text\">\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4755\" style=\"width: 471px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0054.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4755\" data-attachment-id=\"4755\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\/img_0054\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0054.jpg?fit=960%2C1280&amp;ssl=1\" data-orig-size=\"960,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita  (8)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0054.jpg?fit=700%2C933&amp;ssl=1\" class=\" wp-image-4755  \" alt=\"&quot;Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones &quot; por Andreita (8)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0054.jpg?resize=461%2C614&#038;ssl=1\" width=\"461\" height=\"614\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0054.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0054.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0054.jpg?w=960&amp;ssl=1 960w\" sizes=\"auto, (max-width: 461px) 100vw, 461px\" \/><\/a><p id=\"caption-attachment-4755\" class=\"wp-caption-text\">\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4759\" style=\"width: 452px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0060.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4759\" data-attachment-id=\"4759\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\/img_0060\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0060.jpg?fit=1136%2C640&amp;ssl=1\" data-orig-size=\"1136,640\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita  (4)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0060.jpg?fit=700%2C394&amp;ssl=1\" class=\" wp-image-4759   \" alt=\"&quot;Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones &quot; por Andreita (4)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0060.jpg?resize=442%2C249&#038;ssl=1\" width=\"442\" height=\"249\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0060.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0060.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0060.jpg?w=1136&amp;ssl=1 1136w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><\/a><p id=\"caption-attachment-4759\" class=\"wp-caption-text\">\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4754\" style=\"width: 471px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0053.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4754\" data-attachment-id=\"4754\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\/img_0053\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0053.jpg?fit=960%2C1280&amp;ssl=1\" data-orig-size=\"960,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita  (9)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0053.jpg?fit=700%2C933&amp;ssl=1\" class=\" wp-image-4754 \" alt=\"&quot;Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones &quot; por Andreita (9)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0053.jpg?resize=461%2C614&#038;ssl=1\" width=\"461\" height=\"614\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0053.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0053.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0053.jpg?w=960&amp;ssl=1 960w\" sizes=\"auto, (max-width: 461px) 100vw, 461px\" \/><\/a><p id=\"caption-attachment-4754\" class=\"wp-caption-text\">\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4756\" style=\"width: 471px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0056.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4756\" data-attachment-id=\"4756\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\/img_0056\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0056.jpg?fit=960%2C1280&amp;ssl=1\" data-orig-size=\"960,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita  (7)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0056.jpg?fit=700%2C933&amp;ssl=1\" class=\" wp-image-4756 \" alt=\"&quot;Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones &quot; por Andreita (7)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0056.jpg?resize=461%2C614&#038;ssl=1\" width=\"461\" height=\"614\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0056.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0056.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0056.jpg?w=960&amp;ssl=1 960w\" sizes=\"auto, (max-width: 461px) 100vw, 461px\" \/><\/a><p id=\"caption-attachment-4756\" class=\"wp-caption-text\">\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4753\" style=\"width: 452px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0052.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4753\" data-attachment-id=\"4753\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\/img_0052\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0052.jpg?fit=1280%2C960&amp;ssl=1\" data-orig-size=\"1280,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita  (10)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita &lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0052.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-4753   \" alt=\"&quot;Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones &quot; por Andreita (10)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0052.jpg?resize=442%2C332&#038;ssl=1\" width=\"442\" height=\"332\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0052.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0052.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0052.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><\/a><p id=\"caption-attachment-4753\" class=\"wp-caption-text\">\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4748-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_8323.mp4?_=1\" \/><a href=\"https:\/\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_8323.mp4\">https:\/\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_8323.mp4<\/a><\/video><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hace cerca de dos a\u00f1os hice una lista con 50 cosas que hacer antes de morir, y entre ellas la n\u00famero 20 dice lo siguiente: \u00bb Ir a un pa\u00eds&hellip; <\/p>\n","protected":false},"author":2,"featured_media":4758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[80,76],"tags":[],"class_list":["post-4748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-mafia","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones &quot; por Andreita  - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones &quot; por Andreita  - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"Hace cerca de dos a\u00f1os hice una lista con 50 cosas que hacer antes de morir, y entre ellas la n\u00famero 20 dice lo siguiente: \u00bb Ir a un pa\u00eds&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"ValwindCycles\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-02T16:29:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0059.jpg?fit=1136%2C640&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1136\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge ValwindCycles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge ValwindCycles\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\"},\"author\":{\"name\":\"Jorge ValwindCycles\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"headline\":\"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita\",\"datePublished\":\"2015-03-02T16:29:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\"},\"wordCount\":630,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/IMG_0059.jpg?fit=1136%2C640&ssl=1\",\"articleSection\":[\"LA MAFIA\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\",\"name\":\"\\\"Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \\\" por Andreita - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/IMG_0059.jpg?fit=1136%2C640&ssl=1\",\"datePublished\":\"2015-03-02T16:29:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/IMG_0059.jpg?fit=1136%2C640&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/IMG_0059.jpg?fit=1136%2C640&ssl=1\",\"width\":1136,\"height\":640,\"caption\":\"\\\"Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \\\" por Andreita\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\",\"name\":\"Jorge ValwindCycles\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"caption\":\"Jorge ValwindCycles\"},\"description\":\"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.\",\"sameAs\":[\"http:\\\/\\\/www.valwindcycles.es\",\"ValwindCycles\",\"http:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=180972148&trk=nav_responsive_tab_profile\",\"http:\\\/\\\/www.pinterest.com\\\/valwindcycles\\\/\",\"https:\\\/\\\/x.com\\\/JorgeValwind\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/Valwindcycles\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/valwind\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \" por Andreita  - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita","og_locale":"es_ES","og_type":"article","og_title":"\"Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \" por Andreita  - El Blog de ValwindCycles","og_description":"Hace cerca de dos a\u00f1os hice una lista con 50 cosas que hacer antes de morir, y entre ellas la n\u00famero 20 dice lo siguiente: \u00bb Ir a un pa\u00eds&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"ValwindCycles","article_published_time":"2015-03-02T16:29:39+00:00","og_image":[{"width":1136,"height":640,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0059.jpg?fit=1136%2C640&ssl=1","type":"image\/jpeg"}],"author":"Jorge ValwindCycles","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Jorge ValwindCycles","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita"},"author":{"name":"Jorge ValwindCycles","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"headline":"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita","datePublished":"2015-03-02T16:29:39+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita"},"wordCount":630,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0059.jpg?fit=1136%2C640&ssl=1","articleSection":["LA MAFIA","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita","url":"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita","name":"\"Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \" por Andreita - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0059.jpg?fit=1136%2C640&ssl=1","datePublished":"2015-03-02T16:29:39+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0059.jpg?fit=1136%2C640&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0059.jpg?fit=1136%2C640&ssl=1","width":1136,"height":640,"caption":"\"Ir a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \" por Andreita"},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/ir-a-un-pais-subdesarrollado-y-convivir-con-personas-que-viven-en-peores-condiciones-por-andreita#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"\u00abIr a un pa\u00eds subdesarrollado y convivir con personas que viven en peores condiciones \u00bb por Andreita"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3","name":"Jorge ValwindCycles","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","caption":"Jorge ValwindCycles"},"description":"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.","sameAs":["http:\/\/www.valwindcycles.es","ValwindCycles","http:\/\/www.linkedin.com\/profile\/view?id=180972148&trk=nav_responsive_tab_profile","http:\/\/www.pinterest.com\/valwindcycles\/","https:\/\/x.com\/JorgeValwind","http:\/\/www.youtube.com\/user\/Valwindcycles"],"url":"https:\/\/valwindcycles.es\/blog\/author\/valwind"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-1eA","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/03\/IMG_0059.jpg?fit=1136%2C640&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/4748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=4748"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/4748\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/4758"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=4748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=4748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=4748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}