{"id":5122,"date":"2015-06-07T17:29:27","date_gmt":"2015-06-07T16:29:27","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=5122"},"modified":"2015-06-07T17:29:27","modified_gmt":"2015-06-07T16:29:27","slug":"ii-mini-btt-concello-de-cambados-por-pirucho-pequeno","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno","title":{"rendered":"II Mini BTT Concello de Cambados por Pirucho Pequeno"},"content":{"rendered":"<p><b>\u00a0<\/b><\/p>\n<p>Siguiendo con la vor\u00e1gine de dos carreras de Btt por fin de semana, la cual va acabar conmigo, tras asistir a la prueba\u00a0 del Open de XC de Cambre era turno para\u00a0 II Mini BTT Concello de Cambados.<\/p>\n<p>Como bien se puede deducir del nombre,\u00a0 disputado en el Concello de Cambados, para ser m\u00e1s concretos en el Monte da Pastora. Un terreno con pendientes muy pronunciadas, donde los organizadores del Club Ciclista Corbelo Portonovo se han especializado en crear circuitos duros y t\u00e9cnicos. Pero no os cre\u00e1is que esto desanima a los minibeteteros, estos peque\u00f1ajos est\u00e1n hechos de otra pasta, aunque el trazado los exprima al m\u00e1ximo son capaz de seguir disfrutando de la competici\u00f3n.<\/p>\n<p>Si en la edici\u00f3n anterior los organizadores estimaron la participaci\u00f3n de 180 corredores, este a\u00f1o se bati\u00f3 un nuevo record, 250 competidores tomaron parte en las distintas mangas.\u00a0 Siempre es positivo que aumente el n\u00famero de inscritos a un deporte, es s\u00edntoma de una buena salud del mismo. Lamentablemente en el caso del MiniBtt gallego, el incremento de afluencia, saca a la luz fallos log\u00edsticos prolongando innecesariamente\u00a0 la competencia.\u00a0 Concretamente en el II Mini BTT Concello de Cambados la cita abarco desde las 10 a.m. hasta las 15 p.m. . Esta es la principal raz\u00f3n por las que no encontrareis fotos del p\u00f3dium esta vez,\u00a0 el trajin del fin de semana acab\u00f3 con mis pilas y me retire justo despu\u00e9s de finalizar la \u00faltima carrera. Desgraciadamente no me quedaron fuerzas para disfrutar\u00a0 de la clase de Zumba a cargo de Rita Garcia organizada por los chicos del Corbelo en colaboraci\u00f3n con\u00a0 \u00abStudio21 Discotecas M\u00f3viles\u00bb. Todas las fotos del d\u00eda las pod\u00e9is encontrar en el siguiente <a href=\"https:\/\/plus.google.com\/u\/0\/photos\/+LuzIglesias\/albums\/6155126841322770321\">AQU\u00cd<\/a> y las clasificaciones <a href=\"http:\/\/fgalegaciclismo.es\/calendario.aspx\">AQU\u00cd<\/a>.<\/p>\n<p>Por \u00faltimo, la perla de\u00a0 la\u00a0 jornada fue la mejor noticia de todas\u2026 Pablo Rodriguez Guede,\u00a0 el que un d\u00eda fue otro participante del MiniBtt, ese ni\u00f1o que siempre apunto maneras y que al crecer no defraudo, ha conseguido subirse a lo m\u00e1s alto del caj\u00f3n de la Copa del Mundo. Mi m\u00e1s sincera enhorabuena Pablo,\u00a0 los que hemos tenido el privilegio de verte crecer carrera a carrera sabemos que esta es la primera de las muchas recompensas que te esperan por todo tu trabajo.\u00a0 Felicidades.<\/p>\n<div id=\"attachment_5153\" style=\"width: 434px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/Portada2.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5153\" data-attachment-id=\"5153\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/portada-13\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/Portada2.jpg?fit=530%2C756&amp;ssl=1\" data-orig-size=\"530,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (1)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/Portada2.jpg?fit=530%2C756&amp;ssl=1\" class=\" wp-image-5153 \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (1)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/Portada2.jpg?resize=424%2C605&#038;ssl=1\" width=\"424\" height=\"605\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/Portada2.jpg?w=530&amp;ssl=1 530w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/Portada2.jpg?resize=210%2C300&amp;ssl=1 210w\" sizes=\"auto, (max-width: 424px) 100vw, 424px\" \/><\/a><p id=\"caption-attachment-5153\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5139\" style=\"width: 493px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316457.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5139\" data-attachment-id=\"5139\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316457\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316457.jpg?fit=1007%2C756&amp;ssl=1\" data-orig-size=\"1007,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (15)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316457.jpg?fit=700%2C526&amp;ssl=1\" class=\" wp-image-5139  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (15)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316457.jpg?resize=483%2C363&#038;ssl=1\" width=\"483\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316457.jpg?w=1007&amp;ssl=1 1007w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316457.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 483px) 100vw, 483px\" \/><\/a><p id=\"caption-attachment-5139\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5147\" style=\"width: 494px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166491.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5147\" data-attachment-id=\"5147\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316649-2\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166491.jpg?fit=1008%2C756&amp;ssl=1\" data-orig-size=\"1008,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (7)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166491.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-5147  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (7)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166491.jpg?resize=484%2C363&#038;ssl=1\" width=\"484\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166491.jpg?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166491.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/a><p id=\"caption-attachment-5147\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5143\" style=\"width: 493px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316514.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5143\" data-attachment-id=\"5143\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316514\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316514.jpg?fit=1007%2C756&amp;ssl=1\" data-orig-size=\"1007,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (11)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316514.jpg?fit=700%2C526&amp;ssl=1\" class=\" wp-image-5143  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (11)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316514.jpg?resize=483%2C363&#038;ssl=1\" width=\"483\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316514.jpg?w=1007&amp;ssl=1 1007w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316514.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 483px) 100vw, 483px\" \/><\/a><p id=\"caption-attachment-5143\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5150\" style=\"width: 492px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53169411.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5150\" data-attachment-id=\"5150\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316941-2\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53169411.jpg?fit=1005%2C756&amp;ssl=1\" data-orig-size=\"1005,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (4)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53169411.jpg?fit=700%2C527&amp;ssl=1\" class=\" wp-image-5150  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (4)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53169411.jpg?resize=482%2C363&#038;ssl=1\" width=\"482\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53169411.jpg?w=1005&amp;ssl=1 1005w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53169411.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 482px) 100vw, 482px\" \/><\/a><p id=\"caption-attachment-5150\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5151\" style=\"width: 462px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53169981.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5151\" data-attachment-id=\"5151\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316998-2\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53169981.jpg?fit=565%2C756&amp;ssl=1\" data-orig-size=\"565,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (3)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53169981.jpg?fit=565%2C756&amp;ssl=1\" class=\" wp-image-5151 \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (3)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53169981.jpg?resize=452%2C605&#038;ssl=1\" width=\"452\" height=\"605\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53169981.jpg?w=565&amp;ssl=1 565w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53169981.jpg?resize=224%2C300&amp;ssl=1 224w\" sizes=\"auto, (max-width: 452px) 100vw, 452px\" \/><\/a><p id=\"caption-attachment-5151\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5148\" style=\"width: 464px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166711.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5148\" data-attachment-id=\"5148\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316671-2\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166711.jpg?fit=567%2C756&amp;ssl=1\" data-orig-size=\"567,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (6)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166711.jpg?fit=567%2C756&amp;ssl=1\" class=\" wp-image-5148 \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (6)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166711.jpg?resize=454%2C605&#038;ssl=1\" width=\"454\" height=\"605\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166711.jpg?w=567&amp;ssl=1 567w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166711.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 454px) 100vw, 454px\" \/><\/a><p id=\"caption-attachment-5148\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5146\" style=\"width: 494px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166271.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5146\" data-attachment-id=\"5146\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316627-2\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166271.jpg?fit=1008%2C756&amp;ssl=1\" data-orig-size=\"1008,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (8)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166271.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-5146  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (8)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166271.jpg?resize=484%2C363&#038;ssl=1\" width=\"484\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166271.jpg?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53166271.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/a><p id=\"caption-attachment-5146\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5145\" style=\"width: 494px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316624.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5145\" data-attachment-id=\"5145\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316624\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316624.jpg?fit=1008%2C756&amp;ssl=1\" data-orig-size=\"1008,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (9)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316624.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-5145   \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (9)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316624.jpg?resize=484%2C363&#038;ssl=1\" width=\"484\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316624.jpg?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316624.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/a><p id=\"caption-attachment-5145\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5152\" style=\"width: 494px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53170211.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5152\" data-attachment-id=\"5152\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5317021-2\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53170211.jpg?fit=1008%2C756&amp;ssl=1\" data-orig-size=\"1008,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (2)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53170211.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-5152  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (2)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53170211.jpg?resize=484%2C363&#038;ssl=1\" width=\"484\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53170211.jpg?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53170211.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/a><p id=\"caption-attachment-5152\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5149\" style=\"width: 464px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53167671.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5149\" data-attachment-id=\"5149\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316767-2\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53167671.jpg?fit=567%2C756&amp;ssl=1\" data-orig-size=\"567,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (5)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53167671.jpg?fit=567%2C756&amp;ssl=1\" class=\" wp-image-5149 \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (5)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53167671.jpg?resize=454%2C605&#038;ssl=1\" width=\"454\" height=\"605\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53167671.jpg?w=567&amp;ssl=1 567w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P53167671.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 454px) 100vw, 454px\" \/><\/a><p id=\"caption-attachment-5149\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5144\" style=\"width: 493px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316545.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5144\" data-attachment-id=\"5144\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316545\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316545.jpg?fit=1006%2C756&amp;ssl=1\" data-orig-size=\"1006,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (10)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316545.jpg?fit=700%2C526&amp;ssl=1\" class=\" wp-image-5144  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (10)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316545.jpg?resize=483%2C363&#038;ssl=1\" width=\"483\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316545.jpg?w=1006&amp;ssl=1 1006w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316545.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 483px) 100vw, 483px\" \/><\/a><p id=\"caption-attachment-5144\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5142\" style=\"width: 493px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316473.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5142\" data-attachment-id=\"5142\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316473\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316473.jpg?fit=1006%2C756&amp;ssl=1\" data-orig-size=\"1006,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (12)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316473.jpg?fit=700%2C526&amp;ssl=1\" class=\" wp-image-5142  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (12)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316473.jpg?resize=483%2C363&#038;ssl=1\" width=\"483\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316473.jpg?w=1006&amp;ssl=1 1006w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316473.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 483px) 100vw, 483px\" \/><\/a><p id=\"caption-attachment-5142\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5141\" style=\"width: 493px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316472.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5141\" data-attachment-id=\"5141\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316472\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316472.jpg?fit=1007%2C756&amp;ssl=1\" data-orig-size=\"1007,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (13)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316472.jpg?fit=700%2C526&amp;ssl=1\" class=\" wp-image-5141  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (13)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316472.jpg?resize=483%2C363&#038;ssl=1\" width=\"483\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316472.jpg?w=1007&amp;ssl=1 1007w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316472.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 483px) 100vw, 483px\" \/><\/a><p id=\"caption-attachment-5141\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5140\" style=\"width: 494px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316471.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5140\" data-attachment-id=\"5140\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316471\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316471.jpg?fit=1008%2C756&amp;ssl=1\" data-orig-size=\"1008,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (14)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316471.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-5140  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (14)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316471.jpg?resize=484%2C363&#038;ssl=1\" width=\"484\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316471.jpg?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316471.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/a><p id=\"caption-attachment-5140\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5138\" style=\"width: 494px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316449.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5138\" data-attachment-id=\"5138\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316449\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316449.jpg?fit=1008%2C756&amp;ssl=1\" data-orig-size=\"1008,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (16)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316449.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-5138  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (16)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316449.jpg?resize=484%2C363&#038;ssl=1\" width=\"484\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316449.jpg?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316449.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/a><p id=\"caption-attachment-5138\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5137\" style=\"width: 492px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316440.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5137\" data-attachment-id=\"5137\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316440\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316440.jpg?fit=1005%2C756&amp;ssl=1\" data-orig-size=\"1005,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (17)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316440.jpg?fit=700%2C527&amp;ssl=1\" class=\" wp-image-5137  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (17)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316440.jpg?resize=482%2C363&#038;ssl=1\" width=\"482\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316440.jpg?w=1005&amp;ssl=1 1005w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316440.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 482px) 100vw, 482px\" \/><\/a><p id=\"caption-attachment-5137\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5136\" style=\"width: 494px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316435.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5136\" data-attachment-id=\"5136\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316435\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316435.jpg?fit=1008%2C756&amp;ssl=1\" data-orig-size=\"1008,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (18)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316435.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-5136  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (18)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316435.jpg?resize=484%2C363&#038;ssl=1\" width=\"484\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316435.jpg?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316435.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/a><p id=\"caption-attachment-5136\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5135\" style=\"width: 494px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316433.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5135\" data-attachment-id=\"5135\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316433\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316433.jpg?fit=1008%2C756&amp;ssl=1\" data-orig-size=\"1008,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (19)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316433.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-5135  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (19)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316433.jpg?resize=484%2C363&#038;ssl=1\" width=\"484\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316433.jpg?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316433.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/a><p id=\"caption-attachment-5135\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5134\" style=\"width: 492px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316344.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5134\" data-attachment-id=\"5134\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316344\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316344.jpg?fit=1005%2C756&amp;ssl=1\" data-orig-size=\"1005,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (20)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316344.jpg?fit=700%2C527&amp;ssl=1\" class=\" wp-image-5134  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (20)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316344.jpg?resize=482%2C363&#038;ssl=1\" width=\"482\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316344.jpg?w=1005&amp;ssl=1 1005w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316344.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 482px) 100vw, 482px\" \/><\/a><p id=\"caption-attachment-5134\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5133\" style=\"width: 494px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316323.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5133\" data-attachment-id=\"5133\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316323\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316323.jpg?fit=1008%2C756&amp;ssl=1\" data-orig-size=\"1008,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (21)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316323.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-5133  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (21)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316323.jpg?resize=484%2C363&#038;ssl=1\" width=\"484\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316323.jpg?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316323.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/a><p id=\"caption-attachment-5133\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5132\" style=\"width: 494px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316318.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5132\" data-attachment-id=\"5132\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316318\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316318.jpg?fit=1008%2C756&amp;ssl=1\" data-orig-size=\"1008,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (22)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316318.jpg?fit=700%2C525&amp;ssl=1\" class=\" wp-image-5132  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (22)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316318.jpg?resize=484%2C363&#038;ssl=1\" width=\"484\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316318.jpg?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316318.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/a><p id=\"caption-attachment-5132\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_5131\" style=\"width: 492px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316306.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5131\" data-attachment-id=\"5131\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\/p5316306\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316306.jpg?fit=1005%2C756&amp;ssl=1\" data-orig-size=\"1005,756\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (23)\" data-image-description=\"&lt;p&gt;v&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;II Mini BTT Concello de Cambados por Pirucho Pequeno&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316306.jpg?fit=700%2C527&amp;ssl=1\" class=\" wp-image-5131  \" alt=\"II Mini BTT Concello de Cambados por Pirucho Pequeno (23)\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316306.jpg?resize=482%2C363&#038;ssl=1\" width=\"482\" height=\"363\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316306.jpg?w=1005&amp;ssl=1 1005w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316306.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 482px) 100vw, 482px\" \/><\/a><p id=\"caption-attachment-5131\" class=\"wp-caption-text\">II Mini BTT Concello de Cambados por Pirucho Pequeno<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Siguiendo con la vor\u00e1gine de dos carreras de Btt por fin de semana, la cual va acabar conmigo, tras asistir a la prueba\u00a0 del Open de XC de Cambre&hellip; <\/p>\n","protected":false},"author":32,"featured_media":5124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[72,71,80,76],"tags":[],"class_list":["post-5122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-fotos","category-la-mafia","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>II Mini BTT Concello de Cambados por Pirucho Pequeno - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"II Mini BTT Concello de Cambados por Pirucho Pequeno - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"\u00a0 Siguiendo con la vor\u00e1gine de dos carreras de Btt por fin de semana, la cual va acabar conmigo, tras asistir a la prueba\u00a0 del Open de XC de Cambre&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"luzmaria.iglesiasmosquera?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-07T16:29:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316649.jpg?fit=1008%2C756&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1008\" \/>\n\t<meta property=\"og:image:height\" content=\"756\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pirucho Pequeno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pirucho Pequeno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\"},\"author\":{\"name\":\"Pirucho Pequeno\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/2dc70d4ba4335aacd4f8dbf7805eee9e\"},\"headline\":\"II Mini BTT Concello de Cambados por Pirucho Pequeno\",\"datePublished\":\"2015-06-07T16:29:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\"},\"wordCount\":796,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/P5316649.jpg?fit=1008%2C756&ssl=1\",\"articleSection\":[\"Eventos\",\"Fotos\",\"LA MAFIA\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\",\"name\":\"II Mini BTT Concello de Cambados por Pirucho Pequeno - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/P5316649.jpg?fit=1008%2C756&ssl=1\",\"datePublished\":\"2015-06-07T16:29:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/2dc70d4ba4335aacd4f8dbf7805eee9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/P5316649.jpg?fit=1008%2C756&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/P5316649.jpg?fit=1008%2C756&ssl=1\",\"width\":1008,\"height\":756,\"caption\":\"II Mini BTT Concello de Cambados por Pirucho Pequeno\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"II Mini BTT Concello de Cambados por Pirucho Pequeno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/2dc70d4ba4335aacd4f8dbf7805eee9e\",\"name\":\"Pirucho Pequeno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g\",\"caption\":\"Pirucho Pequeno\"},\"description\":\"Se puede decir que es una especie de \u201cgroupie de ciclistas\u201d, nunca ha competido pero le encanta el mundo del ciclismo. Sus tareas principales son avituallar y fotografiar a todo aquel que me se lo pida con una sonrisa. Sus albumes de fotos en GOOGLE+ son visitados por cientos, miles, millones de personas y hasta marcianos y derivados. Ojo que aunque la ve\u00e1is en las carreras con una mirada angelical no recoge ni chaquetillas ni termicas en la salida, lo que le da fama de mala mujer.\",\"sameAs\":[\"https:\\\/\\\/picasaweb.google.com\\\/114831358335341071162\",\"luzmaria.iglesiasmosquera?fref=ts\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/pirucho-pequeno\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"II Mini BTT Concello de Cambados por Pirucho Pequeno - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno","og_locale":"es_ES","og_type":"article","og_title":"II Mini BTT Concello de Cambados por Pirucho Pequeno - El Blog de ValwindCycles","og_description":"\u00a0 Siguiendo con la vor\u00e1gine de dos carreras de Btt por fin de semana, la cual va acabar conmigo, tras asistir a la prueba\u00a0 del Open de XC de Cambre&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"luzmaria.iglesiasmosquera?fref=ts","article_published_time":"2015-06-07T16:29:27+00:00","og_image":[{"width":1008,"height":756,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316649.jpg?fit=1008%2C756&ssl=1","type":"image\/jpeg"}],"author":"Pirucho Pequeno","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Pirucho Pequeno","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno"},"author":{"name":"Pirucho Pequeno","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/2dc70d4ba4335aacd4f8dbf7805eee9e"},"headline":"II Mini BTT Concello de Cambados por Pirucho Pequeno","datePublished":"2015-06-07T16:29:27+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno"},"wordCount":796,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316649.jpg?fit=1008%2C756&ssl=1","articleSection":["Eventos","Fotos","LA MAFIA","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno","url":"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno","name":"II Mini BTT Concello de Cambados por Pirucho Pequeno - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316649.jpg?fit=1008%2C756&ssl=1","datePublished":"2015-06-07T16:29:27+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/2dc70d4ba4335aacd4f8dbf7805eee9e"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316649.jpg?fit=1008%2C756&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316649.jpg?fit=1008%2C756&ssl=1","width":1008,"height":756,"caption":"II Mini BTT Concello de Cambados por Pirucho Pequeno"},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/ii-mini-btt-concello-de-cambados-por-pirucho-pequeno#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"II Mini BTT Concello de Cambados por Pirucho Pequeno"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/2dc70d4ba4335aacd4f8dbf7805eee9e","name":"Pirucho Pequeno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g","caption":"Pirucho Pequeno"},"description":"Se puede decir que es una especie de \u201cgroupie de ciclistas\u201d, nunca ha competido pero le encanta el mundo del ciclismo. Sus tareas principales son avituallar y fotografiar a todo aquel que me se lo pida con una sonrisa. Sus albumes de fotos en GOOGLE+ son visitados por cientos, miles, millones de personas y hasta marcianos y derivados. Ojo que aunque la ve\u00e1is en las carreras con una mirada angelical no recoge ni chaquetillas ni termicas en la salida, lo que le da fama de mala mujer.","sameAs":["https:\/\/picasaweb.google.com\/114831358335341071162","luzmaria.iglesiasmosquera?fref=ts"],"url":"https:\/\/valwindcycles.es\/blog\/author\/pirucho-pequeno"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-1kC","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/06\/P5316649.jpg?fit=1008%2C756&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/5122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=5122"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/5122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/5124"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=5122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=5122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=5122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}