{"id":5581,"date":"2015-10-21T08:12:35","date_gmt":"2015-10-21T07:12:35","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=5581"},"modified":"2015-10-21T08:12:35","modified_gmt":"2015-10-21T07:12:35","slug":"transiciones-de-la-vida-por-almu","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu","title":{"rendered":"Transiciones de la vida por Almu"},"content":{"rendered":"<p>Hac\u00eda ya tiempo que no escrib\u00eda unas l\u00edneas, y sinceramente, aunque lo necesitaba, eran tantas las ideas y motivos que ten\u00eda para hacerlo. que esper\u00e9 a que se ordenaran un poco en la cabeza, y poco a poco surgiese un contenido con el que mereciese la pena perder dos minutos en su lectura. El fin de temporada deportiva es siempre buen momento para reflexionar, aunque yo lo hago m\u00e1s habitualmente incluso de lo necesario.<\/p>\n<p>Llevo unos meses en paro, y quiz\u00e1s ahora, curriculum va y curriculum viene, cortar y pegar, ordenar fechas, recopilar t\u00edtulos, revis\u00e9 por casualidad una vida laboral, y entonces hice memoria de todo lo que he podido experimentar desde hace ya m\u00e1s de 21 a\u00f1os&#8230;..Lo primero que vino a mi memoria fue mi primer trabajo, todav\u00eda finalizando mis estudios, con autorizaci\u00f3n paterna por ser menor de edad, y con vuelo de avi\u00f3n incluido, con viaje a la capital de Espa\u00f1a, para trabajar en una feria de turismo como azafata durante una semana, eran otros tiempos&#8230;.mi primer sueldo, mi primer viaje en avi\u00f3n, y la primera vez que me sent\u00eda una persona de provecho, qu\u00e9 ilusi\u00f3n\u00a1; todav\u00eda guardo la n\u00f3mina, las fotos, y hasta el billete de avi\u00f3n.<\/p>\n<p>Despu\u00e9s de ese minuto de recuerdos cog\u00ed un l\u00e1piz y segu\u00ed recordando los siguientes trabajos: en una conservera, en una empresa de mobiliario, en una empresa textil, en una de congelados, en una de alquiler de coches, en una de cocinas, como auxiliar de peluquer\u00eda, de dependienta en una librer\u00eda, en un taller de coches, como limpiadora, en una empresa de telecomunicaciones, en una asociaci\u00f3n de empresarios, en una empresa de automoci\u00f3n, en un almac\u00e9n agr\u00edcola, como teleoperadora y como dependienta de una tienda de deportes&#8230;&#8230; Buuff&#8230;lo primero que pens\u00e9 es que pr\u00e1cticamente, menos burbuja Freixenet en el anuncio de Navidad, hab\u00eda hecho casi de todo&#8230;.hasta pude dedicar a\u00f1o y medio a recluirme en la biblioteca y en unas pistas de atletismo para preparar unas oposiciones, en las que obviamente, tampoco la suerte estuvo de mi lado.<\/p>\n<p>Salvo dos trabajos que dej\u00e9, porque gratis y sin seguro no trabajo, el resto fue una mala racha prolongada en el tiempo, \u201csustituciones\u201d, \u201ccircunstancias de la producci\u00f3n\u201d, \u201ceres\u201d&#8230;.infinitas excusas en una infinita lista de experiencias, desde llevar la contabilidad, la log\u00edstica, las llamadas, a hacer el caf\u00e9, conducir un cami\u00f3n, una carretilla elevadora, limpiar el ba\u00f1o, destruir papel, contar dinero o hacer manicuras, hasta ser el tel\u00e9fono de la esperanza y vender seguros o doblar camisetas como sino hubiese un ma\u00f1ana.<\/p>\n<p>Entre contrato y contrato, entre experiencias, proyectos y desaf\u00edos, apareci\u00f3 el deporte en mi vida, el que m\u00e1s me ha hecho sufrir, pero el que m\u00e1s satisfacciones me ha dado, del que m\u00e1s he aprendido y al que m\u00e1s le debo, desde el globeril paseo en bicicleta hasta la carrera con m\u00e1s o menos importancia. El deporte ha sido siempre el motor de mis ilusiones, y el motivo que me ha hecho sentir en muchas ocasiones m\u00e1s \u00fatil que lo que describa mi vida laboral. Por eso, aunque a veces, o muchas veces, las cosas no salgan como uno espera, y porque el planeta sigue movi\u00e9ndose, s\u00f3lo habremos fracasado cuando no tengamos sue\u00f1os y motivaciones, mientras tanto, toca decidir a qu\u00e9 reto laboral o deportivo lanzarse, y perseguirlo, ni m\u00e1s ni menos.<\/p>\n<div id=\"attachment_5584\" style=\"width: 501px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu1.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5584\" data-attachment-id=\"5584\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu\/collagealmu1\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu1.png?fit=1900%2C1280&amp;ssl=1\" data-orig-size=\"1900,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Transiciones de la vida por Almu\" data-image-description=\"&lt;p&gt;Transiciones de la vida por Almu&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Transiciones de la vida por Almu&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu1.png?fit=700%2C471&amp;ssl=1\" class=\" wp-image-5584  \" alt=\"Transiciones de la vida por Almu\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu1.png?resize=491%2C330&#038;ssl=1\" width=\"491\" height=\"330\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu1.png?resize=1024%2C689&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu1.png?resize=300%2C202&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu1.png?w=1900&amp;ssl=1 1900w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu1.png?w=1400&amp;ssl=1 1400w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><\/a><p id=\"caption-attachment-5584\" class=\"wp-caption-text\">Transiciones de la vida por Almu<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hac\u00eda ya tiempo que no escrib\u00eda unas l\u00edneas, y sinceramente, aunque lo necesitaba, eran tantas las ideas y motivos que ten\u00eda para hacerlo. que esper\u00e9 a que se ordenaran un&hellip; <\/p>\n","protected":false},"author":65,"featured_media":5585,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[80,76],"tags":[],"class_list":["post-5581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-mafia","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transiciones de la vida por Almu - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transiciones de la vida por Almu - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"Hac\u00eda ya tiempo que no escrib\u00eda unas l\u00edneas, y sinceramente, aunque lo necesitaba, eran tantas las ideas y motivos que ten\u00eda para hacerlo. que esper\u00e9 a que se ordenaran un&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-21T07:12:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu11-1024x689.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"689\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Almu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Almu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/transiciones-de-la-vida-por-almu#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/transiciones-de-la-vida-por-almu\"},\"author\":{\"name\":\"Almu\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/081173dcdb570286f86e577c70e9822d\"},\"headline\":\"Transiciones de la vida por Almu\",\"datePublished\":\"2015-10-21T07:12:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/transiciones-de-la-vida-por-almu\"},\"wordCount\":620,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/transiciones-de-la-vida-por-almu#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/collagealmu11.png?fit=1900%2C1280&ssl=1\",\"articleSection\":[\"LA MAFIA\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/transiciones-de-la-vida-por-almu#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/transiciones-de-la-vida-por-almu\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/transiciones-de-la-vida-por-almu\",\"name\":\"Transiciones de la vida por Almu - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/transiciones-de-la-vida-por-almu#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/transiciones-de-la-vida-por-almu#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/collagealmu11.png?fit=1900%2C1280&ssl=1\",\"datePublished\":\"2015-10-21T07:12:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/081173dcdb570286f86e577c70e9822d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/transiciones-de-la-vida-por-almu#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/transiciones-de-la-vida-por-almu\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/transiciones-de-la-vida-por-almu#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/collagealmu11.png?fit=1900%2C1280&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/collagealmu11.png?fit=1900%2C1280&ssl=1\",\"width\":1900,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/transiciones-de-la-vida-por-almu#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transiciones de la vida por Almu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/081173dcdb570286f86e577c70e9822d\",\"name\":\"Almu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g\",\"caption\":\"Almu\"},\"description\":\"Como dec\u00eda hace unos d\u00edas en una de sus entradas en el blog.. el trail running es correr en la monta\u00f1a, la monta\u00f1a es libertad, naturaleza, aire puro, desconexi\u00f3n, es sentirse en afinidad y comuni\u00f3n con ese entorno natural, es avanzar sin importar el tiempo, la distancia o el ritmo, es buscar la soledad y el silencio\u2026. Es llegar a meta habiendo recorrido un camino en el que te has hecho fuerte, en el que has controlado todas las dificultades que se han presentado a lo largo de ese viaje\u2026.. Parece una filosof\u00eda de la vida no ? SweetSmile \u2026 la chica que corre\u2026 nada.. pedalea \u2026 escribe y vive la \u201cESENCIA\u201d Valwind como una autentica MafiosaValwind, la m\u00e1gica sonrisa, la runner-biker-nadadora-reportera dicharachera, energ\u00eda contagiosa en su m\u00e1ximo esplendor. El otro d\u00eda se desped\u00eda en una de sus entradas en el blog con esta sabia frase del Baron Pierre de Coubertin; \u201cEl deporte busca dominar el miedo, triunfar sobre la fatiga, vencer a la dificultad\u201d. Ella lo hace y adem\u00e1s con una m\u00e1gica sonrisa\u2026 Almu SweetSmile\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/almu\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transiciones de la vida por Almu - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu","og_locale":"es_ES","og_type":"article","og_title":"Transiciones de la vida por Almu - El Blog de ValwindCycles","og_description":"Hac\u00eda ya tiempo que no escrib\u00eda unas l\u00edneas, y sinceramente, aunque lo necesitaba, eran tantas las ideas y motivos que ten\u00eda para hacerlo. que esper\u00e9 a que se ordenaran un&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_published_time":"2015-10-21T07:12:35+00:00","og_image":[{"width":1024,"height":689,"url":"https:\/\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu11-1024x689.png","type":"image\/png"}],"author":"Almu","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Almu","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu"},"author":{"name":"Almu","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/081173dcdb570286f86e577c70e9822d"},"headline":"Transiciones de la vida por Almu","datePublished":"2015-10-21T07:12:35+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu"},"wordCount":620,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu11.png?fit=1900%2C1280&ssl=1","articleSection":["LA MAFIA","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu","url":"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu","name":"Transiciones de la vida por Almu - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu11.png?fit=1900%2C1280&ssl=1","datePublished":"2015-10-21T07:12:35+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/081173dcdb570286f86e577c70e9822d"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu11.png?fit=1900%2C1280&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu11.png?fit=1900%2C1280&ssl=1","width":1900,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/transiciones-de-la-vida-por-almu#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Transiciones de la vida por Almu"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/081173dcdb570286f86e577c70e9822d","name":"Almu","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g","caption":"Almu"},"description":"Como dec\u00eda hace unos d\u00edas en una de sus entradas en el blog.. el trail running es correr en la monta\u00f1a, la monta\u00f1a es libertad, naturaleza, aire puro, desconexi\u00f3n, es sentirse en afinidad y comuni\u00f3n con ese entorno natural, es avanzar sin importar el tiempo, la distancia o el ritmo, es buscar la soledad y el silencio\u2026. Es llegar a meta habiendo recorrido un camino en el que te has hecho fuerte, en el que has controlado todas las dificultades que se han presentado a lo largo de ese viaje\u2026.. Parece una filosof\u00eda de la vida no ? SweetSmile \u2026 la chica que corre\u2026 nada.. pedalea \u2026 escribe y vive la \u201cESENCIA\u201d Valwind como una autentica MafiosaValwind, la m\u00e1gica sonrisa, la runner-biker-nadadora-reportera dicharachera, energ\u00eda contagiosa en su m\u00e1ximo esplendor. El otro d\u00eda se desped\u00eda en una de sus entradas en el blog con esta sabia frase del Baron Pierre de Coubertin; \u201cEl deporte busca dominar el miedo, triunfar sobre la fatiga, vencer a la dificultad\u201d. Ella lo hace y adem\u00e1s con una m\u00e1gica sonrisa\u2026 Almu SweetSmile","url":"https:\/\/valwindcycles.es\/blog\/author\/almu"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-1s1","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/10\/collagealmu11.png?fit=1900%2C1280&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/5581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=5581"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/5581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/5585"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=5581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=5581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=5581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}