{"id":5687,"date":"2015-11-12T20:34:15","date_gmt":"2015-11-12T19:34:15","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=5687"},"modified":"2015-11-12T20:34:15","modified_gmt":"2015-11-12T19:34:15","slug":"sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida","title":{"rendered":"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida"},"content":{"rendered":"<p>Sonia Mac\u00edas Rom\u00e1n, te suena ? lo mas seguro es que no.. pero si te digo la Princesa del Desierto ? muchos much\u00edsimos ya la conoc\u00e9is\u2026\u00a0 es una chica de esas que conoces de \u201ccasualidad\u201d pero que siempre estar\u00e1s agradecido de que sucediera\u2026 es una chica con una esencia de la vida muy especial\u2026 con una chispa que transmite energ\u00eda a quienes la rodean en su vida y en sus aventuras, es emprendedora, ultrafondista y apasionada por las aventuras que no tengan l\u00edmites, y que desprende tanto \u201cfeeling\u201d que sientes la necesidad imperiosa de \u201ccolaborar\u201d o hacer lo m\u00e1ximo posible por aportar un granito de arena en su proyecto..<\/p>\n<div id=\"attachment_5688\" style=\"width: 440px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5688\" data-attachment-id=\"5688\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida\/collagesonia\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?fit=1900%2C1600&amp;ssl=1\" data-orig-size=\"1900,1600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"collagesonia\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?fit=700%2C589&amp;ssl=1\" class=\" wp-image-5688\" title=\"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida\" alt=\"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?resize=430%2C362&#038;ssl=1\" width=\"430\" height=\"362\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?resize=1024%2C862&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?resize=300%2C252&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?w=1900&amp;ssl=1 1900w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?w=1400&amp;ssl=1 1400w\" sizes=\"auto, (max-width: 430px) 100vw, 430px\" \/><\/a><p id=\"caption-attachment-5688\" class=\"wp-caption-text\">Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida<\/p><\/div>\n<p>Para empezar ah\u00ed va su propia definici\u00f3n:<strong><em> \u201cMe defino como una ultrafondista de la vida\u00a0porque cada d\u00eda intento vivir como si fuera la \u00faltima carrera que voy a realizar\u201d<\/em><\/strong>. Toda una declaraci\u00f3n de intenciones de esta chica que ha puesto en marcha un proyecto muy especial: <a href=\"http:\/\/www.laprincesadeldesierto.com\/\">www.laprincesadeldesierto.com<\/a>.<\/p>\n<p>Esta aventura no la har\u00e1 sola, el viajero y cineasta \u00c1lvaro Cuadrado, conocedor de la zona y n\u00f3mada de la vida con mas de 50 viajes a sus espaldas en los 5 continentes, acompa\u00f1ar\u00e1 a nuestra protagonista y contar\u00e1 su historia.<\/p>\n<p>La misi\u00f3n es poner de relieve y reivindicar la figura de la mujer en el deporte.<\/p>\n<p>Se enfrentan a uno de los mayores desaf\u00edos sobre la faz de la tierra: correr 1.000km en 20 d\u00edas por el desierto de Namibia. Todo ello se recoger\u00e1 en un documental que se emitir\u00e1 en m\u00e1s de 15 pa\u00edses, donde mostrar\u00e1n todo el esfuerzo, motivaci\u00f3n y toda su fuerza tanto f\u00edsica como mental\u2026 el mundo del \u201cultrafondo\u201d \u2026 y siguiendo siempre un lema gravado a fuego en sus mentes y en sus cuerpos\u2026 \u201csomos nuestros pasos\u201d.<\/p>\n<div id=\"attachment_5690\" style=\"width: 440px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/sonia_modelo5-1024x682.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5690\" data-attachment-id=\"5690\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida\/sonia_modelo5-1024x682\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/sonia_modelo5-1024x682.jpg?fit=1024%2C682&amp;ssl=1\" data-orig-size=\"1024,682\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"sonia_modelo5-1024&amp;#215;682\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/sonia_modelo5-1024x682.jpg?fit=700%2C466&amp;ssl=1\" class=\" wp-image-5690\" title=\"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida\" alt=\"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/sonia_modelo5-1024x682.jpg?resize=430%2C286&#038;ssl=1\" width=\"430\" height=\"286\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/sonia_modelo5-1024x682.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/sonia_modelo5-1024x682.jpg?resize=300%2C199&amp;ssl=1 300w\" sizes=\"auto, (max-width: 430px) 100vw, 430px\" \/><\/a><p id=\"caption-attachment-5690\" class=\"wp-caption-text\">Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida<\/p><\/div>\n<p>Actualmente, el proyecto de la princesadeldesierto.com est\u00e1 en fase de financiaci\u00f3n para desarrollar este emprendimiento social aplicando innovaci\u00f3n al patrocinio habitual\u2026.. para ello Sonia pone en marcha varias formas de colaboraci\u00f3n:<\/p>\n<p><strong>1.<\/strong> La pasi\u00f3n de Sonia Mac\u00edas y su formaci\u00f3n como coaching deportivo y profesora es llevada de la mano de su socio \u00c1lvaro Cuadrado a eventos en toda Espa\u00f1a, usando su experiencia vital en el deporte como met\u00e1fora de c\u00f3mo afrontar la vida, en una emotiva conferencia que no dejar\u00e1 indiferente a nadie. Si est\u00e1s interesado en contar con sus servicios como conferencista o formadora contacta con ellos.<\/p>\n<p><strong>2.<\/strong> Donaciones en una cuenta bancaria que han creado espec\u00edficamente para el Proyecto y que pod\u00e9is consultar en la secci\u00f3n espec\u00edfica de la p\u00e1gina web: <a href=\"http:\/\/www.laprincesadeldesierto.com\/reto-2015\/\">http:\/\/www.laprincesadeldesierto.com\/reto-2015\/<\/a><\/p>\n<p><strong>3.<\/strong> Adquiriendo en la tienda online alguno de los productos (camisetas, pulsera, taza, mochila): <a href=\"http:\/\/www.laprincesadeldesierto.com\/tienda\/\">http:\/\/www.laprincesadeldesierto.com\/tienda\/<\/a><\/p>\n<div id=\"attachment_5689\" style=\"width: 440px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/1966293_721636084523336_690878946_o.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5689\" data-attachment-id=\"5689\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida\/1966293_721636084523336_690878946_o\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/1966293_721636084523336_690878946_o.png?fit=1182%2C519&amp;ssl=1\" data-orig-size=\"1182,519\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"1966293_721636084523336_690878946_o\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/1966293_721636084523336_690878946_o.png?fit=700%2C307&amp;ssl=1\" class=\" wp-image-5689\" title=\"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida\" alt=\"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/1966293_721636084523336_690878946_o.png?resize=430%2C188&#038;ssl=1\" width=\"430\" height=\"188\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/1966293_721636084523336_690878946_o.png?resize=1024%2C449&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/1966293_721636084523336_690878946_o.png?resize=300%2C131&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/1966293_721636084523336_690878946_o.png?w=1182&amp;ssl=1 1182w\" sizes=\"auto, (max-width: 430px) 100vw, 430px\" \/><\/a><p id=\"caption-attachment-5689\" class=\"wp-caption-text\">Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida<\/p><\/div>\n<p>No solo ser\u00e1 un \u201creto personal\u201d ni una reivindicaci\u00f3n \u2026\u00a0 El proyecto La Princesa del Desierto Ayudar\u00e1 a las \u00e1reas locales por las que pasen con su desaf\u00edo: llevaran a la tribu de los Himba, en el norte de Namibia, comida para las familia, balones y juguetes para los ni\u00f1os. Por cada kil\u00f3metro del desaf\u00edo formaran a un ni\u00f1o hasta un total de 1.000 en 6 colegios perif\u00e9ricos, transmitiendo el mensaje de superaci\u00f3n y de vida saludable e impartiran m\u00e1s de 12 conferencias nacionales e internacionales en zonas desfavorecidas para transmitir el mensaje de superaci\u00f3n: Espa\u00f1a, Colombia, Paraguay y Guatemala.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/119629828\" width=\"700\" height=\"394\" frameborder=\"0\" title=\"Teaser: &quot;La princesa del desierto&quot;\" webkitallowfullscreen mozallowfullscreen allowfullscreen><\/iframe><\/p>\n<p>Esto es solo un 1% de todo lo que puedes leer sobre el proyecto en su web\u2026 te invito a informarte sobre ello y por supuesto a colaborar\u2026. yo lo voy para empezar con una camiseta y una taza muy guapas y tu ?<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sonia Mac\u00edas Rom\u00e1n, te suena ? lo mas seguro es que no.. pero si te digo la Princesa del Desierto ? muchos much\u00edsimos ya la conoc\u00e9is\u2026\u00a0 es una chica de&hellip; <\/p>\n","protected":false},"author":2,"featured_media":5688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[80,76],"tags":[],"class_list":["post-5687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-mafia","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"Sonia Mac\u00edas Rom\u00e1n, te suena ? lo mas seguro es que no.. pero si te digo la Princesa del Desierto ? muchos much\u00edsimos ya la conoc\u00e9is\u2026\u00a0 es una chica de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"ValwindCycles\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-12T19:34:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?fit=1900%2C1600&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jorge ValwindCycles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge ValwindCycles\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida\"},\"author\":{\"name\":\"Jorge ValwindCycles\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"headline\":\"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida\",\"datePublished\":\"2015-11-12T19:34:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida\"},\"wordCount\":695,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/collagesonia.png?fit=1900%2C1600&ssl=1\",\"articleSection\":[\"LA MAFIA\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida\",\"name\":\"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/collagesonia.png?fit=1900%2C1600&ssl=1\",\"datePublished\":\"2015-11-12T19:34:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/collagesonia.png?fit=1900%2C1600&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/collagesonia.png?fit=1900%2C1600&ssl=1\",\"width\":1900,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\",\"name\":\"Jorge ValwindCycles\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"caption\":\"Jorge ValwindCycles\"},\"description\":\"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.\",\"sameAs\":[\"http:\\\/\\\/www.valwindcycles.es\",\"ValwindCycles\",\"http:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=180972148&trk=nav_responsive_tab_profile\",\"http:\\\/\\\/www.pinterest.com\\\/valwindcycles\\\/\",\"https:\\\/\\\/x.com\\\/JorgeValwind\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/Valwindcycles\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/valwind\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida","og_locale":"es_ES","og_type":"article","og_title":"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida - El Blog de ValwindCycles","og_description":"Sonia Mac\u00edas Rom\u00e1n, te suena ? lo mas seguro es que no.. pero si te digo la Princesa del Desierto ? muchos much\u00edsimos ya la conoc\u00e9is\u2026\u00a0 es una chica de&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"ValwindCycles","article_published_time":"2015-11-12T19:34:15+00:00","og_image":[{"width":1900,"height":1600,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?fit=1900%2C1600&ssl=1","type":"image\/png"}],"author":"Jorge ValwindCycles","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Jorge ValwindCycles","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida"},"author":{"name":"Jorge ValwindCycles","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"headline":"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida","datePublished":"2015-11-12T19:34:15+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida"},"wordCount":695,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?fit=1900%2C1600&ssl=1","articleSection":["LA MAFIA","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida","url":"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida","name":"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?fit=1900%2C1600&ssl=1","datePublished":"2015-11-12T19:34:15+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?fit=1900%2C1600&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?fit=1900%2C1600&ssl=1","width":1900,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/sonia-macias-la-princesa-del-desierto-un-proyecto-con-esencia-de-vida#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Sonia Mac\u00edas, La Princesa del Desierto, un proyecto con esencia de vida"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3","name":"Jorge ValwindCycles","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","caption":"Jorge ValwindCycles"},"description":"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.","sameAs":["http:\/\/www.valwindcycles.es","ValwindCycles","http:\/\/www.linkedin.com\/profile\/view?id=180972148&trk=nav_responsive_tab_profile","http:\/\/www.pinterest.com\/valwindcycles\/","https:\/\/x.com\/JorgeValwind","http:\/\/www.youtube.com\/user\/Valwindcycles"],"url":"https:\/\/valwindcycles.es\/blog\/author\/valwind"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-1tJ","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2015\/11\/collagesonia.png?fit=1900%2C1600&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/5687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=5687"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/5687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/5688"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=5687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=5687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=5687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}