{"id":6735,"date":"2016-10-24T13:50:35","date_gmt":"2016-10-24T12:50:35","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=6735"},"modified":"2016-10-24T13:50:38","modified_gmt":"2016-10-24T12:50:38","slug":"triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo","title":{"rendered":"Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes &#8211; 24 Septiembre Fotos IL Capo"},"content":{"rendered":"<p>Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes &#8211; 24 Septiembre<br \/>\n<a href=\"http:\/\/www.valwindcycles.es\/\" target=\"_blank\" rel=\"nofollow nofollow\">www.Valwindcycles.es<\/a><br \/>\n<a href=\"http:\/\/www.valwindcycles.es\/blog\" target=\"_blank\" rel=\"nofollow nofollow\">www.Valwindcycles.es\/blog<\/a><br \/>\n@desafio.cies<\/p>\n<p>Una mini selecci\u00f3n de las fotos que saque en el Desaf\u00edo<\/p>\n<p>Puedes ver todas directamente los \u00e1lbumes de\u00a0Google+<\/p>\n<p>Triatlon Medio IronMan Desaf\u00edo Pastor Islas Cies\u00a0 <a href=\"https:\/\/goo.gl\/photos\/fF5K1J6dv1Hcf9sB7\" target=\"_blank\">ALBUM 1<\/a><\/p>\n<p>Triatlon Medio IronMan Desaf\u00edo Pastor Islas Cies\u00a0 <a href=\"https:\/\/goo.gl\/photos\/HmmNRxjjXy8YGorx6\" target=\"_blank\">ALBUM 2<\/a><\/p>\n<p>COMPARTIR lo que os apetezca\u00a0<i>\ud83d\ude42<\/i><\/p>\n<p>pd. una vez en GOOGLE+ aprovechar el bot\u00f3n de descarga que tiene cada foto y no haciendo una captura de pantalla o similar ya que as\u00ed pierden mucha calidad, de todas formas est\u00e1 reducidas para facilitar su subida y para \u201cahorrar\u201d espacio en mi cuenta Google !!!! si la quieres sin reducir a escribirme un mail a info@valwindcycles.es o directamente por\u00a0<a href=\"https:\/\/www.facebook.com\/ValwindCycles\" target=\"_blank\">facebook<\/a>\u00a0<i>\ud83d\ude42<\/i><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-2\" rel=\"attachment wp-att-6736\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6736\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-2\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6736\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-2\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-69\" rel=\"attachment wp-att-6737\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6737\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-69\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-69.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-69\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-69.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6737\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-69.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-69\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-69.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-69.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-69.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-69.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-69.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-210\" rel=\"attachment wp-att-6738\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6738\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-210\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-210.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-210\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-210.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6738\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-210.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-210\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-210.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-210.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-210.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-210.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-210.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-230\" rel=\"attachment wp-att-6739\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6739\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-230\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-230.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-230\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-230.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6739\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-230.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-230\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-230.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-230.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-230.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-230.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-230.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-259\" rel=\"attachment wp-att-6740\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6740\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-259\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-259.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-259\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-259.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6740\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-259.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-259\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-259.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-259.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-259.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-259.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-259.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-324\" rel=\"attachment wp-att-6742\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6742\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-324\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-324.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-324\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-324.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6742\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-324.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-324\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-324.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-324.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-324.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-324.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-324.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-354\" rel=\"attachment wp-att-6743\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6743\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-354\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-354.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-354\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-354.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6743\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-354.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-354\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-354.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-354.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-354.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-354.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-354.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-372\" rel=\"attachment wp-att-6744\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6744\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-372\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-372.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-372\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-372.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6744\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-372.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-372\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-372.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-372.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-372.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-372.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-372.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-405\" rel=\"attachment wp-att-6745\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6745\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-405\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-405.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-405\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-405.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6745\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-405.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-405\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-405.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-405.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-405.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-405.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-405.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-410\" rel=\"attachment wp-att-6746\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6746\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-410\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-410.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-410\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-410.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6746\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-410.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-410\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-410.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-410.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-410.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-410.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-410.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-689\" rel=\"attachment wp-att-6747\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6747\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-689\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-689.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-689\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-689.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6747\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-689.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-689\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-689.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-689.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-689.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-689.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-689.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-718\" rel=\"attachment wp-att-6748\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6748\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-718\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-718.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-718\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-718.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6748\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-718.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-718\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-718.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-718.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-718.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-718.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-718.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-741\" rel=\"attachment wp-att-6749\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6749\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-741\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-741.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-741\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-741.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6749\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-741.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-741\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-741.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-741.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-741.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-741.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-741.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-748\" rel=\"attachment wp-att-6750\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6750\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-748\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-748.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-748\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-748.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6750\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-748.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-748\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-748.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-748.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-748.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-748.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-748.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-787\" rel=\"attachment wp-att-6751\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6751\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-787\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-787.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-787\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-787.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6751\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-787.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-787\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-787.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-787.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-787.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-787.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-787.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-859\" rel=\"attachment wp-att-6752\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6752\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-859\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-859.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-859\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-859.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6752\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-859.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-859\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-859.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-859.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-859.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-859.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-859.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-860\" rel=\"attachment wp-att-6753\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6753\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-860\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-860.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-860\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-860.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6753\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-860.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-860\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-860.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-860.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-860.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-860.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-860.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-889\" rel=\"attachment wp-att-6754\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6754\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-889\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-889.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-889\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-889.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6754\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-889.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-889\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-889.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-889.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-889.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-889.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-889.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-928\" rel=\"attachment wp-att-6755\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6755\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-928\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-928.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-928\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-928.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6755\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-928.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-928\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-928.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-928.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-928.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-928.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-928.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-938\" rel=\"attachment wp-att-6756\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6756\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-938\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-938.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-938\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-938.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6756\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-938.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-938\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-938.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-938.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-938.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-938.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-938.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-942\" rel=\"attachment wp-att-6757\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6757\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-942\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-942.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-942\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-942.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6757\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-942.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-942\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-942.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-942.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-942.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-942.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-942.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-970\" rel=\"attachment wp-att-6758\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6758\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-970\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-970.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-970\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-970.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6758\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-970.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-970\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-970.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-970.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-970.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-970.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-970.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1054\" rel=\"attachment wp-att-6759\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6759\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1054\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1054.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-1054\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1054.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6759\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1054.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-1054\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1054.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1054.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1054.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1054.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1054.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1062\" rel=\"attachment wp-att-6760\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6760\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1062\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1062.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-1062\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1062.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6760\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1062.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-1062\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1062.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1062.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1062.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1062.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1062.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1096\" rel=\"attachment wp-att-6761\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6761\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1096\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1096.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-1096\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1096.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6761\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1096.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-1096\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1096.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1096.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1096.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1096.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1096.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1112\" rel=\"attachment wp-att-6762\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6762\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1112\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1112.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-1112\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1112.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6762\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1112.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-1112\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1112.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1112.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1112.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1112.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1112.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1296\" rel=\"attachment wp-att-6763\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6763\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1296\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1296.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-1296\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1296.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6763\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1296.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-1296\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1296.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1296.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1296.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1296.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1296.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1449\" rel=\"attachment wp-att-6765\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6765\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1449\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1449.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-1449\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1449.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6765\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1449.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-1449\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1449.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1449.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1449.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1449.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1449.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1496\" rel=\"attachment wp-att-6766\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6766\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1496\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1496.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-1496\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1496.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6766\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1496.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-1496\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1496.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1496.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1496.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1496.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1496.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1503\" rel=\"attachment wp-att-6767\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6767\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1503\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1503.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-1503\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1503.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6767\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1503.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-1503\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1503.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1503.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1503.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1503.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1503.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1653-1\" rel=\"attachment wp-att-6768\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6768\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1653-1\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1653-1.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-1653-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1653-1.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6768\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1653-1.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-1653-1\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1653-1.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1653-1.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1653-1.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1653-1.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1653-1.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1834\" rel=\"attachment wp-att-6769\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6769\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1834\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1834.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-1834\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1834.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6769\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1834.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-1834\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1834.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1834.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1834.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1834.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1834.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1934\" rel=\"attachment wp-att-6770\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6770\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-1934\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1934.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-1934\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1934.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6770\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1934.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-1934\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1934.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1934.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1934.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1934.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-1934.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-2113\" rel=\"attachment wp-att-6772\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6772\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-2113\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2113.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-2113\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2113.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6772\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2113.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-2113\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2113.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2113.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2113.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2113.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2113.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-2161\" rel=\"attachment wp-att-6773\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6773\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-2161\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2161.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-2161\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2161.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6773\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2161.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-2161\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2161.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2161.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2161.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2161.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2161.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-2254\" rel=\"attachment wp-att-6775\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6775\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\/1ok-2254\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?fit=3686%2C2448&amp;ssl=1\" data-orig-size=\"3686,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1ok-2254\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-6775\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?resize=700%2C465&#038;ssl=1\" alt=\"1ok-2254\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes &#8211; 24 Septiembre www.Valwindcycles.es www.Valwindcycles.es\/blog @desafio.cies Una mini selecci\u00f3n de las fotos que saque en el Desaf\u00edo Puedes ver todas directamente los \u00e1lbumes&hellip; <\/p>\n","protected":false},"author":2,"featured_media":6775,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[72,71,80,76],"tags":[],"class_list":["post-6735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-fotos","category-la-mafia","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes - 24 Septiembre Fotos IL Capo - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes - 24 Septiembre Fotos IL Capo - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes &#8211; 24 Septiembre www.Valwindcycles.es www.Valwindcycles.es\/blog @desafio.cies Una mini selecci\u00f3n de las fotos que saque en el Desaf\u00edo Puedes ver todas directamente los \u00e1lbumes&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"ValwindCycles\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-24T12:50:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-24T12:50:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?fit=3686%2C2448&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"3686\" \/>\n\t<meta property=\"og:image:height\" content=\"2448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge ValwindCycles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge ValwindCycles\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\"},\"author\":{\"name\":\"Jorge ValwindCycles\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"headline\":\"Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes &#8211; 24 Septiembre Fotos IL Capo\",\"datePublished\":\"2016-10-24T12:50:35+00:00\",\"dateModified\":\"2016-10-24T12:50:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\"},\"wordCount\":179,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/1ok-2254.jpg?fit=3686%2C2448&ssl=1\",\"articleSection\":[\"Eventos\",\"Fotos\",\"LA MAFIA\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\",\"name\":\"Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes - 24 Septiembre Fotos IL Capo - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/1ok-2254.jpg?fit=3686%2C2448&ssl=1\",\"datePublished\":\"2016-10-24T12:50:35+00:00\",\"dateModified\":\"2016-10-24T12:50:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/1ok-2254.jpg?fit=3686%2C2448&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/1ok-2254.jpg?fit=3686%2C2448&ssl=1\",\"width\":3686,\"height\":2448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes &#8211; 24 Septiembre Fotos IL Capo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\",\"name\":\"Jorge ValwindCycles\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"caption\":\"Jorge ValwindCycles\"},\"description\":\"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.\",\"sameAs\":[\"http:\\\/\\\/www.valwindcycles.es\",\"ValwindCycles\",\"http:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=180972148&trk=nav_responsive_tab_profile\",\"http:\\\/\\\/www.pinterest.com\\\/valwindcycles\\\/\",\"https:\\\/\\\/x.com\\\/JorgeValwind\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/Valwindcycles\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/valwind\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes - 24 Septiembre Fotos IL Capo - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo","og_locale":"es_ES","og_type":"article","og_title":"Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes - 24 Septiembre Fotos IL Capo - El Blog de ValwindCycles","og_description":"Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes &#8211; 24 Septiembre www.Valwindcycles.es www.Valwindcycles.es\/blog @desafio.cies Una mini selecci\u00f3n de las fotos que saque en el Desaf\u00edo Puedes ver todas directamente los \u00e1lbumes&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"ValwindCycles","article_published_time":"2016-10-24T12:50:35+00:00","article_modified_time":"2016-10-24T12:50:38+00:00","og_image":[{"width":3686,"height":2448,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?fit=3686%2C2448&ssl=1","type":"image\/jpeg"}],"author":"Jorge ValwindCycles","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Jorge ValwindCycles","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo"},"author":{"name":"Jorge ValwindCycles","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"headline":"Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes &#8211; 24 Septiembre Fotos IL Capo","datePublished":"2016-10-24T12:50:35+00:00","dateModified":"2016-10-24T12:50:38+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo"},"wordCount":179,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?fit=3686%2C2448&ssl=1","articleSection":["Eventos","Fotos","LA MAFIA","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo","url":"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo","name":"Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes - 24 Septiembre Fotos IL Capo - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?fit=3686%2C2448&ssl=1","datePublished":"2016-10-24T12:50:35+00:00","dateModified":"2016-10-24T12:50:38+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?fit=3686%2C2448&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?fit=3686%2C2448&ssl=1","width":3686,"height":2448},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/triatlon-medio-ironman-desafio-pastor-islas-cies-24-septiembre-fotos-il-capo#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Triatlon Medio IronMan Desaf\u00edo Pastor Islas C\u00edes &#8211; 24 Septiembre Fotos IL Capo"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3","name":"Jorge ValwindCycles","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","caption":"Jorge ValwindCycles"},"description":"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.","sameAs":["http:\/\/www.valwindcycles.es","ValwindCycles","http:\/\/www.linkedin.com\/profile\/view?id=180972148&trk=nav_responsive_tab_profile","http:\/\/www.pinterest.com\/valwindcycles\/","https:\/\/x.com\/JorgeValwind","http:\/\/www.youtube.com\/user\/Valwindcycles"],"url":"https:\/\/valwindcycles.es\/blog\/author\/valwind"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-1KD","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2016\/10\/1ok-2254.jpg?fit=3686%2C2448&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/6735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=6735"}],"version-history":[{"count":3,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/6735\/revisions"}],"predecessor-version":[{"id":6778,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/6735\/revisions\/6778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/6775"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=6735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=6735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=6735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}