{"id":7246,"date":"2017-05-31T14:26:23","date_gmt":"2017-05-31T13:26:23","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=7246"},"modified":"2017-05-31T14:28:19","modified_gmt":"2017-05-31T13:28:19","slug":"ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo","title":{"rendered":"Ultra Trail Aldeas do Courel 2017 &#8211; Alto de Penaboa Fotos IL Capo"},"content":{"rendered":"<p>Algunas de las fotos del\u00a0 Ultra Trail Aldeas do Courel 2017 &#8211; \u00a0Alto de Penaboa<br \/>\nTodas en el alb\u00fam de <a href=\"https:\/\/goo.gl\/photos\/r6581YPRUGwDzjbd8\">Google<\/a><br \/>\n<a href=\"http:\/\/www.valwindcycles.es\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">www.Valwindcycles.es<\/a><span class=\"text_exposed_show\"><br \/>\n<a href=\"http:\/\/www.valwindcycles.es\/blog\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">www.Valwindcycles.es\/blog<\/a><br \/>\nCOMPARTIR \u00a0lo que os apetezca !!!<\/span><\/p>\n<p><span class=\"text_exposed_show\"><br \/>\npd. una vez en GOOGLE+ aprovechar el bot\u00f3n de descarga que tiene cada foto y no haciendo una captura de pantalla o similar ya que as\u00ed pierden mucha calidad, de todas formas est\u00e1n reducidas para facilitar su subida y para \u201cahorrar\u201d espacio en mi cuenta Google !!!! si la quieres sin reducir a escribirme un mail a info@valwindcycles.es o directamente por aqu\u00ed o por facebook.<\/span><\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-1-imp\" rel=\"attachment wp-att-7247\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7247\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-1-imp\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-1-imp.jpg?fit=3056%2C1349&amp;ssl=1\" data-orig-size=\"3056,1349\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 6&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1495888312&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.15&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.00042992261392949&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1 &amp;#8211; 1-imp\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-1-imp.jpg?fit=700%2C309&amp;ssl=1\" class=\"aligncenter wp-image-7247\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-1-imp.jpg?resize=700%2C309&#038;ssl=1\" alt=\"\" width=\"700\" height=\"309\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-1-imp.jpg?resize=1024%2C452&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-1-imp.jpg?resize=300%2C132&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-1-imp.jpg?resize=768%2C339&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-1-imp.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-1-imp.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-40-imp\" rel=\"attachment wp-att-7248\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7248\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-40-imp\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-40-imp.jpg?fit=2144%2C1131&amp;ssl=1\" data-orig-size=\"2144,1131\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D90&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1495899614&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;280&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1 &amp;#8211; 40-imp\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-40-imp.jpg?fit=700%2C369&amp;ssl=1\" class=\"aligncenter wp-image-7248\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-40-imp.jpg?resize=700%2C369&#038;ssl=1\" alt=\"\" width=\"700\" height=\"369\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-40-imp.jpg?resize=1024%2C540&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-40-imp.jpg?resize=300%2C158&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-40-imp.jpg?resize=768%2C405&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-40-imp.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-40-imp.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-47-imp\" rel=\"attachment wp-att-7249\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7249\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-47-imp\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-47-imp.jpg?fit=2144%2C1164&amp;ssl=1\" data-orig-size=\"2144,1164\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D90&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1495899776&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;116&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1 &amp;#8211; 47-imp\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-47-imp.jpg?fit=700%2C380&amp;ssl=1\" class=\"aligncenter wp-image-7249\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-47-imp.jpg?resize=700%2C380&#038;ssl=1\" alt=\"\" width=\"700\" height=\"380\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-47-imp.jpg?resize=1024%2C556&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-47-imp.jpg?resize=300%2C163&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-47-imp.jpg?resize=768%2C417&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-47-imp.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-47-imp.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-80-imp\" rel=\"attachment wp-att-7250\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7250\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-80-imp\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-80-imp.jpg?fit=2144%2C1233&amp;ssl=1\" data-orig-size=\"2144,1233\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.3&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D90&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1495902751&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;220&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1 &amp;#8211; 80-imp\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-80-imp.jpg?fit=700%2C403&amp;ssl=1\" class=\"aligncenter wp-image-7250\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-80-imp.jpg?resize=700%2C403&#038;ssl=1\" alt=\"\" width=\"700\" height=\"403\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-80-imp.jpg?resize=1024%2C589&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-80-imp.jpg?resize=300%2C173&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-80-imp.jpg?resize=768%2C442&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-80-imp.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-80-imp.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-113-imp\" rel=\"attachment wp-att-7251\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7251\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-113-imp\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-113-imp.jpg?fit=1570%2C1256&amp;ssl=1\" data-orig-size=\"1570,1256\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D90&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1495903442&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;92&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1 &amp;#8211; 113-imp\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-113-imp.jpg?fit=700%2C560&amp;ssl=1\" class=\"aligncenter wp-image-7251\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-113-imp.jpg?resize=700%2C560&#038;ssl=1\" alt=\"\" width=\"700\" height=\"560\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-113-imp.jpg?resize=1024%2C819&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-113-imp.jpg?resize=300%2C240&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-113-imp.jpg?resize=768%2C614&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-113-imp.jpg?w=1570&amp;ssl=1 1570w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-113-imp.jpg?w=1400&amp;ssl=1 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-124-imp\" rel=\"attachment wp-att-7252\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7252\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-124-imp\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-124-imp.jpg?fit=2144%2C1159&amp;ssl=1\" data-orig-size=\"2144,1159\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D90&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1495903544&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;116&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1 &amp;#8211; 124-imp\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-124-imp.jpg?fit=700%2C379&amp;ssl=1\" class=\"aligncenter wp-image-7252\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-124-imp.jpg?resize=700%2C379&#038;ssl=1\" alt=\"\" width=\"700\" height=\"379\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-124-imp.jpg?resize=1024%2C554&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-124-imp.jpg?resize=300%2C162&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-124-imp.jpg?resize=768%2C415&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-124-imp.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-124-imp.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-189-imp\" rel=\"attachment wp-att-7254\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7254\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-189-imp\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-189-imp.jpg?fit=2144%2C1424&amp;ssl=1\" data-orig-size=\"2144,1424\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D90&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1495907578&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;130&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1 &amp;#8211; 189-imp\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-189-imp.jpg?fit=700%2C465&amp;ssl=1\" class=\"aligncenter wp-image-7254\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-189-imp.jpg?resize=700%2C465&#038;ssl=1\" alt=\"\" width=\"700\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-189-imp.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-189-imp.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-189-imp.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-189-imp.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-189-imp.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-194-imp\" rel=\"attachment wp-att-7255\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7255\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-194-imp\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-194-imp.jpg?fit=2144%2C1061&amp;ssl=1\" data-orig-size=\"2144,1061\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D90&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1495909460&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;100&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1 &amp;#8211; 194-imp\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-194-imp.jpg?fit=700%2C347&amp;ssl=1\" class=\"aligncenter wp-image-7255\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-194-imp.jpg?resize=700%2C346&#038;ssl=1\" alt=\"\" width=\"700\" height=\"346\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-194-imp.jpg?resize=1024%2C507&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-194-imp.jpg?resize=300%2C148&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-194-imp.jpg?resize=768%2C380&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-194-imp.jpg?w=1400&amp;ssl=1 1400w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-194-imp.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-198-imp\" rel=\"attachment wp-att-7256\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7256\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-198-imp\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-198-imp.jpg?fit=1708%2C1180&amp;ssl=1\" data-orig-size=\"1708,1180\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D90&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1495909568&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;86&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1 &amp;#8211; 198-imp\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-198-imp.jpg?fit=700%2C483&amp;ssl=1\" class=\"aligncenter wp-image-7256\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-198-imp.jpg?resize=700%2C484&#038;ssl=1\" alt=\"\" width=\"700\" height=\"484\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-198-imp.jpg?resize=1024%2C707&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-198-imp.jpg?resize=300%2C207&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-198-imp.jpg?resize=768%2C531&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-198-imp.jpg?w=1708&amp;ssl=1 1708w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-198-imp.jpg?w=1400&amp;ssl=1 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-239-imp\" rel=\"attachment wp-att-7257\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7257\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-239-imp\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-239-imp.jpg?fit=2096%2C1023&amp;ssl=1\" data-orig-size=\"2096,1023\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D90&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1495914024&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;120&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1 &amp;#8211; 239-imp\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-239-imp.jpg?fit=700%2C342&amp;ssl=1\" class=\"aligncenter wp-image-7257\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-239-imp.jpg?resize=700%2C341&#038;ssl=1\" alt=\"\" width=\"700\" height=\"341\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-239-imp.jpg?resize=1024%2C500&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-239-imp.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-239-imp.jpg?resize=768%2C375&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-239-imp.jpg?w=1400&amp;ssl=1 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-252-imp\" rel=\"attachment wp-att-7258\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7258\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-252-imp\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-252-imp.jpg?fit=1943%2C1250&amp;ssl=1\" data-orig-size=\"1943,1250\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D90&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1495914524&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;55&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1 &amp;#8211; 252-imp\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-252-imp.jpg?fit=700%2C450&amp;ssl=1\" class=\"aligncenter wp-image-7258\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-252-imp.jpg?resize=700%2C450&#038;ssl=1\" alt=\"\" width=\"700\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-252-imp.jpg?resize=1024%2C659&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-252-imp.jpg?resize=300%2C193&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-252-imp.jpg?resize=768%2C494&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-252-imp.jpg?w=1943&amp;ssl=1 1943w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-252-imp.jpg?w=1400&amp;ssl=1 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-254-imp\" rel=\"attachment wp-att-7259\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7259\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-254-imp\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?fit=1942%2C1258&amp;ssl=1\" data-orig-size=\"1942,1258\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.3&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D90&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1495914738&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;240&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1 &amp;#8211; 254-imp\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?fit=700%2C453&amp;ssl=1\" class=\"aligncenter wp-image-7259\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?resize=700%2C453&#038;ssl=1\" alt=\"\" width=\"700\" height=\"453\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?resize=1024%2C663&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?resize=300%2C194&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?resize=768%2C497&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?w=1942&amp;ssl=1 1942w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?w=1400&amp;ssl=1 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-163-imp\" rel=\"attachment wp-att-7253\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7253\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\/1-163-imp\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-163-imp.jpg?fit=749%2C241&amp;ssl=1\" data-orig-size=\"749,241\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D90&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1495905320&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;86&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1 &amp;#8211; 163-imp\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-163-imp.jpg?fit=700%2C225&amp;ssl=1\" class=\"aligncenter wp-image-7253\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-163-imp.jpg?resize=700%2C226&#038;ssl=1\" alt=\"\" width=\"700\" height=\"226\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-163-imp.jpg?w=749&amp;ssl=1 749w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-163-imp.jpg?resize=300%2C97&amp;ssl=1 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Algunas de las fotos del\u00a0 Ultra Trail Aldeas do Courel 2017 &#8211; \u00a0Alto de Penaboa Todas en el alb\u00fam de Google www.Valwindcycles.es www.Valwindcycles.es\/blog COMPARTIR \u00a0lo que os apetezca !!! pd.&hellip; <\/p>\n","protected":false},"author":2,"featured_media":7259,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[71,80,76,1],"tags":[1041,1040,1039],"class_list":["post-7246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotos","category-la-mafia","category-noticias","category-sin-categoria","tag-penaboa","tag-ultra-trail-aldeas-courel","tag-utac"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ultra Trail Aldeas do Courel 2017 - Alto de Penaboa Fotos IL Capo - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ultra Trail Aldeas do Courel 2017 - Alto de Penaboa Fotos IL Capo - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"Algunas de las fotos del\u00a0 Ultra Trail Aldeas do Courel 2017 &#8211; \u00a0Alto de Penaboa Todas en el alb\u00fam de Google www.Valwindcycles.es www.Valwindcycles.es\/blog COMPARTIR \u00a0lo que os apetezca !!! pd.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"ValwindCycles\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-31T13:26:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-31T13:28:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?fit=1942%2C1258&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1942\" \/>\n\t<meta property=\"og:image:height\" content=\"1258\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge ValwindCycles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge ValwindCycles\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\"},\"author\":{\"name\":\"Jorge ValwindCycles\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"headline\":\"Ultra Trail Aldeas do Courel 2017 &#8211; Alto de Penaboa Fotos IL Capo\",\"datePublished\":\"2017-05-31T13:26:23+00:00\",\"dateModified\":\"2017-05-31T13:28:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\"},\"wordCount\":128,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/1-254-imp.jpg?fit=1942%2C1258&ssl=1\",\"keywords\":[\"Penaboa\",\"Ultra Trail Aldeas Courel\",\"UTAC\"],\"articleSection\":[\"Fotos\",\"LA MAFIA\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\",\"name\":\"Ultra Trail Aldeas do Courel 2017 - Alto de Penaboa Fotos IL Capo - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/1-254-imp.jpg?fit=1942%2C1258&ssl=1\",\"datePublished\":\"2017-05-31T13:26:23+00:00\",\"dateModified\":\"2017-05-31T13:28:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/1-254-imp.jpg?fit=1942%2C1258&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/1-254-imp.jpg?fit=1942%2C1258&ssl=1\",\"width\":1942,\"height\":1258},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ultra Trail Aldeas do Courel 2017 &#8211; Alto de Penaboa Fotos IL Capo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\",\"name\":\"Jorge ValwindCycles\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"caption\":\"Jorge ValwindCycles\"},\"description\":\"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.\",\"sameAs\":[\"http:\\\/\\\/www.valwindcycles.es\",\"ValwindCycles\",\"http:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=180972148&trk=nav_responsive_tab_profile\",\"http:\\\/\\\/www.pinterest.com\\\/valwindcycles\\\/\",\"https:\\\/\\\/x.com\\\/JorgeValwind\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/Valwindcycles\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/valwind\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ultra Trail Aldeas do Courel 2017 - Alto de Penaboa Fotos IL Capo - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo","og_locale":"es_ES","og_type":"article","og_title":"Ultra Trail Aldeas do Courel 2017 - Alto de Penaboa Fotos IL Capo - El Blog de ValwindCycles","og_description":"Algunas de las fotos del\u00a0 Ultra Trail Aldeas do Courel 2017 &#8211; \u00a0Alto de Penaboa Todas en el alb\u00fam de Google www.Valwindcycles.es www.Valwindcycles.es\/blog COMPARTIR \u00a0lo que os apetezca !!! pd.&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"ValwindCycles","article_published_time":"2017-05-31T13:26:23+00:00","article_modified_time":"2017-05-31T13:28:19+00:00","og_image":[{"width":1942,"height":1258,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?fit=1942%2C1258&ssl=1","type":"image\/jpeg"}],"author":"Jorge ValwindCycles","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Jorge ValwindCycles","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo"},"author":{"name":"Jorge ValwindCycles","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"headline":"Ultra Trail Aldeas do Courel 2017 &#8211; Alto de Penaboa Fotos IL Capo","datePublished":"2017-05-31T13:26:23+00:00","dateModified":"2017-05-31T13:28:19+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo"},"wordCount":128,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?fit=1942%2C1258&ssl=1","keywords":["Penaboa","Ultra Trail Aldeas Courel","UTAC"],"articleSection":["Fotos","LA MAFIA","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo","url":"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo","name":"Ultra Trail Aldeas do Courel 2017 - Alto de Penaboa Fotos IL Capo - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?fit=1942%2C1258&ssl=1","datePublished":"2017-05-31T13:26:23+00:00","dateModified":"2017-05-31T13:28:19+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?fit=1942%2C1258&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?fit=1942%2C1258&ssl=1","width":1942,"height":1258},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/ultra-trail-aldeas-do-courel-2017-alto-penaboa-fotos-il-capo#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Ultra Trail Aldeas do Courel 2017 &#8211; Alto de Penaboa Fotos IL Capo"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3","name":"Jorge ValwindCycles","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","caption":"Jorge ValwindCycles"},"description":"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.","sameAs":["http:\/\/www.valwindcycles.es","ValwindCycles","http:\/\/www.linkedin.com\/profile\/view?id=180972148&trk=nav_responsive_tab_profile","http:\/\/www.pinterest.com\/valwindcycles\/","https:\/\/x.com\/JorgeValwind","http:\/\/www.youtube.com\/user\/Valwindcycles"],"url":"https:\/\/valwindcycles.es\/blog\/author\/valwind"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-1SS","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2017\/05\/1-254-imp.jpg?fit=1942%2C1258&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/7246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=7246"}],"version-history":[{"count":3,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/7246\/revisions"}],"predecessor-version":[{"id":7262,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/7246\/revisions\/7262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/7259"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=7246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=7246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=7246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}