{"id":79,"date":"2010-12-31T18:17:00","date_gmt":"2010-12-31T18:17:00","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=79"},"modified":"2010-12-31T18:17:00","modified_gmt":"2010-12-31T18:17:00","slug":"feliz-2011","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/feliz-2011","title":{"rendered":"FELIZ 2011"},"content":{"rendered":"<div class=\"separator\" style=\"clear: both; text-align: center;\"><a href=\"https:\/\/i0.wp.com\/1.bp.blogspot.com\/_4Vs_a38m158\/TR4d7Fctn4I\/AAAAAAAACO4\/xhDPFhvMFTI\/s1600\/DSC06429.JPG\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"480\" n4=\"true\" src=\"https:\/\/i0.wp.com\/1.bp.blogspot.com\/_4Vs_a38m158\/TR4d7Fctn4I\/AAAAAAAACO4\/xhDPFhvMFTI\/s640\/DSC06429.JPG?resize=640%2C480\" width=\"640\" \/><\/a><\/div>\n<p>31 Diciembre 2010&#8230; 3..2..1&#8230;.largate 2010&#8230;&#8230;y bienvenido 2011&#8230;..<\/p>\n<p>Estos dias suelen ser los de los propositos para el nuevo a\u00f1o y por no faltar a la tradicion:<\/p>\n<p>Quiero ver siempre el vaso medio lleno <\/p>\n<p>No me conformo con menos\u2026 <\/p>\n<p>No quiero m\u00e1s palabras de piedra <\/p>\n<p>No mas caricias vac\u00edas\u2026 <\/p>\n<p>No quiero m\u00e1s espacios ni saltos de p\u00e1gina que me separen de lo que busco en mi vida&#8230;.seguir siendo feliz&#8230;.<\/p>\n<p>No quiero m\u00e1s ausencias ni mas olvidos\u2026quiero medir el tiempo con los dedos de mis manos&#8230;.vivir cada segundo de locura como si fuera el \u00faltimo&#8230;&#8230; sin pensar en el futuro y menos en el pasado. <\/p>\n<p>Saborear todo lo que me den estos 365 dias&#8230;..despacio\u2026 muy despacio y hacia dentro&#8230;.. y solo dejar que pruebe su dulce sabor los que me quieren&#8230;.los que me lo demostraron y los que me lo demostraran&#8230;.<\/p>\n<p>Quiero seguir sintiendo mis latidos con la tranquilidad y conciencia de que estos dias que se quedan en el recuerdo hice feliz o al menos lo intente a los que me demostraron que me quieren&#8230;&#8230;y lo hicieron&#8230;. con mayusculas&#8230;.es en los momentos que no ves la salida y estas en lo mas profundo de un pozo es cuando te das cuenta de los que te quieren de corazon&#8230;&#8230;<\/p>\n<p>Me pasaron muchas cosas en estos meses&#8230;. bonitas y otras no tanto&#8230;.. pero hab\u00eda que estar ah\u00ed para sentirlo, vivirlo\u2026 Y estuve, en el momento preciso yo estaba ah\u00ed\u2026 y de pronto en un segundo me doy cuenta que solo fue un a\u00f1o mas vivido con mas o menos fortuna pero vivido&#8230;..<\/p>\n<p>Ahora solo queda saltar a la pr\u00f3xima nube&#8230;.. una que me lleve mas alto todavia&#8230;.. y sin paracaidas&#8230;.me gusta vivir segun mi instinto y mi corazon&#8230;.. la cabeza se la dejo para los que le gusta vivir friamente&#8230; si me caigo espero que alguno de los que este a\u00f1o me demostrasteis lo mucho que me quereis me agarre para que la caida no sea muy fuerte&#8230;.<\/p>\n<p>Y GRACIAS (ya sabeis quienes sois) a los que este a\u00f1o me ayudasteis a recoger del suelo los fragmentos de mi cuore&#8230;.que la caida fue muy dura pero no hay nada que vuestro cari\u00f1o y un poco de loctite no solucionen&#8230;.. es mas&#8230; ahora soy o estoy mas duro&#8230;. el ni\u00f1o Toffe&#8230; eh Sandrita&#8230;.<\/p>\n<p>Feliz a\u00f1o a todos&#8230;..a los que me quereis y a los que no tambien&#8230;..<\/p>\n<p>Bye. <br \/>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>31 Diciembre 2010&#8230; 3..2..1&#8230;.largate 2010&#8230;&#8230;y bienvenido 2011&#8230;.. Estos dias suelen ser los de los propositos para el nuevo a\u00f1o y por no faltar a la tradicion: Quiero ver siempre el&hellip; <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-79","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FELIZ 2011 - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/feliz-2011\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FELIZ 2011 - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"31 Diciembre 2010&#8230; 3..2..1&#8230;.largate 2010&#8230;&#8230;y bienvenido 2011&#8230;.. Estos dias suelen ser los de los propositos para el nuevo a\u00f1o y por no faltar a la tradicion: Quiero ver siempre el&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/feliz-2011\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"ValwindCycles\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-31T18:17:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/1.bp.blogspot.com\/_4Vs_a38m158\/TR4d7Fctn4I\/AAAAAAAACO4\/xhDPFhvMFTI\/s640\/DSC06429.JPG\" \/>\n<meta name=\"author\" content=\"Jorge ValwindCycles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge ValwindCycles\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/feliz-2011#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/feliz-2011\"},\"author\":{\"name\":\"Jorge ValwindCycles\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"headline\":\"FELIZ 2011\",\"datePublished\":\"2010-12-31T18:17:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/feliz-2011\"},\"wordCount\":416,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/feliz-2011#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/1.bp.blogspot.com\\\/_4Vs_a38m158\\\/TR4d7Fctn4I\\\/AAAAAAAACO4\\\/xhDPFhvMFTI\\\/s640\\\/DSC06429.JPG\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/feliz-2011#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/feliz-2011\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/feliz-2011\",\"name\":\"FELIZ 2011 - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/feliz-2011#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/feliz-2011#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/1.bp.blogspot.com\\\/_4Vs_a38m158\\\/TR4d7Fctn4I\\\/AAAAAAAACO4\\\/xhDPFhvMFTI\\\/s640\\\/DSC06429.JPG\",\"datePublished\":\"2010-12-31T18:17:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/feliz-2011#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/feliz-2011\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/feliz-2011#primaryimage\",\"url\":\"http:\\\/\\\/1.bp.blogspot.com\\\/_4Vs_a38m158\\\/TR4d7Fctn4I\\\/AAAAAAAACO4\\\/xhDPFhvMFTI\\\/s640\\\/DSC06429.JPG\",\"contentUrl\":\"http:\\\/\\\/1.bp.blogspot.com\\\/_4Vs_a38m158\\\/TR4d7Fctn4I\\\/AAAAAAAACO4\\\/xhDPFhvMFTI\\\/s640\\\/DSC06429.JPG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/feliz-2011#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FELIZ 2011\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/951c392974a112df481d1ae7391282f3\",\"name\":\"Jorge ValwindCycles\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g\",\"caption\":\"Jorge ValwindCycles\"},\"description\":\"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.\",\"sameAs\":[\"http:\\\/\\\/www.valwindcycles.es\",\"ValwindCycles\",\"http:\\\/\\\/www.linkedin.com\\\/profile\\\/view?id=180972148&trk=nav_responsive_tab_profile\",\"http:\\\/\\\/www.pinterest.com\\\/valwindcycles\\\/\",\"https:\\\/\\\/x.com\\\/JorgeValwind\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/Valwindcycles\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/valwind\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FELIZ 2011 - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/feliz-2011","og_locale":"es_ES","og_type":"article","og_title":"FELIZ 2011 - El Blog de ValwindCycles","og_description":"31 Diciembre 2010&#8230; 3..2..1&#8230;.largate 2010&#8230;&#8230;y bienvenido 2011&#8230;.. Estos dias suelen ser los de los propositos para el nuevo a\u00f1o y por no faltar a la tradicion: Quiero ver siempre el&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/feliz-2011","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"ValwindCycles","article_published_time":"2010-12-31T18:17:00+00:00","og_image":[{"url":"http:\/\/1.bp.blogspot.com\/_4Vs_a38m158\/TR4d7Fctn4I\/AAAAAAAACO4\/xhDPFhvMFTI\/s640\/DSC06429.JPG","type":"","width":"","height":""}],"author":"Jorge ValwindCycles","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Jorge ValwindCycles","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/feliz-2011#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/feliz-2011"},"author":{"name":"Jorge ValwindCycles","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"headline":"FELIZ 2011","datePublished":"2010-12-31T18:17:00+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/feliz-2011"},"wordCount":416,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/feliz-2011#primaryimage"},"thumbnailUrl":"http:\/\/1.bp.blogspot.com\/_4Vs_a38m158\/TR4d7Fctn4I\/AAAAAAAACO4\/xhDPFhvMFTI\/s640\/DSC06429.JPG","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/feliz-2011#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/feliz-2011","url":"https:\/\/valwindcycles.es\/blog\/feliz-2011","name":"FELIZ 2011 - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/feliz-2011#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/feliz-2011#primaryimage"},"thumbnailUrl":"http:\/\/1.bp.blogspot.com\/_4Vs_a38m158\/TR4d7Fctn4I\/AAAAAAAACO4\/xhDPFhvMFTI\/s640\/DSC06429.JPG","datePublished":"2010-12-31T18:17:00+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/feliz-2011#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/feliz-2011"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/feliz-2011#primaryimage","url":"http:\/\/1.bp.blogspot.com\/_4Vs_a38m158\/TR4d7Fctn4I\/AAAAAAAACO4\/xhDPFhvMFTI\/s640\/DSC06429.JPG","contentUrl":"http:\/\/1.bp.blogspot.com\/_4Vs_a38m158\/TR4d7Fctn4I\/AAAAAAAACO4\/xhDPFhvMFTI\/s640\/DSC06429.JPG"},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/feliz-2011#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"FELIZ 2011"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/951c392974a112df481d1ae7391282f3","name":"Jorge ValwindCycles","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20f7d73dff2efa8d0cfa4f58b36f280c8617fb91750a7365829dc7a97fcc74cd?s=96&d=mm&r=g","caption":"Jorge ValwindCycles"},"description":"IL Capo y alma mater de ValwindCycles, es el encargado de que est\u00e9s contento con lo que hayas comprado y lo disfrutes al m\u00e1ximo, que practiques tu deporte con la mayor seguridad, la mejor comodidad y que tu mente solo se centre en sudar, en superarte, en ese dolor placentero\u2026 en hacer que tus sue\u00f1os, tus ideas y anhelos te mantengan vivo.","sameAs":["http:\/\/www.valwindcycles.es","ValwindCycles","http:\/\/www.linkedin.com\/profile\/view?id=180972148&trk=nav_responsive_tab_profile","http:\/\/www.pinterest.com\/valwindcycles\/","https:\/\/x.com\/JorgeValwind","http:\/\/www.youtube.com\/user\/Valwindcycles"],"url":"https:\/\/valwindcycles.es\/blog\/author\/valwind"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-1h","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/79","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=79"}],"version-history":[{"count":0,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/79\/revisions"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=79"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=79"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=79"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}