{"id":8111,"date":"2018-12-20T19:06:01","date_gmt":"2018-12-20T18:06:01","guid":{"rendered":"http:\/\/valwindcycles.es\/blog\/?p=8111"},"modified":"2018-12-20T19:06:01","modified_gmt":"2018-12-20T18:06:01","slug":"ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno","status":"publish","type":"post","link":"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno","title":{"rendered":"II Cx Caimanes Betanzos &#8211; For the love of mud por PIRUCHO PEQUENO"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Los Caimanes, esos animales traicioneros que reinan en los pantanos, donde debes saber moverte sobre las aguas turbias y lidiar con el barro. \u00bfQu\u00e9 esperar de una prueba de Ciclocross en pleno h\u00e1bitat caim\u00e1n?&#8230;lo resumir\u00e9 en una frase, for the love of mud&#8230;as\u00ed, en ingl\u00e9s, que queda m\u00e1s pro.<\/span><\/p>\n<p><span style=\"font-weight: 400\">El agua es vida, el barro movida. Todo el mundo habla de la movida madrile\u00f1a, yo prefiero la movida betanceira, nace de mezclar bicis, barro y una gran dosis de sentido del humor, y el resultado es el II CX Caimanes Betanzos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Sobre las campas que rodean el Parque del Pasatiempos, e incluso atraves\u00e1ndolo, se dibujaba un circuito llano, engalanado por una gran cantidad de barro, de mucho curveo. Con el terreno totalmente enlamado, se intensific\u00f3 la dificultad t\u00e9cnica y la exigencia f\u00edsica, pero tambi\u00e9n aument\u00f3 el grado de diversi\u00f3n. Qu\u00e9 quereis que os diga, los ciclocrossman tienen un punto masoquista, cuanto m\u00e1s dif\u00edcil, cuanto m\u00e1s duro, cuanto m\u00e1s adverso, m\u00e1s divertido.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Pinchar <\/span><a href=\"https:\/\/flic.kr\/s\/aHsmxzZuLx\"><span style=\"font-weight: 400\">AQUI<\/span><\/a><span style=\"font-weight: 400\"> para verlo por vosotros mismos, caritas embarradas, ropas pingajosas, pero ciclistas felices. Atentos al detalle de los trofeos, que chispa tienen estos Caimanes.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ya no queda nada y a\u00fan queda mucho en juego&#8230;la \u00faltima jornada doble, Maceda y Ba\u00f1os de Molgas; cierre de la Copa de Galicia, el Campeonato Gallego y el Campeonato de Espa\u00f1a. Solo cuatro carreras para terminar una temporada que arranc\u00f3 hace dos meses con 17 pruebas por delante. <\/span><\/p>\n<p><span style=\"font-weight: 400\">A todos a los que os vea este fin de semana por tierras Ourensanas os lo deseare en persona, al resto&#8230;FELIZ NAVIDAD. <\/span><\/p>\n<p><span style=\"font-weight: 400\">PD:Lo de pr\u00f3spero a\u00f1o nuevo os lo deseo en la pr\u00f3xima cr\u00f3nica.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46346681671_5099ec6816_k.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8120\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\/46346681671_5099ec6816_k\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46346681671_5099ec6816_k.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"46346681671_5099ec6816_k\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46346681671_5099ec6816_k.jpg?fit=700%2C525&amp;ssl=1\" class=\"aligncenter wp-image-8120\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46346681671_5099ec6816_k.jpg?resize=700%2C525&#038;ssl=1\" alt=\"\" width=\"700\" height=\"525\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46346681671_5099ec6816_k.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46346681671_5099ec6816_k.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46346681671_5099ec6816_k.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46344827681_58d4e8629b_k.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8119\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\/46344827681_58d4e8629b_k\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46344827681_58d4e8629b_k.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"46344827681_58d4e8629b_k\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46344827681_58d4e8629b_k.jpg?fit=700%2C525&amp;ssl=1\" class=\"aligncenter wp-image-8119\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46344827681_58d4e8629b_k.jpg?resize=700%2C525&#038;ssl=1\" alt=\"\" width=\"700\" height=\"525\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46344827681_58d4e8629b_k.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46344827681_58d4e8629b_k.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46344827681_58d4e8629b_k.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46343846231_15ef565ad2_k.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8118\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\/46343846231_15ef565ad2_k\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46343846231_15ef565ad2_k.jpg?fit=768%2C1024&amp;ssl=1\" data-orig-size=\"768,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"46343846231_15ef565ad2_k\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46343846231_15ef565ad2_k.jpg?fit=700%2C933&amp;ssl=1\" class=\"size-full wp-image-8118 aligncenter\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46343846231_15ef565ad2_k.jpg?resize=700%2C933&#038;ssl=1\" alt=\"\" width=\"700\" height=\"933\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46343846231_15ef565ad2_k.jpg?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46343846231_15ef565ad2_k.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45619910244_1c8a209554_k.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8117\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\/45619910244_1c8a209554_k\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45619910244_1c8a209554_k.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"45619910244_1c8a209554_k\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45619910244_1c8a209554_k.jpg?fit=700%2C525&amp;ssl=1\" class=\"aligncenter wp-image-8117\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45619910244_1c8a209554_k.jpg?resize=700%2C525&#038;ssl=1\" alt=\"\" width=\"700\" height=\"525\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45619910244_1c8a209554_k.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45619910244_1c8a209554_k.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45619910244_1c8a209554_k.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45433974465_5d1915a143_k.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8116\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\/45433974465_5d1915a143_k\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45433974465_5d1915a143_k.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"45433974465_5d1915a143_k\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45433974465_5d1915a143_k.jpg?fit=700%2C525&amp;ssl=1\" class=\"aligncenter wp-image-8116\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45433974465_5d1915a143_k.jpg?resize=700%2C525&#038;ssl=1\" alt=\"\" width=\"700\" height=\"525\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45433974465_5d1915a143_k.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45433974465_5d1915a143_k.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45433974465_5d1915a143_k.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45432681555_61854fe3f9_k.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8115\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\/45432681555_61854fe3f9_k\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45432681555_61854fe3f9_k.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"45432681555_61854fe3f9_k\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45432681555_61854fe3f9_k.jpg?fit=700%2C525&amp;ssl=1\" class=\"aligncenter wp-image-8115\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45432681555_61854fe3f9_k.jpg?resize=700%2C525&#038;ssl=1\" alt=\"\" width=\"700\" height=\"525\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45432681555_61854fe3f9_k.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45432681555_61854fe3f9_k.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/45432681555_61854fe3f9_k.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/44529593510_1bb25fc63d_k.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8114\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\/44529593510_1bb25fc63d_k\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/44529593510_1bb25fc63d_k.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"44529593510_1bb25fc63d_k\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/44529593510_1bb25fc63d_k.jpg?fit=700%2C525&amp;ssl=1\" class=\"aligncenter wp-image-8114\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/44529593510_1bb25fc63d_k.jpg?resize=700%2C525&#038;ssl=1\" alt=\"\" width=\"700\" height=\"525\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/44529593510_1bb25fc63d_k.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/44529593510_1bb25fc63d_k.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/44529593510_1bb25fc63d_k.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/44528233590_4d03c1be91_k.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8113\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\/44528233590_4d03c1be91_k\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/44528233590_4d03c1be91_k.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"44528233590_4d03c1be91_k\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/44528233590_4d03c1be91_k.jpg?fit=700%2C525&amp;ssl=1\" class=\"aligncenter wp-image-8113\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/44528233590_4d03c1be91_k.jpg?resize=700%2C525&#038;ssl=1\" alt=\"\" width=\"700\" height=\"525\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/44528233590_4d03c1be91_k.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/44528233590_4d03c1be91_k.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/44528233590_4d03c1be91_k.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/31405911017_6189417dfd_k.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8112\" data-permalink=\"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\/31405911017_6189417dfd_k\" data-orig-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/31405911017_6189417dfd_k.jpg?fit=1024%2C683&amp;ssl=1\" data-orig-size=\"1024,683\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"31405911017_6189417dfd_k\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/31405911017_6189417dfd_k.jpg?fit=700%2C467&amp;ssl=1\" class=\"aligncenter wp-image-8112\" src=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/31405911017_6189417dfd_k.jpg?resize=700%2C467&#038;ssl=1\" alt=\"\" width=\"700\" height=\"467\" srcset=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/31405911017_6189417dfd_k.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/31405911017_6189417dfd_k.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/31405911017_6189417dfd_k.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Caimanes, esos animales traicioneros que reinan en los pantanos, donde debes saber moverte sobre las aguas turbias y lidiar con el barro. \u00bfQu\u00e9 esperar de una prueba de Ciclocross&hellip; <\/p>\n","protected":false},"author":32,"featured_media":8120,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[71,80,76],"tags":[1068,1049,1036,1035,1029],"class_list":["post-8111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotos","category-la-mafia","category-noticias","tag-ciclocross","tag-cyclocross","tag-fotos-luz-iglesias","tag-fotos-pirucho-pequeno","tag-valwindcycles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>II Cx Caimanes Betanzos - For the love of mud por PIRUCHO PEQUENO - El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"II Cx Caimanes Betanzos - For the love of mud por PIRUCHO PEQUENO - El Blog de ValwindCycles\" \/>\n<meta property=\"og:description\" content=\"Los Caimanes, esos animales traicioneros que reinan en los pantanos, donde debes saber moverte sobre las aguas turbias y lidiar con el barro. \u00bfQu\u00e9 esperar de una prueba de Ciclocross&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc\" \/>\n<meta property=\"article:author\" content=\"luzmaria.iglesiasmosquera?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-20T18:06:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46346681671_5099ec6816_k.jpg?fit=1024%2C768&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pirucho Pequeno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pirucho Pequeno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\"},\"author\":{\"name\":\"Pirucho Pequeno\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/2dc70d4ba4335aacd4f8dbf7805eee9e\"},\"headline\":\"II Cx Caimanes Betanzos &#8211; For the love of mud por PIRUCHO PEQUENO\",\"datePublished\":\"2018-12-20T18:06:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\"},\"wordCount\":310,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/46346681671_5099ec6816_k.jpg?fit=1024%2C768&ssl=1\",\"keywords\":[\"ciclocross\",\"cyclocross\",\"Fotos Luz Iglesias\",\"Fotos Pirucho Pequeno\",\"Valwindcycles\"],\"articleSection\":[\"Fotos\",\"LA MAFIA\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\",\"name\":\"II Cx Caimanes Betanzos - For the love of mud por PIRUCHO PEQUENO - El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/46346681671_5099ec6816_k.jpg?fit=1024%2C768&ssl=1\",\"datePublished\":\"2018-12-20T18:06:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/2dc70d4ba4335aacd4f8dbf7805eee9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/46346681671_5099ec6816_k.jpg?fit=1024%2C768&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/valwindcycles.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/46346681671_5099ec6816_k.jpg?fit=1024%2C768&ssl=1\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"II Cx Caimanes Betanzos &#8211; For the love of mud por PIRUCHO PEQUENO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/2dc70d4ba4335aacd4f8dbf7805eee9e\",\"name\":\"Pirucho Pequeno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g\",\"caption\":\"Pirucho Pequeno\"},\"description\":\"Se puede decir que es una especie de \u201cgroupie de ciclistas\u201d, nunca ha competido pero le encanta el mundo del ciclismo. Sus tareas principales son avituallar y fotografiar a todo aquel que me se lo pida con una sonrisa. Sus albumes de fotos en GOOGLE+ son visitados por cientos, miles, millones de personas y hasta marcianos y derivados. Ojo que aunque la ve\u00e1is en las carreras con una mirada angelical no recoge ni chaquetillas ni termicas en la salida, lo que le da fama de mala mujer.\",\"sameAs\":[\"https:\\\/\\\/picasaweb.google.com\\\/114831358335341071162\",\"luzmaria.iglesiasmosquera?fref=ts\"],\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/pirucho-pequeno\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"II Cx Caimanes Betanzos - For the love of mud por PIRUCHO PEQUENO - El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno","og_locale":"es_ES","og_type":"article","og_title":"II Cx Caimanes Betanzos - For the love of mud por PIRUCHO PEQUENO - El Blog de ValwindCycles","og_description":"Los Caimanes, esos animales traicioneros que reinan en los pantanos, donde debes saber moverte sobre las aguas turbias y lidiar con el barro. \u00bfQu\u00e9 esperar de una prueba de Ciclocross&hellip;","og_url":"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno","og_site_name":"El Blog de ValwindCycles","article_publisher":"https:\/\/www.facebook.com\/VALWINDCYCLES-59614610981\/?pnref=lhc","article_author":"luzmaria.iglesiasmosquera?fref=ts","article_published_time":"2018-12-20T18:06:01+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46346681671_5099ec6816_k.jpg?fit=1024%2C768&ssl=1","type":"image\/jpeg"}],"author":"Pirucho Pequeno","twitter_card":"summary_large_image","twitter_creator":"@JorgeValwind","twitter_site":"@JorgeValwind","twitter_misc":{"Escrito por":"Pirucho Pequeno","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#article","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno"},"author":{"name":"Pirucho Pequeno","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/2dc70d4ba4335aacd4f8dbf7805eee9e"},"headline":"II Cx Caimanes Betanzos &#8211; For the love of mud por PIRUCHO PEQUENO","datePublished":"2018-12-20T18:06:01+00:00","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno"},"wordCount":310,"commentCount":0,"image":{"@id":"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46346681671_5099ec6816_k.jpg?fit=1024%2C768&ssl=1","keywords":["ciclocross","cyclocross","Fotos Luz Iglesias","Fotos Pirucho Pequeno","Valwindcycles"],"articleSection":["Fotos","LA MAFIA","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno","url":"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno","name":"II Cx Caimanes Betanzos - For the love of mud por PIRUCHO PEQUENO - El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#primaryimage"},"image":{"@id":"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46346681671_5099ec6816_k.jpg?fit=1024%2C768&ssl=1","datePublished":"2018-12-20T18:06:01+00:00","author":{"@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/2dc70d4ba4335aacd4f8dbf7805eee9e"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#primaryimage","url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46346681671_5099ec6816_k.jpg?fit=1024%2C768&ssl=1","contentUrl":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46346681671_5099ec6816_k.jpg?fit=1024%2C768&ssl=1","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/ii-cx-caimanes-betanzos-for-the-love-of-mud-pirucho-pequeno#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"II Cx Caimanes Betanzos &#8211; For the love of mud por PIRUCHO PEQUENO"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/2dc70d4ba4335aacd4f8dbf7805eee9e","name":"Pirucho Pequeno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c2ae204eafa0804bdb4945936e28dac6c87d1f8b8dc2e1ead63c0d13b2effb9?s=96&d=mm&r=g","caption":"Pirucho Pequeno"},"description":"Se puede decir que es una especie de \u201cgroupie de ciclistas\u201d, nunca ha competido pero le encanta el mundo del ciclismo. Sus tareas principales son avituallar y fotografiar a todo aquel que me se lo pida con una sonrisa. Sus albumes de fotos en GOOGLE+ son visitados por cientos, miles, millones de personas y hasta marcianos y derivados. Ojo que aunque la ve\u00e1is en las carreras con una mirada angelical no recoge ni chaquetillas ni termicas en la salida, lo que le da fama de mala mujer.","sameAs":["https:\/\/picasaweb.google.com\/114831358335341071162","luzmaria.iglesiasmosquera?fref=ts"],"url":"https:\/\/valwindcycles.es\/blog\/author\/pirucho-pequeno"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p47mZM-26P","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/valwindcycles.es\/blog\/wp-content\/uploads\/2018\/12\/46346681671_5099ec6816_k.jpg?fit=1024%2C768&ssl=1","_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/8111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/comments?post=8111"}],"version-history":[{"count":1,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/8111\/revisions"}],"predecessor-version":[{"id":8121,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/posts\/8111\/revisions\/8121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media\/8120"}],"wp:attachment":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/media?parent=8111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/categories?post=8111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/tags?post=8111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}