{"id":65,"name":"Almu","url":"","description":"Como dec\u00eda hace unos d\u00edas en una de sus entradas en el blog.. el trail running es correr en la monta\u00f1a, la monta\u00f1a es libertad, naturaleza, aire puro, desconexi\u00f3n, es sentirse en afinidad y comuni\u00f3n con ese entorno natural, es avanzar sin importar el tiempo, la distancia o el ritmo, es buscar la soledad y el silencio\u2026. Es llegar a meta habiendo recorrido un camino en el que te has hecho fuerte, en el que has controlado todas las dificultades que se han presentado a lo largo de ese viaje\u2026..\r\nParece una filosof\u00eda de la vida no ? SweetSmile \u2026 la chica que corre\u2026 nada.. pedalea \u2026 escribe y vive la \u201cESENCIA\u201d Valwind como una autentica MafiosaValwind, la m\u00e1gica sonrisa, la runner-biker-nadadora-reportera dicharachera, energ\u00eda contagiosa en su m\u00e1ximo esplendor.\r\nEl otro d\u00eda se desped\u00eda en una de sus entradas en el blog con esta sabia frase del Baron Pierre de Coubertin; \u201cEl deporte busca dominar el miedo, triunfar sobre la fatiga, vencer a la dificultad\u201d. Ella lo hace y adem\u00e1s con una m\u00e1gica sonrisa\u2026 Almu SweetSmile","link":"https:\/\/valwindcycles.es\/blog\/author\/almu","slug":"almu","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g"},"meta":{"jetpack_donation_warning_dismissed":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Almu, autor en El Blog de ValwindCycles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valwindcycles.es\/blog\/author\/almu\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Almu, autor en El Blog de ValwindCycles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valwindcycles.es\/blog\/author\/almu\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de ValwindCycles\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/60d6b82e516149caae4cd93134c642a3?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@JorgeValwind\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/almu\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/almu\",\"name\":\"Almu, autor en El Blog de ValwindCycles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/almu#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/almu\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/almu#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valwindcycles.es\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archivo de Almu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/\",\"name\":\"El Blog de ValwindCycles\",\"description\":\"Viento del Valle ... www.Valwindcycles.es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/#\\\/schema\\\/person\\\/081173dcdb570286f86e577c70e9822d\",\"name\":\"Almu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g\",\"caption\":\"Almu\"},\"description\":\"Como dec\u00eda hace unos d\u00edas en una de sus entradas en el blog.. el trail running es correr en la monta\u00f1a, la monta\u00f1a es libertad, naturaleza, aire puro, desconexi\u00f3n, es sentirse en afinidad y comuni\u00f3n con ese entorno natural, es avanzar sin importar el tiempo, la distancia o el ritmo, es buscar la soledad y el silencio\u2026. Es llegar a meta habiendo recorrido un camino en el que te has hecho fuerte, en el que has controlado todas las dificultades que se han presentado a lo largo de ese viaje\u2026.. Parece una filosof\u00eda de la vida no ? SweetSmile \u2026 la chica que corre\u2026 nada.. pedalea \u2026 escribe y vive la \u201cESENCIA\u201d Valwind como una autentica MafiosaValwind, la m\u00e1gica sonrisa, la runner-biker-nadadora-reportera dicharachera, energ\u00eda contagiosa en su m\u00e1ximo esplendor. El otro d\u00eda se desped\u00eda en una de sus entradas en el blog con esta sabia frase del Baron Pierre de Coubertin; \u201cEl deporte busca dominar el miedo, triunfar sobre la fatiga, vencer a la dificultad\u201d. Ella lo hace y adem\u00e1s con una m\u00e1gica sonrisa\u2026 Almu SweetSmile\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valwindcycles.es\\\/blog\\\/author\\\/almu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Almu, autor en El Blog de ValwindCycles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valwindcycles.es\/blog\/author\/almu","og_locale":"es_ES","og_type":"profile","og_title":"Almu, autor en El Blog de ValwindCycles","og_url":"https:\/\/valwindcycles.es\/blog\/author\/almu","og_site_name":"El Blog de ValwindCycles","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/60d6b82e516149caae4cd93134c642a3?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@JorgeValwind","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/valwindcycles.es\/blog\/author\/almu","url":"https:\/\/valwindcycles.es\/blog\/author\/almu","name":"Almu, autor en El Blog de ValwindCycles","isPartOf":{"@id":"https:\/\/valwindcycles.es\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/valwindcycles.es\/blog\/author\/almu#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valwindcycles.es\/blog\/author\/almu"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/valwindcycles.es\/blog\/author\/almu#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valwindcycles.es\/blog"},{"@type":"ListItem","position":2,"name":"Archivo de Almu"}]},{"@type":"WebSite","@id":"https:\/\/valwindcycles.es\/blog\/#website","url":"https:\/\/valwindcycles.es\/blog\/","name":"El Blog de ValwindCycles","description":"Viento del Valle ... www.Valwindcycles.es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valwindcycles.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valwindcycles.es\/blog\/#\/schema\/person\/081173dcdb570286f86e577c70e9822d","name":"Almu","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/09d3d4057f60e22f6c2c08114d5d26095eabeef395cb6d3d50ecde0a6f61eff5?s=96&d=mm&r=g","caption":"Almu"},"description":"Como dec\u00eda hace unos d\u00edas en una de sus entradas en el blog.. el trail running es correr en la monta\u00f1a, la monta\u00f1a es libertad, naturaleza, aire puro, desconexi\u00f3n, es sentirse en afinidad y comuni\u00f3n con ese entorno natural, es avanzar sin importar el tiempo, la distancia o el ritmo, es buscar la soledad y el silencio\u2026. Es llegar a meta habiendo recorrido un camino en el que te has hecho fuerte, en el que has controlado todas las dificultades que se han presentado a lo largo de ese viaje\u2026.. Parece una filosof\u00eda de la vida no ? SweetSmile \u2026 la chica que corre\u2026 nada.. pedalea \u2026 escribe y vive la \u201cESENCIA\u201d Valwind como una autentica MafiosaValwind, la m\u00e1gica sonrisa, la runner-biker-nadadora-reportera dicharachera, energ\u00eda contagiosa en su m\u00e1ximo esplendor. El otro d\u00eda se desped\u00eda en una de sus entradas en el blog con esta sabia frase del Baron Pierre de Coubertin; \u201cEl deporte busca dominar el miedo, triunfar sobre la fatiga, vencer a la dificultad\u201d. Ella lo hace y adem\u00e1s con una m\u00e1gica sonrisa\u2026 Almu SweetSmile","mainEntityOfPage":{"@id":"https:\/\/valwindcycles.es\/blog\/author\/almu"}}]}},"_links":{"self":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valwindcycles.es\/blog\/wp-json\/wp\/v2\/users"}]}}